{"id":98378,"date":"2025-01-02T08:57:34","date_gmt":"2025-01-02T15:57:34","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=98378"},"modified":"2025-01-02T08:57:36","modified_gmt":"2025-01-02T15:57:36","slug":"esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/","title":{"rendered":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La secretaria del Bienestar, Ariadna Montiel, revel\u00f3 el orden en el cual se dispersar\u00e1 el pago del primer bimestre para adultos mayores y personas con discapacidad.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este jueves inicia el pago de la pensi\u00f3n del Bienestar para adultos mayores y para personas con discapacidad, correspondiente al primer bimestre de 2025. La dispersi\u00f3n de estos recursos llegar\u00e1 con el aumento anual anunciado por el gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Calendario de pagos de la Pensi\u00f3n del Bienestar<\/strong><br>Este jueves, la secretaria del Bienestar, Ariadna Montiel, dio a conocer el calendario de pagos, en orden alfab\u00e9tico. Este 2 de enero, caer\u00e1 el pago de los beneficiarios cuya primera letra de su apellido sea la A.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A<\/strong>, 2 de enero<br><strong>B<\/strong>, 3 de enero<br><strong>C<\/strong>, 4 y 6 de enero<br><strong>D,E,F<\/strong>, 7 de enero<br><strong>G<\/strong>, 8 y 9 de enero<br><strong>H, I, J, K<\/strong>, 10 de enero<br><strong>L<\/strong>, 11 de enero<br><strong>M<\/strong>, 13 y 14 de enero<br><strong>N, \u00d1, O<\/strong>, 15 de enero<br><strong>P, Q<\/strong>, 16 de enero<br><strong>R<\/strong>, 17 y 18 de enero<br><strong>S<\/strong>, 20 de enero<br><strong>T, U, V<\/strong>, 21 de enero<br><strong>W, X, Y, Z<\/strong>, 22 de enero<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De cu\u00e1nto es la pensi\u00f3n del Bienestar en 2025<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En 2025, el pago bimestral para los adultos mayores ser\u00e1 de 6,200 pesos. Y para las personas con discapacidad ser\u00e1 de 3,200 pesos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><\/h3>\n","protected":false},"excerpt":{"rendered":"<p>La secretaria del Bienestar, Ariadna Montiel, revel\u00f3 el orden en el cual se dispersar\u00e1 el pago del primer bimestre para adultos mayores y personas con discapacidad. Este jueves inicia el pago de la pensi\u00f3n del Bienestar para adultos mayores y para personas con discapacidad, correspondiente al primer bimestre de 2025. La dispersi\u00f3n de estos recursos [&hellip;]<\/p>\n","protected":false},"author":89,"featured_media":46275,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-98378","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La secretaria del Bienestar, Ariadna Montiel, revel\u00f3 el orden en el cual se dispersar\u00e1 el pago del primer bimestre para adultos mayores y personas con discapacidad. Este jueves inicia el pago de la pensi\u00f3n del Bienestar para adultos mayores y para personas con discapacidad, correspondiente al primer bimestre de 2025. La dispersi\u00f3n de estos recursos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-02T15:57:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-02T15:57:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expansi\u00f3n \u00a0\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expansi\u00f3n \u00a0\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/\"},\"author\":{\"name\":\"Expansi\u00f3n \u00a0\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/927b77c3bc41c5093b47873a3f0c99ae\"},\"headline\":\"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025\",\"datePublished\":\"2025-01-02T15:57:34+00:00\",\"dateModified\":\"2025-01-02T15:57:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/\"},\"wordCount\":214,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/\",\"name\":\"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg\",\"datePublished\":\"2025-01-02T15:57:34+00:00\",\"dateModified\":\"2025-01-02T15:57:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2025\\\/01\\\/02\\\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/927b77c3bc41c5093b47873a3f0c99ae\",\"name\":\"Expansi\u00f3n \u00a0\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g\",\"caption\":\"Expansi\u00f3n \u00a0\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/expansion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/","og_locale":"es_MX","og_type":"article","og_title":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas","og_description":"La secretaria del Bienestar, Ariadna Montiel, revel\u00f3 el orden en el cual se dispersar\u00e1 el pago del primer bimestre para adultos mayores y personas con discapacidad. Este jueves inicia el pago de la pensi\u00f3n del Bienestar para adultos mayores y para personas con discapacidad, correspondiente al primer bimestre de 2025. La dispersi\u00f3n de estos recursos [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2025-01-02T15:57:34+00:00","article_modified_time":"2025-01-02T15:57:36+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg","type":"image\/jpeg"}],"author":"Expansi\u00f3n \u00a0","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Expansi\u00f3n \u00a0","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/"},"author":{"name":"Expansi\u00f3n \u00a0","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/927b77c3bc41c5093b47873a3f0c99ae"},"headline":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025","datePublished":"2025-01-02T15:57:34+00:00","dateModified":"2025-01-02T15:57:36+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/"},"wordCount":214,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/","name":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025 - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg","datePublished":"2025-01-02T15:57:34+00:00","dateModified":"2025-01-02T15:57:36+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/pension-bienestar-adultos-mayores-2023-deposito-pago-enero-.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2025\/01\/02\/esta-listo-el-calendario-de-pagos-de-la-pension-del-bienestar-para-enero-de-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Est\u00e1 listo el calendario de pagos de la Pensi\u00f3n del Bienestar para enero de 2025"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/927b77c3bc41c5093b47873a3f0c99ae","name":"Expansi\u00f3n \u00a0","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7c9dbe4c29cb2eb7c516f4e4492be1f7e1a6d27cc733b89158d7523a49b1266?s=96&d=mm&r=g","caption":"Expansi\u00f3n \u00a0"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/expansion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/98378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=98378"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/98378\/revisions"}],"predecessor-version":[{"id":98379,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/98378\/revisions\/98379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/46275"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=98378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=98378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=98378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}