{"id":97810,"date":"2024-12-18T04:35:00","date_gmt":"2024-12-18T11:35:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=97810"},"modified":"2024-12-17T21:40:38","modified_gmt":"2024-12-18T04:40:38","slug":"el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/","title":{"rendered":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este lunes 16 de diciembre dio inicio el IV Coloquio de la primera generaci\u00f3n de la Maestr\u00eda en Violencias de G\u00e9nero (MVG) que oferta el Centro de Pol\u00edticas de G\u00e9nero para la Igualdad entre Mujeres y Hombres (CPGIMH) de la Universidad Aut\u00f3noma de Sinaloa (UAS).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presentaci\u00f3n se realiz\u00f3 en el Aula Veneranda B\u00e1tiz del Edificio 5 ubicado en el Campus Rafael Buelna, en la que la coordinadora de la maestr\u00eda, la doctora Lizbeth Garc\u00eda Montoya dio la bienvenida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEllos lo que hacen en este cuarto coloquio es subsanar las observaciones que se les hizo en el primer coloquio, en el segundo y en el tercero, sus cap\u00edtulos 1, 2, 3 y 4; y presentan todos esos avances con las observaciones subsanadas, pero aparte con el plus de lo que elaboraron este semestre que es el proyecto de intervenci\u00f3n\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, el programa incluir\u00e1 la presentaci\u00f3n de los \u201cavances de proyectos de investigaci\u00f3n e intervenci\u00f3n\u201d de 17 alumnas y alumnos de la maestr\u00eda durante tres d\u00edas de trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEllos tuvieron para este coloquio que elaborar el dise\u00f1o del proyecto de intervenci\u00f3n, ejecutarlo y, algunos hasta lo pudieron evaluar\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La idea principal, a\u00f1adi\u00f3 la coordinadora es que las y los maestrantes, tanto de la primera generaci\u00f3n como de la segunda, \u201cdesarrollen estrategias necesarias para intervenir desde paradigmas interpretativos sobre la perspectiva de igualdad de g\u00e9nero, la interseccionalidad y los derechos humanos\u201d en todos los aspectos relacionados con la violencia hacia las mujeres y hacia otros grupos en situaci\u00f3n de vulnerabilidad social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa mayor\u00eda, como lo he reiterado en las dem\u00e1s entrevistas, vienen de aqu\u00ed del Centro de Pol\u00edticas y sus proyectos de intervenci\u00f3n se van a ejecutar aqu\u00ed en la universidad; y otros vienen de instituciones educativas y de gobierno donde tambi\u00e9n se van a implementar estos proyectos de intervenci\u00f3n en sus \u00e1reas laborales\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, dio a conocer que, pr\u00f3ximamente, se abrir\u00e1 la convocatoria 2025-2027 del programa que \u201cbusca cubrir una urgente demanda de profesionalizaci\u00f3n por quienes enfrentan el d\u00eda a d\u00eda en la prevenci\u00f3n, atenci\u00f3n y sanci\u00f3n de las violencias de g\u00e9nero, con la finalidad de aportar al cumplimiento de los derechos humanos, igualdad, justicia y paz\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera alumna en exponer fue la licenciada Beatriz L\u00f3pez Castro con el tema \u201cEl mecanismo de medidas de protecci\u00f3n para mujeres v\u00edctimas de violencia familiar\u201d asesorado por la doctora Ofelia L\u00f3pez Mej\u00eda y la maestra Lydia Guadalupe Ojeda Esquerra, dirigido por la doctora Carlota Leticia Rodr\u00edguez.&nbsp;&nbsp; &nbsp;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este lunes 16 de diciembre dio inicio el IV Coloquio de la primera generaci\u00f3n de la Maestr\u00eda en Violencias de G\u00e9nero (MVG) que oferta el Centro de Pol\u00edticas de G\u00e9nero para la Igualdad entre Mujeres y Hombres (CPGIMH) de la Universidad Aut\u00f3noma de Sinaloa (UAS). La presentaci\u00f3n se realiz\u00f3 en el Aula Veneranda B\u00e1tiz del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":97811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[33,36],"tags":[],"class_list":["post-97810","post","type-post","status-publish","format-standard","has-post-thumbnail","category-igualdad-sustantiva","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Este lunes 16 de diciembre dio inicio el IV Coloquio de la primera generaci\u00f3n de la Maestr\u00eda en Violencias de G\u00e9nero (MVG) que oferta el Centro de Pol\u00edticas de G\u00e9nero para la Igualdad entre Mujeres y Hombres (CPGIMH) de la Universidad Aut\u00f3noma de Sinaloa (UAS). La presentaci\u00f3n se realiz\u00f3 en el Aula Veneranda B\u00e1tiz del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T11:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero\",\"datePublished\":\"2024-12-18T11:35:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg\",\"articleSection\":[\"IGUALDAD SUSTANTIVA\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/\",\"name\":\"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg\",\"datePublished\":\"2024-12-18T11:35:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/12\\\/18\\\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/","og_locale":"es_MX","og_type":"article","og_title":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas","og_description":"Este lunes 16 de diciembre dio inicio el IV Coloquio de la primera generaci\u00f3n de la Maestr\u00eda en Violencias de G\u00e9nero (MVG) que oferta el Centro de Pol\u00edticas de G\u00e9nero para la Igualdad entre Mujeres y Hombres (CPGIMH) de la Universidad Aut\u00f3noma de Sinaloa (UAS). La presentaci\u00f3n se realiz\u00f3 en el Aula Veneranda B\u00e1tiz del [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-12-18T11:35:00+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero","datePublished":"2024-12-18T11:35:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg","articleSection":["IGUALDAD SUSTANTIVA","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/","name":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg","datePublished":"2024-12-18T11:35:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/12\/Coloquio-de-la-Maestria-en-Violencias-de-Genero-2.jpeg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/12\/18\/el-cpgimh-de-la-uas-dio-inicio-el-iv-coloquio-de-la-maestria-en-violencias-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"El CPGIMH de la UAS dio inici\u00f3 el IV Coloquio de la Maestr\u00eda en Violencias de G\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/97810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=97810"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/97810\/revisions"}],"predecessor-version":[{"id":97812,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/97810\/revisions\/97812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/97811"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=97810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=97810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=97810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}