{"id":96113,"date":"2024-11-25T10:08:30","date_gmt":"2024-11-25T17:08:30","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=96113"},"modified":"2024-11-25T10:08:30","modified_gmt":"2024-11-25T17:08:30","slug":"quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/","title":{"rendered":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones"},"content":{"rendered":"\n<p><strong><em>Adem\u00e1s de que sus percepciones ser\u00e1n casi 1.4 millones de pesos menos, en 2025, los magistrados del Tribunal Electoral perder\u00e1n prestaciones<\/em><\/strong><\/p>\n\n\n\n<p>Ciudad de M\u00e9xico.- Las magistraturas de la sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n disminuir\u00e1n sus percepciones salariales en casi un mill\u00f3n 400 mil pesos anuales brutos, luego de que bajaron la compensaci\u00f3n garantizada, desaparece el pago por riesgo, y disminuyen algunos otros rubros de sus prestaciones.<\/p>\n\n\n\n<p>Durante 2024, cada magistratura recibi\u00f3 5 millones 529 mil 451 pesos brutos entre sueldo, compensaci\u00f3n garantizada y prestaciones, pero para 2025 se presupuestaron percepciones brutas anuales por 4 millones 146 mil 26 pesos, es decir, un mill\u00f3n 383 mil 425 pesos menos que este 2024.<\/p>\n\n\n\n<p>En el anteproyecto de presupuesto entregado por la presidencia a la C\u00e1mara de Diputados, para 2025, no refiere ning\u00fan monto por pago de riesgo, cuando en 2024 esta cantidad fue de 587 mil 649 pesos.<\/p>\n\n\n\n<p>En adici\u00f3n, la compensaci\u00f3n garantizada que durante este a\u00f1o fue de 2 millones 785 mil 844 pesos, para el pr\u00f3ximo a\u00f1o se proyecta en 2 millones 269 mil 80 pesos, es decir, 516 mil 764 pesos menos, para cada magistratura.<\/p>\n\n\n\n<p>En prestaciones, se disminuye de 1 mill\u00f3n 408 mil 914 pesos al a\u00f1o, a 1 mill\u00f3n 216 mil 883 afectando varios rubros, entre ellos, el aguinaldo de 683 mil 11 pesos que recibir\u00e1n en 2024, que baja a 497 mil 389 pesos brutos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de que sus percepciones ser\u00e1n casi 1.4 millones de pesos menos, en 2025, los magistrados del Tribunal Electoral perder\u00e1n prestaciones Ciudad de M\u00e9xico.- Las magistraturas de la sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n disminuir\u00e1n sus percepciones salariales en casi un mill\u00f3n 400 mil pesos anuales brutos, luego de que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":96112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-96113","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de que sus percepciones ser\u00e1n casi 1.4 millones de pesos menos, en 2025, los magistrados del Tribunal Electoral perder\u00e1n prestaciones Ciudad de M\u00e9xico.- Las magistraturas de la sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n disminuir\u00e1n sus percepciones salariales en casi un mill\u00f3n 400 mil pesos anuales brutos, luego de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-25T17:08:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"679\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exc\u00e9lsior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exc\u00e9lsior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/\"},\"author\":{\"name\":\"Exc\u00e9lsior\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\"},\"headline\":\"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones\",\"datePublished\":\"2024-11-25T17:08:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/img_1227-1.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/\",\"name\":\"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/img_1227-1.jpg\",\"datePublished\":\"2024-11-25T17:08:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/img_1227-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/img_1227-1.jpg\",\"width\":679,\"height\":452},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/11\\\/25\\\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\",\"name\":\"Exc\u00e9lsior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"caption\":\"Exc\u00e9lsior\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/excelsior\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/","og_locale":"es_MX","og_type":"article","og_title":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas","og_description":"Adem\u00e1s de que sus percepciones ser\u00e1n casi 1.4 millones de pesos menos, en 2025, los magistrados del Tribunal Electoral perder\u00e1n prestaciones Ciudad de M\u00e9xico.- Las magistraturas de la sala Superior del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n disminuir\u00e1n sus percepciones salariales en casi un mill\u00f3n 400 mil pesos anuales brutos, luego de que [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-11-25T17:08:30+00:00","og_image":[{"width":679,"height":452,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg","type":"image\/jpeg"}],"author":"Exc\u00e9lsior","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Exc\u00e9lsior","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/"},"author":{"name":"Exc\u00e9lsior","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780"},"headline":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones","datePublished":"2024-11-25T17:08:30+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/"},"wordCount":231,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/","name":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg","datePublished":"2024-11-25T17:08:30+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/11\/img_1227-1.jpg","width":679,"height":452},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/11\/25\/quitaran-a-magistrados-pago-por-riesgo-tepjf-se-recorta-prestaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Quitar\u00e1n a magistrados pago por riesgo; TEPJF se recorta prestaciones"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780","name":"Exc\u00e9lsior","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","caption":"Exc\u00e9lsior"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/excelsior\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/96113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=96113"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/96113\/revisions"}],"predecessor-version":[{"id":96114,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/96113\/revisions\/96114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/96112"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=96113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=96113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=96113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}