{"id":93394,"date":"2024-10-15T17:19:37","date_gmt":"2024-10-16T00:19:37","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=93394"},"modified":"2024-10-15T17:19:37","modified_gmt":"2024-10-16T00:19:37","slug":"el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/","title":{"rendered":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- El Partido Acci\u00f3n Nacional (PAN) en Sinaloa, debe volver a ser un contrapeso real y no ser m\u00e1s un partido que administre derrotas a trav\u00e9s de la repartici\u00f3n de cargos por representaci\u00f3n proporcional, asegur\u00f3 Vanessa Vizcarra, candidata a la Presidencia del Comit\u00e9 Directivo Estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl PAN debe ser una opci\u00f3n verdadera para la ciudadan\u00eda, dejar de ser este partido que administra derrotas, porque no estamos pretendiendo ser una dirigencia para poder colocarse en estas posiciones simplemente como un PAN administrador de representaci\u00f3n proporcional, regresemos a ser el PAN de la representaci\u00f3n popular\u201d, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aspirante a la dirigencia estatal de Acci\u00f3n Nacional record\u00f3 la importancia de recuperar la confianza de los sinaloenses, para abanderar todas esas causas justas que ha defendido el partido a lo largo de d\u00e9cadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQue la ciudadan\u00eda nos vea como panistas, como dirigentes, que somos emp\u00e1ticos y que sabemos escuchar, que llevamos sus banderas y no pretender que somos nosotros los que vamos a imponerle las banderas a la ciudadan\u00eda\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al sostener diversos encuentros con miembros activos del Partido Acci\u00f3n Nacional durante su campa\u00f1a, Vanessa Vizcarra resalt\u00f3 la importancia de una verdadera renovaci\u00f3n que permita reconstruir la oposici\u00f3n que se necesita para darle voz a las causas de los sinaloenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNecesitamos esta renovaci\u00f3n, porque necesitamos recuperar la identidad. Hoy, el PAN en Sinaloa, y en este proyecto de dirigencia, entendemos que lo m\u00e1s importante es recuperar la identidad\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sin.- El Partido Acci\u00f3n Nacional (PAN) en Sinaloa, debe volver a ser un contrapeso real y no ser m\u00e1s un partido que administre derrotas a trav\u00e9s de la repartici\u00f3n de cargos por representaci\u00f3n proporcional, asegur\u00f3 Vanessa Vizcarra, candidata a la Presidencia del Comit\u00e9 Directivo Estatal. \u201cEl PAN debe ser una opci\u00f3n verdadera para la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":93393,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[38],"tags":[],"class_list":["post-93394","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-locales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n, Sin.- El Partido Acci\u00f3n Nacional (PAN) en Sinaloa, debe volver a ser un contrapeso real y no ser m\u00e1s un partido que administre derrotas a trav\u00e9s de la repartici\u00f3n de cargos por representaci\u00f3n proporcional, asegur\u00f3 Vanessa Vizcarra, candidata a la Presidencia del Comit\u00e9 Directivo Estatal. \u201cEl PAN debe ser una opci\u00f3n verdadera para la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-16T00:19:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"811\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra\",\"datePublished\":\"2024-10-16T00:19:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/\"},\"wordCount\":272,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg\",\"articleSection\":[\"NOTICIAS LOCALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/\",\"name\":\"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg\",\"datePublished\":\"2024-10-16T00:19:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg\",\"width\":1200,\"height\":811},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/15\\\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/","og_locale":"es_MX","og_type":"article","og_title":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas","og_description":"Culiac\u00e1n, Sin.- El Partido Acci\u00f3n Nacional (PAN) en Sinaloa, debe volver a ser un contrapeso real y no ser m\u00e1s un partido que administre derrotas a trav\u00e9s de la repartici\u00f3n de cargos por representaci\u00f3n proporcional, asegur\u00f3 Vanessa Vizcarra, candidata a la Presidencia del Comit\u00e9 Directivo Estatal. \u201cEl PAN debe ser una opci\u00f3n verdadera para la [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-10-16T00:19:37+00:00","og_image":[{"width":1200,"height":811,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra","datePublished":"2024-10-16T00:19:37+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/"},"wordCount":272,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg","articleSection":["NOTICIAS LOCALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/","name":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg","datePublished":"2024-10-16T00:19:37+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/b250bf56-6bec-4447-a224-624292d96e67-1.jpg","width":1200,"height":811},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/15\/el-pan-debe-dejar-de-ser-un-partido-que-administra-derrotas-vanessa-vizcarra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"El PAN debe dejar de ser un partido que administra derrotas: Vanessa Vizcarra"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=93394"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93394\/revisions"}],"predecessor-version":[{"id":93395,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93394\/revisions\/93395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/93393"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=93394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=93394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=93394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}