{"id":93239,"date":"2024-10-13T13:26:05","date_gmt":"2024-10-13T20:26:05","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=93239"},"modified":"2024-10-13T13:26:06","modified_gmt":"2024-10-13T20:26:06","slug":"aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/","title":{"rendered":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jorge Anatolio Medina Le\u00f3n cubri\u00f3 una \u00e9poca gloriosa del periodismo de combate y su capacidad de an\u00e1lisis y s\u00edntesis quedo plasmada para la posteridad en su columna \u201cSinaloa de Frente y de Perfil\u201d, que public\u00f3 en El Sol de Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue el hombre de la prosa fina, el de la palabra demoledora, el del an\u00e1lisis profundo, como lo defin\u00eda su propio hijo, el amigo periodista Jorge Walterio Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me consta: como aquella vez que escribi\u00f3 en una sola l\u00ednea demoledora que el gobernador Juan Mill\u00e1n era tan capaz e inteligente que se daba el lujo de no tener secretario particular, en alusi\u00f3n directa a la descortes\u00eda o indiferencia quiz\u00e1s, de quien ten\u00eda el cargo en ese momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Naci\u00f3 en Ahome el 20 de febrero de 1925 y muri\u00f3 en Culiac\u00e1n el 13 de octubre de 2004, hijo menor de la maestra Velina Le\u00f3n de Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue el patriarca de una familia donde domina la gen\u00e9tica del periodismo y la comunicaci\u00f3n. Su recuerdo perdura con admiraci\u00f3n y afecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comparto en este art\u00edculo una fotograf\u00eda de Jorge Medina Le\u00f3n (a la izquierda), con Jos\u00e9 Mar\u00eda Figueroa D\u00edaz, quien muri\u00f3 en 2003.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Don Jorge Medina Le\u00f3n, t\u00edo de la amiga periodista y excelente comunicadora Velina Medina, le hice una extensa entrevista para el peri\u00f3dico Noroeste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esa ocasi\u00f3n inolvidable, tomamos a la par, cerveza oscura en vaso con hielo, desde el balc\u00f3n de su casa por la avenida Nic\u00f3las Bravo, frente al Bar \u201c7 Mares\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Don Jorge beb\u00eda la cerveza como agua y debo confesar que solo un bohemio profesional y no de afici\u00f3n podr\u00eda mantenerle el ritmo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ambarinas hicieron su efecto inspirador y la charla fue fruct\u00edfera. Creo que esa publicaci\u00f3n fue enmarcada y colocada en un lugar especial de su hogar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hombre de letras, escribi\u00f3 en La Voz de Sinaloa, y dirigi\u00f3 La Verdad y La Voz del Valle, si no me equivoco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tendr\u00eda que acudir a la entrevista que escrib\u00ed, donde intent\u00e9 plasmar cada detalle biogr\u00e1fico del personaje y de su admirable progenitora Velina Le\u00f3n de Medina, destacada mujer en la historia de Sinaloa que naci\u00f3 a finales del siglo XIX y fue profesora, pol\u00edtica y luchadora social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, soy poco afecto a guardar mis trabajos, los cuales solo quedan en mi memoria, as\u00ed como la grata charla en la que, entre cerveza y cerveza, antes de iniciar cualquier comentario, Don Jorge me dec\u00eda: Mire, maestro \u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy se cumplen diez a\u00f1os de su partida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jorge Anatolio Medina Le\u00f3n cubri\u00f3 una \u00e9poca gloriosa del periodismo de combate y su capacidad de an\u00e1lisis y s\u00edntesis quedo plasmada para la posteridad en su columna \u201cSinaloa de Frente y de Perfil\u201d, que public\u00f3 en El Sol de Sinaloa. Fue el hombre de la prosa fina, el de la palabra demoledora, el del an\u00e1lisis [&hellip;]<\/p>\n","protected":false},"author":157,"featured_media":93240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3093],"tags":[],"class_list":["post-93239","post","type-post","status-publish","format-standard","has-post-thumbnail","category-el-iconoclasta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Jorge Anatolio Medina Le\u00f3n cubri\u00f3 una \u00e9poca gloriosa del periodismo de combate y su capacidad de an\u00e1lisis y s\u00edntesis quedo plasmada para la posteridad en su columna \u201cSinaloa de Frente y de Perfil\u201d, que public\u00f3 en El Sol de Sinaloa. Fue el hombre de la prosa fina, el de la palabra demoledora, el del an\u00e1lisis [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/licmiguelalonsoriverabojorquez\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-13T20:26:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-13T20:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"644\" \/>\n\t<meta property=\"og:image:height\" content=\"398\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miguel Alonso Rivera Boj\u00f3rquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Miguel_A_Rivera\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miguel Alonso Rivera Boj\u00f3rquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/\"},\"author\":{\"name\":\"Miguel Alonso Rivera Boj\u00f3rquez\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/095dfdd37aa8185778b70f6dfceb617b\"},\"headline\":\"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n\",\"datePublished\":\"2024-10-13T20:26:05+00:00\",\"dateModified\":\"2024-10-13T20:26:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/\"},\"wordCount\":448,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Jorge-Anatolio-Medina-Leon.jpeg\",\"articleSection\":[\"El iconoclasta\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/\",\"name\":\"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Jorge-Anatolio-Medina-Leon.jpeg\",\"datePublished\":\"2024-10-13T20:26:05+00:00\",\"dateModified\":\"2024-10-13T20:26:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Jorge-Anatolio-Medina-Leon.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Jorge-Anatolio-Medina-Leon.jpeg\",\"width\":644,\"height\":398},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/10\\\/13\\\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/095dfdd37aa8185778b70f6dfceb617b\",\"name\":\"Miguel Alonso Rivera Boj\u00f3rquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g\",\"caption\":\"Miguel Alonso Rivera Boj\u00f3rquez\"},\"description\":\"Con una trayectoria de tres d\u00e9cadas, Miguel Alonso Rivera Boj\u00f3rquez (Culiac\u00e1n, 1968) es un reconocido periodista de prensa, radio y televisi\u00f3n, labor por la cual ha recibido importantes premios. Es licenciado en periodismo y licenciado en psicolog\u00eda. Ha sido titular de comunicaci\u00f3n en diversas secretar\u00edas y dependencias gubernamentales, colaborador de medios locales e internacionales y miembro de asociaciones de escritores, periodistas, historiadores y agrupaciones relacionadas con la salud. Entre los galardones recibidos figuran Premio Sinaloa de Periodismo en Cr\u00f3nica Deportiva \u201cGustavo D. Ca\u00f1edo\u201d (1995), Premio \u201cEl Payo del Rosario\u201d en Reportaje, Universidad Aut\u00f3noma de Sinaloa (1998), Premio Sinaloa de Periodismo \u201cJos\u00e9 Cayetano Valad\u00e9s\u201d, G\u00e9nero Reportaje (1999), Premio Ciudadano Sinaloa de Periodismo en Cr\u00f3nica Deportiva (2001), Premio \u201cEl Payo del Rosario\u201d, Cr\u00f3nica Deportiva, Universidad Aut\u00f3noma de Sinaloa (2002), seis premios de periodismo en el Certamen Estatal de Periodismo del Peri\u00f3dico Noroeste: dos veces en el g\u00e9nero de reportaje, dos en cr\u00f3nica social, cr\u00f3nica cultural y cr\u00f3nica deportiva (1997-2000), Galard\u00f3n al M\u00e9rito en Periodismo otorgado por el Comit\u00e9 Ciudadano Culiac\u00e1n para la Cultura y las Artes Populares (2018) y reconocimiento especial por trayectoria otorgado por la Asociaci\u00f3n de Periodistas de Sinaloa (2023).\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/licmiguelalonsoriverabojorquez\\\/\",\"https:\\\/\\\/www.instagram.com\\\/miguelalonsoriverabojorquez\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Miguel_A_Rivera\",\"https:\\\/\\\/www.youtube.com\\\/@miguelalonsoriverabojorquez\"],\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/miguelalonso\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/","og_locale":"es_MX","og_type":"article","og_title":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas","og_description":"Jorge Anatolio Medina Le\u00f3n cubri\u00f3 una \u00e9poca gloriosa del periodismo de combate y su capacidad de an\u00e1lisis y s\u00edntesis quedo plasmada para la posteridad en su columna \u201cSinaloa de Frente y de Perfil\u201d, que public\u00f3 en El Sol de Sinaloa. Fue el hombre de la prosa fina, el de la palabra demoledora, el del an\u00e1lisis [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_author":"https:\/\/www.facebook.com\/licmiguelalonsoriverabojorquez\/","article_published_time":"2024-10-13T20:26:05+00:00","article_modified_time":"2024-10-13T20:26:06+00:00","og_image":[{"width":644,"height":398,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg","type":"image\/jpeg"}],"author":"Miguel Alonso Rivera Boj\u00f3rquez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Miguel_A_Rivera","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Miguel Alonso Rivera Boj\u00f3rquez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/"},"author":{"name":"Miguel Alonso Rivera Boj\u00f3rquez","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/095dfdd37aa8185778b70f6dfceb617b"},"headline":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n","datePublished":"2024-10-13T20:26:05+00:00","dateModified":"2024-10-13T20:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/"},"wordCount":448,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg","articleSection":["El iconoclasta"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/","name":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg","datePublished":"2024-10-13T20:26:05+00:00","dateModified":"2024-10-13T20:26:06+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/10\/Jorge-Anatolio-Medina-Leon.jpeg","width":644,"height":398},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/10\/13\/aniversario-luctuoso-del-periodista-jorge-anatolio-medina-leon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Aniversario luctuoso del periodista Jorge Anatolio Medina Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/095dfdd37aa8185778b70f6dfceb617b","name":"Miguel Alonso Rivera Boj\u00f3rquez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bef5d27436917080a19bc816535d8292d13c8271f955a4cccf933064ff1c2862?s=96&d=mm&r=g","caption":"Miguel Alonso Rivera Boj\u00f3rquez"},"description":"Con una trayectoria de tres d\u00e9cadas, Miguel Alonso Rivera Boj\u00f3rquez (Culiac\u00e1n, 1968) es un reconocido periodista de prensa, radio y televisi\u00f3n, labor por la cual ha recibido importantes premios. Es licenciado en periodismo y licenciado en psicolog\u00eda. Ha sido titular de comunicaci\u00f3n en diversas secretar\u00edas y dependencias gubernamentales, colaborador de medios locales e internacionales y miembro de asociaciones de escritores, periodistas, historiadores y agrupaciones relacionadas con la salud. Entre los galardones recibidos figuran Premio Sinaloa de Periodismo en Cr\u00f3nica Deportiva \u201cGustavo D. Ca\u00f1edo\u201d (1995), Premio \u201cEl Payo del Rosario\u201d en Reportaje, Universidad Aut\u00f3noma de Sinaloa (1998), Premio Sinaloa de Periodismo \u201cJos\u00e9 Cayetano Valad\u00e9s\u201d, G\u00e9nero Reportaje (1999), Premio Ciudadano Sinaloa de Periodismo en Cr\u00f3nica Deportiva (2001), Premio \u201cEl Payo del Rosario\u201d, Cr\u00f3nica Deportiva, Universidad Aut\u00f3noma de Sinaloa (2002), seis premios de periodismo en el Certamen Estatal de Periodismo del Peri\u00f3dico Noroeste: dos veces en el g\u00e9nero de reportaje, dos en cr\u00f3nica social, cr\u00f3nica cultural y cr\u00f3nica deportiva (1997-2000), Galard\u00f3n al M\u00e9rito en Periodismo otorgado por el Comit\u00e9 Ciudadano Culiac\u00e1n para la Cultura y las Artes Populares (2018) y reconocimiento especial por trayectoria otorgado por la Asociaci\u00f3n de Periodistas de Sinaloa (2023).","sameAs":["https:\/\/www.facebook.com\/licmiguelalonsoriverabojorquez\/","https:\/\/www.instagram.com\/miguelalonsoriverabojorquez\/","https:\/\/x.com\/https:\/\/twitter.com\/Miguel_A_Rivera","https:\/\/www.youtube.com\/@miguelalonsoriverabojorquez"],"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/miguelalonso\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/157"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=93239"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93239\/revisions"}],"predecessor-version":[{"id":93241,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/93239\/revisions\/93241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/93240"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=93239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=93239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=93239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}