{"id":92099,"date":"2024-09-27T04:34:00","date_gmt":"2024-09-27T11:34:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=92099"},"modified":"2024-09-26T16:40:02","modified_gmt":"2024-09-26T23:40:02","slug":"resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/","title":{"rendered":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Cient\u00edficos chinos acaban de ponerle fin a un misterio que inici\u00f3 hace dos d\u00e9cadas, cuando varias momias de hace 3.600 a\u00f1os fueron descubiertas y, en sus cabezas y cuello, ten\u00edan untadas una misteriosa sustancia blanca.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace dos d\u00e9cadas, un equipo de arque\u00f3logos descubri\u00f3 en el cementerio de Xiaohe, en el noroeste de China, varias momias que databan de hace unos 3.300 a 3.600 a\u00f1os. Lo particular de estas momias de la Edad de Bronce, es que en las cabezas y cuello ten\u00edan untadas misteriosas sustancias blancas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque los cient\u00edficos cre\u00edan que dichas sustancias pod\u00edan ser alg\u00fan tipo de producto l\u00e1cteo fermentado, las t\u00e9cnicas de an\u00e1lisis e investigaci\u00f3n disponibles para la \u00e9poca les impidi\u00f3 determinar con precisi\u00f3n de qu\u00e9 se trata realmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora, un equipo de cient\u00edficos chinos asegura haber descifrado el misterio que rodeaba la sustancia untada en las momias. Los resultados de su trabajo, fruto de investigaciones de varios a\u00f1os, fueron publicados recientemente en la revista acad\u00e9mica Cell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores, liderados por Qiaomei Fu, lograron extraer AND mitocondrial de muestras halladas en tres tumbas distintas del cementerio de Xiaohe. Los primeros an\u00e1lisis identificaron ADN de vaca y cabra, lo que respaldaba las hip\u00f3tesis que se plantearon hace 20 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el ADN de los microorganismos de las muestras, los cient\u00edficos chinos pudieron, por fin, identificar con precisi\u00f3n la sustancia con la que hab\u00edan sido untadas las momias hace m\u00e1s de 3.000 a\u00f1os: queso k\u00e9fir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los investigadores tambi\u00e9n lograron determinar que las muestras ten\u00edan especies bacterianas y f\u00fangicas, entre las que se encuentran la Lactobacillus kefiranofaciens y Pichia kudriavzevii, todav\u00eda muy habituales en los granos de k\u00e9fir que se utilizan en la actualidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos granos de k\u00e9fir \u2014explican los cient\u00edficos\u2014, son cultivos simbi\u00f3ticos que contienen m\u00faltiples especies de bacterias probi\u00f3ticas y levaduras, que fermentan la leche y la convierten en queso k\u00e9fir, de forma muy parecida al fermento de la masa madre\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, los investigadores chinos fueron m\u00e1s all\u00e1 y estudiaron la evoluci\u00f3n de las bacterias probi\u00f3ticas, en concreto el Lactobacillus kefiranofaciens, en estos \u00faltimos 3.600 a\u00f1os y la compararon con las especies actuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta etapa del trabajo les permiti\u00f3 refutar una idea muy arraigada: que el k\u00e9fir se origin\u00f3 en la regi\u00f3n monta\u00f1osa del C\u00e1ucaso Norte, actualmente Rusia. Si bien uno de los dos grandes grupos de la bacteria Lactobacillus se origin\u00f3 all\u00ed y es la m\u00e1s utilizada en el mundo, este reciente estudio apunta a que el otro grupo, originaria del T\u00edbet, ser\u00eda m\u00e1s antigua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestra observaci\u00f3n sugiere que la cultura del k\u00e9fir se ha mantenido en la regi\u00f3n de Xinjiang, en el noroeste de China, desde la Edad de Bronce\u201d, explic\u00f3 Fu. Pero no solo esto: la sustancia blanca untada en las momias ser\u00eda la muestra de queso m\u00e1s antigua conocida hasta ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe trata de un estudio sin precedentes, que nos permite observar c\u00f3mo ha evolucionado una bacteria en los \u00faltimos 3.000 a\u00f1os. Adem\u00e1s, al examinar los productos l\u00e1cteos, hemos obtenido una imagen m\u00e1s clara de la antigua vida humana y sus interacciones con el mundo\u201d, concluy\u00f3 Fu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cient\u00edficos chinos acaban de ponerle fin a un misterio que inici\u00f3 hace dos d\u00e9cadas, cuando varias momias de hace 3.600 a\u00f1os fueron descubiertas y, en sus cabezas y cuello, ten\u00edan untadas una misteriosa sustancia blanca. Hace dos d\u00e9cadas, un equipo de arque\u00f3logos descubri\u00f3 en el cementerio de Xiaohe, en el noroeste de China, varias momias [&hellip;]<\/p>\n","protected":false},"author":168,"featured_media":92100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[40],"tags":[],"class_list":["post-92099","post","type-post","status-publish","format-standard","has-post-thumbnail","category-las-asombrosas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Cient\u00edficos chinos acaban de ponerle fin a un misterio que inici\u00f3 hace dos d\u00e9cadas, cuando varias momias de hace 3.600 a\u00f1os fueron descubiertas y, en sus cabezas y cuello, ten\u00edan untadas una misteriosa sustancia blanca. Hace dos d\u00e9cadas, un equipo de arque\u00f3logos descubri\u00f3 en el cementerio de Xiaohe, en el noroeste de China, varias momias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T11:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"650\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Espectador\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Espectador\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/\"},\"author\":{\"name\":\"El Espectador\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/6e839dd60de9b0081758c8965194ec9d\"},\"headline\":\"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os\",\"datePublished\":\"2024-09-27T11:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/momia_unguento.jpg\",\"articleSection\":[\"LAS ASOMBROSAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/\",\"name\":\"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/momia_unguento.jpg\",\"datePublished\":\"2024-09-27T11:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/momia_unguento.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/momia_unguento.jpg\",\"width\":650,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/09\\\/27\\\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/6e839dd60de9b0081758c8965194ec9d\",\"name\":\"El Espectador\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g\",\"caption\":\"El Espectador\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/espectador\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/","og_locale":"es_MX","og_type":"article","og_title":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas","og_description":"Cient\u00edficos chinos acaban de ponerle fin a un misterio que inici\u00f3 hace dos d\u00e9cadas, cuando varias momias de hace 3.600 a\u00f1os fueron descubiertas y, en sus cabezas y cuello, ten\u00edan untadas una misteriosa sustancia blanca. Hace dos d\u00e9cadas, un equipo de arque\u00f3logos descubri\u00f3 en el cementerio de Xiaohe, en el noroeste de China, varias momias [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-09-27T11:34:00+00:00","og_image":[{"width":650,"height":430,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg","type":"image\/jpeg"}],"author":"El Espectador","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Espectador","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/"},"author":{"name":"El Espectador","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/6e839dd60de9b0081758c8965194ec9d"},"headline":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os","datePublished":"2024-09-27T11:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg","articleSection":["LAS ASOMBROSAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/","name":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg","datePublished":"2024-09-27T11:34:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/09\/momia_unguento.jpg","width":650,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/09\/27\/resuelven-el-misterio-de-la-sustancia-que-fue-untada-en-momias-de-hace-3-mil-600-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Resuelven el misterio de la sustancia que fue untada en momias de hace 3 mil 600 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/6e839dd60de9b0081758c8965194ec9d","name":"El Espectador","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c143a7568478d11635930dbbadc40069c6a9eb7b804990a7e2f0aa32e5847e0?s=96&d=mm&r=g","caption":"El Espectador"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/espectador\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/92099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=92099"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/92099\/revisions"}],"predecessor-version":[{"id":92101,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/92099\/revisions\/92101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/92100"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=92099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=92099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=92099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}