{"id":9181,"date":"2021-08-06T17:59:51","date_gmt":"2021-08-07T00:59:51","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=9181"},"modified":"2021-08-06T17:59:53","modified_gmt":"2021-08-07T00:59:53","slug":"chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/","title":{"rendered":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo"},"content":{"rendered":"\n<p><strong><em>La mayor\u00eda de los estados se mantiene en color naranja del Sem\u00e1foro Epidemiol\u00f3gico, mientras que siete estados regresaron al rojo, el nivel m\u00e1ximo<\/em><\/strong><br><\/p>\n\n\n\n<p>Ciudad de M\u00e9xico.- El Sem\u00e1foro Epidemiol\u00f3gico por COVID-19 en M\u00e9xico se\u00f1ala que siete estados del pa\u00eds regresar\u00e1n al color rojo ante la tercera ola de la epidemia.<\/p>\n\n\n\n<p>Las entidades que regresan al nivel m\u00e1ximo de alerta son Sinaloa, Nayarit, Jalisco, Colima, Ciudad de M\u00e9xico, Nuevo Le\u00f3n y Guerrero.<\/p>\n\n\n\n<p>Destaca el caso de la capital mexicana, debido a que las autoridades locales mantuvieron en naranja el nivel de riesgo.<\/p>\n\n\n\n<p>La mayor\u00eda de entidades permanecen en color naranja de alerta, mientras que nueve se ubicaron en amarillo.<\/p>\n\n\n\n<p>Chiapas es el \u00fanico estado del pa\u00eds que se mantiene en sem\u00e1foro verde.<\/p>\n\n\n\n<p>M\u00e9xico es el cuarto pa\u00eds del mundo con m\u00e1s muertes por COVID-19, por detr\u00e1s de Estados Unidos, Brasil y la India, y ha regresado al decimoquinto en n\u00famero de contagios confirmados, seg\u00fan el recuento de la Universidad Johns Hopkins.<\/p>\n\n\n\n<p>Desde hace varias semanas, M\u00e9xico se encuentra en plena tercera ola de COVID-19, con jornadas en las que ha registrado m\u00e1s de 19 mil contagios diarios, cifras que no se ve\u00edan desde el pico de la segunda ola, en enero pasado.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Comunicado T\u00e9cnico Diario: Nuevo Coronavirus en el Mundo <a href=\"https:\/\/twitter.com\/hashtag\/COVID19?src=hash&amp;ref_src=twsrc%5Etfw\">#COVID19<\/a> | 6 de agosto de 2021<br><br>\u27a1\ufe0f <a href=\"https:\/\/t.co\/QwVIfrjCzl\">https:\/\/t.co\/QwVIfrjCzl<\/a> <a href=\"https:\/\/t.co\/E1NVCoUatV\">pic.twitter.com\/E1NVCoUatV<\/a><\/p>&mdash; SALUD M\u00e9xico (@SSalud_mx) <a href=\"https:\/\/twitter.com\/SSalud_mx\/status\/1423770211782692878?ref_src=twsrc%5Etfw\">August 6, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Adem\u00e1s, las autoridades sanitarias creen que, con base en las actas de defunci\u00f3n, la pandemia ha dejado m\u00e1s de 350 mil muertos en el pa\u00eds y estiman que M\u00e9xico acumula en realidad 3 millones 145 mil 307 casos de contagio.<\/p>\n\n\n\n<p>De esta cifra, 144 mil 176 son los casos activos, que han presentado s\u00edntomas durante los \u00faltimos 14 d\u00edas y que representan el 4.6 % del total.<\/p>\n\n\n\n<p>Mientras que desde el inicio de la pandemia se han recuperado 2 millones 298 mil 74 personas.<\/p>\n\n\n\n<p>La ocupaci\u00f3n media de camas generales en los hospitales mexicanos es del 51% y del 42 % para camas de terapia intensiva.<\/p>\n\n\n\n<p>Con respecto a las defunciones, Ciudad de M\u00e9xico -el foco de la pandemia- acumula el 19 % de todos los decesos a nivel nacional; es decir, casi una de cada cinco muertes.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de los estados se mantiene en color naranja del Sem\u00e1foro Epidemiol\u00f3gico, mientras que siete estados regresaron al rojo, el nivel m\u00e1ximo Ciudad de M\u00e9xico.- El Sem\u00e1foro Epidemiol\u00f3gico por COVID-19 en M\u00e9xico se\u00f1ala que siete estados del pa\u00eds regresar\u00e1n al color rojo ante la tercera ola de la epidemia. Las entidades que regresan al [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":9182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[332,59,416,193],"class_list":{"0":"post-9181","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales","8":"tag-coronavirus","9":"tag-covid-19","10":"tag-sars-cov-2","11":"tag-viral"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La mayor\u00eda de los estados se mantiene en color naranja del Sem\u00e1foro Epidemiol\u00f3gico, mientras que siete estados regresaron al rojo, el nivel m\u00e1ximo Ciudad de M\u00e9xico.- El Sem\u00e1foro Epidemiol\u00f3gico por COVID-19 en M\u00e9xico se\u00f1ala que siete estados del pa\u00eds regresar\u00e1n al color rojo ante la tercera ola de la epidemia. Las entidades que regresan al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-07T00:59:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-07T00:59:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanguardia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanguardia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/\"},\"author\":{\"name\":\"Vanguardia\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\"},\"headline\":\"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo\",\"datePublished\":\"2021-08-07T00:59:51+00:00\",\"dateModified\":\"2021-08-07T00:59:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SEMAFORO.jpg\",\"keywords\":[\"Coronavirus\",\"Covid-19\",\"SARS-CoV-2\",\"Viral\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/\",\"name\":\"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SEMAFORO.jpg\",\"datePublished\":\"2021-08-07T00:59:51+00:00\",\"dateModified\":\"2021-08-07T00:59:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SEMAFORO.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/SEMAFORO.jpg\",\"width\":980,\"height\":617},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/06\\\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\",\"name\":\"Vanguardia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"caption\":\"Vanguardia\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/vanguardia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/","og_locale":"es_MX","og_type":"article","og_title":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas","og_description":"La mayor\u00eda de los estados se mantiene en color naranja del Sem\u00e1foro Epidemiol\u00f3gico, mientras que siete estados regresaron al rojo, el nivel m\u00e1ximo Ciudad de M\u00e9xico.- El Sem\u00e1foro Epidemiol\u00f3gico por COVID-19 en M\u00e9xico se\u00f1ala que siete estados del pa\u00eds regresar\u00e1n al color rojo ante la tercera ola de la epidemia. Las entidades que regresan al [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-08-07T00:59:51+00:00","article_modified_time":"2021-08-07T00:59:53+00:00","og_image":[{"width":980,"height":617,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg","type":"image\/jpeg"}],"author":"Vanguardia","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Vanguardia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/"},"author":{"name":"Vanguardia","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b"},"headline":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo","datePublished":"2021-08-07T00:59:51+00:00","dateModified":"2021-08-07T00:59:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg","keywords":["Coronavirus","Covid-19","SARS-CoV-2","Viral"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/","name":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg","datePublished":"2021-08-07T00:59:51+00:00","dateModified":"2021-08-07T00:59:53+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/SEMAFORO.jpg","width":980,"height":617},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/06\/chiapas-el-unico-en-verde-en-semaforo-covid-19-siete-estados-regresan-a-rojo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Chiapas el \u00fanico en verde en Sem\u00e1foro COVID-19, siete estados regresan a rojo"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b","name":"Vanguardia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","caption":"Vanguardia"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/vanguardia\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=9181"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9181\/revisions"}],"predecessor-version":[{"id":9183,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/9181\/revisions\/9183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/9182"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=9181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=9181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=9181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}