{"id":88965,"date":"2024-08-17T13:13:16","date_gmt":"2024-08-17T20:13:16","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=88965"},"modified":"2024-08-17T13:13:16","modified_gmt":"2024-08-17T20:13:16","slug":"aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/","title":{"rendered":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- El Pleno del Congreso del Estado de Sinaloa aprob\u00f3 por unanimidad, en Sesi\u00f3n Extraordinaria, la renuncia de la maestra Sara Bruna Qui\u00f1\u00f3nez Estrada a la titularidad de la Fiscal\u00eda General del Estado, por lo que declar\u00f3 vacante este cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Sesi\u00f3n que tuvo lugar este s\u00e1bado 17 de agosto a las 12:00 horas, se dio lectura a Acuerdo de la Junta de Coordinaci\u00f3n Pol\u00edtica que preside el diputado Feliciano Castro Mel\u00e9ndrez, en el cual se aprueba la renuncia de Qui\u00f1\u00f3nez Estrada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Acuerdo se establece que \u201cse aprueba la renuncia voluntaria de la Mtra. Sara Bruna Qui\u00f1\u00f3nez Estrada, conforme a la solicitud hecha llegar a este Congreso del Estado de Sinaloa, en el entendido de que este Poder Legislativo, en apego a las atribuciones constitucionales exclusivas el que la design\u00f3 como Fiscal General del Estado de Sinaloa; y por ende, es la instituci\u00f3n que debe aceptarle la renuncia en atenci\u00f3n a la interpretaci\u00f3n teleol\u00f3gica, sistem\u00e1tica y amplia del art\u00edculo 76 Bis de la Constituci\u00f3n Pol\u00edtica de Sinaloa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un segundo art\u00edculo del Acuerdo se establece que una vez aceptada la renuncia por este H. Congreso del Estado \u201ces procedente declarar la vacante del cargo de Fiscal General del Estado de Sinaloa\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En consecuencia, se instruye notificar de esta vacante a la Coordinaci\u00f3n General del Consejo Estatal de Seguridad P\u00fablica para los efectos de que expida la convocatoria a que se refiere el art\u00edculo 76 Bis. Fracci\u00f3n I de la Constituci\u00f3n Pol\u00edtica del Estado de Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera se instruye que se comunique del Acuerdo aprobado al titular del Poder Ejecutivo para todos los efectos legales y administrativos a que haya lugar conforme al \u00e1mbito de su competencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo se mandata comunicar al Vicefiscal General de la Fiscal\u00eda General para todos los efectos legales y administrativos a que haya lugar de acuerdo a su Ley Org\u00e1nica y al reglamento de dicha ley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sin.- El Pleno del Congreso del Estado de Sinaloa aprob\u00f3 por unanimidad, en Sesi\u00f3n Extraordinaria, la renuncia de la maestra Sara Bruna Qui\u00f1\u00f3nez Estrada a la titularidad de la Fiscal\u00eda General del Estado, por lo que declar\u00f3 vacante este cargo. En Sesi\u00f3n que tuvo lugar este s\u00e1bado 17 de agosto a las 12:00 horas, [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":88964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-88965","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n, Sin.- El Pleno del Congreso del Estado de Sinaloa aprob\u00f3 por unanimidad, en Sesi\u00f3n Extraordinaria, la renuncia de la maestra Sara Bruna Qui\u00f1\u00f3nez Estrada a la titularidad de la Fiscal\u00eda General del Estado, por lo que declar\u00f3 vacante este cargo. En Sesi\u00f3n que tuvo lugar este s\u00e1bado 17 de agosto a las 12:00 horas, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-17T20:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marissa Palafox\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marissa Palafox\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/\"},\"author\":{\"name\":\"Marissa Palafox\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ea0920516f5277d3d81d090523946958\"},\"headline\":\"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo\",\"datePublished\":\"2024-08-17T20:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/\"},\"wordCount\":351,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/img_4398-1.jpg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/\",\"name\":\"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/img_4398-1.jpg\",\"datePublished\":\"2024-08-17T20:13:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/img_4398-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/img_4398-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/17\\\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ea0920516f5277d3d81d090523946958\",\"name\":\"Marissa Palafox\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g\",\"caption\":\"Marissa Palafox\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/marissa1\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/","og_locale":"es_MX","og_type":"article","og_title":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas","og_description":"Culiac\u00e1n, Sin.- El Pleno del Congreso del Estado de Sinaloa aprob\u00f3 por unanimidad, en Sesi\u00f3n Extraordinaria, la renuncia de la maestra Sara Bruna Qui\u00f1\u00f3nez Estrada a la titularidad de la Fiscal\u00eda General del Estado, por lo que declar\u00f3 vacante este cargo. En Sesi\u00f3n que tuvo lugar este s\u00e1bado 17 de agosto a las 12:00 horas, [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-08-17T20:13:16+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg","type":"image\/jpeg"}],"author":"Marissa Palafox","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Marissa Palafox","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/"},"author":{"name":"Marissa Palafox","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ea0920516f5277d3d81d090523946958"},"headline":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo","datePublished":"2024-08-17T20:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/"},"wordCount":351,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/","name":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg","datePublished":"2024-08-17T20:13:16+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/img_4398-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/17\/aprueban-diputados-renuncia-de-titular-de-fge-declara-vacante-el-cargo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Aprueban diputados renuncia de titular de FGE; declara vacante el cargo"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ea0920516f5277d3d81d090523946958","name":"Marissa Palafox","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ed69e134f8f3fc8287605cad3fe490a105c1493624a870aa61efbe8bdabd5b5?s=96&d=mm&r=g","caption":"Marissa Palafox"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/marissa1\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=88965"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88965\/revisions"}],"predecessor-version":[{"id":88966,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88965\/revisions\/88966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/88964"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=88965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=88965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=88965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}