{"id":88392,"date":"2024-08-08T16:04:06","date_gmt":"2024-08-08T23:04:06","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=88392"},"modified":"2024-08-09T08:45:59","modified_gmt":"2024-08-09T15:45:59","slug":"analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/","title":{"rendered":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- Consejeros y Consejeras de Institutos Locales Electorales de Coahuila, Michoac\u00e1n, Sonora y Chihuahua coincidieron que, si bien las acciones afirmativas son medidas especiales que obligan a dar un tratamiento preferencial y temporal hacia un grupo hist\u00f3ricamente y de m\u00faltiples formas discriminado, como lo es Comunidad LGBTTTIQ+, es necesario que se cuente con una normativa legal al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el Foro \u201cAn\u00e1lisis de las Acciones Afirmativas en favor de la Comunidad LGBTTTIQ+ implementadas en el Proceso Electoral 2024\u201d, organizado por el Instituto Electoral del Estado de Sinaloa (IEES), a trav\u00e9s de la Comisi\u00f3n de Igualdad de G\u00e9nero y Derechos Humanos, que preside la Consejera Electoral, Gloria Icela Garc\u00eda Cuadras, las y los invitados panelistas subrayaron que es necesario analizar si se debe transitar a la autoadscripci\u00f3n calificada para comprobar la pertenencia a dicha comunidad, para evitar candidaturas simuladas y fraudes en futuros procesos electorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje, el Consejero Presidente del IEES, Arturo Fajardo Mej\u00eda, resalt\u00f3 la importancia de escuchar experiencias de otros institutos locales electorales en cuanto a la aplicaci\u00f3n de acciones afirmativas hacia la comunidad LGBTTTQ+, y en ese sentido afirm\u00f3 que Sinaloa es el segundo proceso electoral en Sinaloa en que se implementan tales acciones de manera progresiva, por lo que dijo valorar la realizaci\u00f3n de este foro, para conocer la idoneidad de los lineamientos y en qu\u00e9 se puede mejorar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al evento asistieron las Consejeros y Consejeras de los Institutos Electorales de Coahuila, \u00d3scar Daniel Rodr\u00edguez Fuentes; de Michoac\u00e1n, Viridiana Villase\u00f1or Aguirre; de Sonora, Alma Lorena Alonso Valdivia; y de Chihuahua, Luis Eduardo Guti\u00e9rrez Ruiz, quienes adem\u00e1s compartieron sus experiencias en el establecimiento de acciones afirmativas y los resultados logrados en el pasado proceso electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como moderadora del evento fungi\u00f3 la Consejera Electoral e integrante de la Comisi\u00f3n de Igualdad de G\u00e9nero y Derechos Humanos del IEES, Marisol Quevedo Gonz\u00e1lez. De igual forma, asistieron la tambi\u00e9n integrante de dicha Comisi\u00f3n, Judith Gabriela L\u00f3pez Del Rinc\u00f3n y los Consejeros Electorales, Rafael Berm\u00fadez Soto, \u00d3scar S\u00e1nchez F\u00e9lix y Mart\u00edn Gonz\u00e1lez Burgos, as\u00ed como el Secretario Ejecutivo, Jos\u00e9 Guadalupe Guicho Rojas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al foro acudieron representantes de la Junta local del INE, Sinaloa Incluyente A.C. Comisi\u00f3n Estatal de Derechos Humanos, CEAIP, integrantes de los Consejos Distritales y Municipales, representantes de partidos, adem\u00e1s de organismos y asociaciones civiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sin.- Consejeros y Consejeras de Institutos Locales Electorales de Coahuila, Michoac\u00e1n, Sonora y Chihuahua coincidieron que, si bien las acciones afirmativas son medidas especiales que obligan a dar un tratamiento preferencial y temporal hacia un grupo hist\u00f3ricamente y de m\u00faltiples formas discriminado, como lo es Comunidad LGBTTTIQ+, es necesario que se cuente con una [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":88391,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-88392","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n, Sin.- Consejeros y Consejeras de Institutos Locales Electorales de Coahuila, Michoac\u00e1n, Sonora y Chihuahua coincidieron que, si bien las acciones afirmativas son medidas especiales que obligan a dar un tratamiento preferencial y temporal hacia un grupo hist\u00f3ricamente y de m\u00faltiples formas discriminado, como lo es Comunidad LGBTTTIQ+, es necesario que se cuente con una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-08T23:04:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-09T15:45:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica\",\"datePublished\":\"2024-08-08T23:04:06+00:00\",\"dateModified\":\"2024-08-09T15:45:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/\",\"name\":\"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg\",\"datePublished\":\"2024-08-08T23:04:06+00:00\",\"dateModified\":\"2024-08-09T15:45:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/08\\\/08\\\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/","og_locale":"es_MX","og_type":"article","og_title":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas","og_description":"Culiac\u00e1n, Sin.- Consejeros y Consejeras de Institutos Locales Electorales de Coahuila, Michoac\u00e1n, Sonora y Chihuahua coincidieron que, si bien las acciones afirmativas son medidas especiales que obligan a dar un tratamiento preferencial y temporal hacia un grupo hist\u00f3ricamente y de m\u00faltiples formas discriminado, como lo es Comunidad LGBTTTIQ+, es necesario que se cuente con una [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-08-08T23:04:06+00:00","article_modified_time":"2024-08-09T15:45:59+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica","datePublished":"2024-08-08T23:04:06+00:00","dateModified":"2024-08-09T15:45:59+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/"},"wordCount":424,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/","name":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg","datePublished":"2024-08-08T23:04:06+00:00","dateModified":"2024-08-09T15:45:59+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/08\/d44c5be6-eaa7-47c9-bc07-cbffaa5000c9-1.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/08\/08\/analizan-acciones-en-favor-de-la-comunidad-lgbt-dentro-de-la-politica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Analizan acciones en favor de la Comunidad LGBT+ dentro de la pol\u00edtica"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=88392"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88392\/revisions"}],"predecessor-version":[{"id":88393,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/88392\/revisions\/88393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/88391"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=88392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=88392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=88392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}