{"id":8724,"date":"2021-08-02T00:34:00","date_gmt":"2021-08-02T07:34:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=8724"},"modified":"2021-08-01T17:58:40","modified_gmt":"2021-08-02T00:58:40","slug":"graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/","title":{"rendered":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia"},"content":{"rendered":"\n<p><strong><em>Miles de millones de moscas aparecieron en Bielorrusia y provocaron incre\u00edbles im\u00e1genes.<\/em><\/strong><\/p>\n\n\n\n<p>Cada verano, cientos de miles de millones de huevos de&nbsp;<a href=\"https:\/\/www.excelsior.com.mx\/nacional\/a-donde-van-las-horripilantes-moscas-en-invierno\/1410794\" target=\"_blank\" rel=\"noreferrer noopener\">moscas&nbsp;<\/a>de mayo -o ef\u00edmeras- eclosionan y se &#8220;<strong>adue\u00f1an<\/strong>&#8221; del cielo de tal forma que da la sensaci\u00f3n de que nieva o graniza.<\/p>\n\n\n\n<p>Este peculiar insecto pasa aproximadamente el 99% de su vida como ninfa hasta que&nbsp;<strong>todas emergen<\/strong>, a menudo a la vez, durante &#8220;la eclosi\u00f3n&#8221; para el apareamiento. Las ef\u00edmeras adultas viven alrededor de un mes, generalmente menos, y se sienten atra\u00eddas por las grandes luces de la calle.<\/p>\n\n\n\n<p>Una vez fuera del cascar\u00f3n, las<a href=\"https:\/\/www.excelsior.com.mx\/global\/radiacion-de-celulares-mata-abejas-moscas-estudios\/1406248\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;moscas de mayo se re\u00fanen&nbsp;<\/a>en densos enjambres y pueden provocar la huida de personas. En Mogilve, Bielorrusia, una mujer captur\u00f3 en v\u00eddeo a un enjambre grande de estos insectos apoder\u00e1ndose de sus calles.<\/p>\n\n\n\n<p><strong>Karina Ovsyannikova<\/strong>, de 22 a\u00f1os, conduc\u00eda por la ciudad, cuando de repente se vio rodeada por un enjambre de estos insectos tan particulares.<\/p>\n\n\n\n<p>Al frenar el coche, lo que cre\u00eda que era nieve, resultaron ser moscas de mayo que pululaban por el cielo e intentaban aparearse.<\/p>\n\n\n\n<p>Los insectos cubr\u00edan la carretera, los sem\u00e1foros e&nbsp;<strong>incluso los caminos,<\/strong>&nbsp;y a medida que avanzaba aparec\u00edan m\u00e1s moscas.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Woman Surrounded By Swam Of Mayflies\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/IAR2kzKvJO0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Miles de millones de moscas aparecieron en Bielorrusia y provocaron incre\u00edbles im\u00e1genes. Cada verano, cientos de miles de millones de huevos de&nbsp;moscas&nbsp;de mayo -o ef\u00edmeras- eclosionan y se &#8220;adue\u00f1an&#8221; del cielo de tal forma que da la sensaci\u00f3n de que nieva o graniza. Este peculiar insecto pasa aproximadamente el 99% de su vida como ninfa [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":8735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[40],"tags":[290,193],"class_list":{"0":"post-8724","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-las-asombrosas","8":"tag-asombrosa","9":"tag-viral"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Miles de millones de moscas aparecieron en Bielorrusia y provocaron incre\u00edbles im\u00e1genes. Cada verano, cientos de miles de millones de huevos de&nbsp;moscas&nbsp;de mayo -o ef\u00edmeras- eclosionan y se &#8220;adue\u00f1an&#8221; del cielo de tal forma que da la sensaci\u00f3n de que nieva o graniza. Este peculiar insecto pasa aproximadamente el 99% de su vida como ninfa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-02T07:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Actualidad RT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Actualidad RT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/\"},\"author\":{\"name\":\"Actualidad RT\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/eade03a5d4a96f9b557ac266e3d63718\"},\"headline\":\"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia\",\"datePublished\":\"2021-08-02T07:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/\"},\"wordCount\":240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MOSCAS.jpg\",\"keywords\":[\"Asombrosa\",\"Viral\"],\"articleSection\":[\"LAS ASOMBROSAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/\",\"name\":\"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MOSCAS.jpg\",\"datePublished\":\"2021-08-02T07:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MOSCAS.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/MOSCAS.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/08\\\/02\\\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/eade03a5d4a96f9b557ac266e3d63718\",\"name\":\"Actualidad RT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g\",\"caption\":\"Actualidad RT\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/actualidad\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/","og_locale":"es_MX","og_type":"article","og_title":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas","og_description":"Miles de millones de moscas aparecieron en Bielorrusia y provocaron incre\u00edbles im\u00e1genes. Cada verano, cientos de miles de millones de huevos de&nbsp;moscas&nbsp;de mayo -o ef\u00edmeras- eclosionan y se &#8220;adue\u00f1an&#8221; del cielo de tal forma que da la sensaci\u00f3n de que nieva o graniza. Este peculiar insecto pasa aproximadamente el 99% de su vida como ninfa [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-08-02T07:34:00+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg","type":"image\/jpeg"}],"author":"Actualidad RT","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Actualidad RT","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/"},"author":{"name":"Actualidad RT","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/eade03a5d4a96f9b557ac266e3d63718"},"headline":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia","datePublished":"2021-08-02T07:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/"},"wordCount":240,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg","keywords":["Asombrosa","Viral"],"articleSection":["LAS ASOMBROSAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/","name":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg","datePublished":"2021-08-02T07:34:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/08\/MOSCAS.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/08\/02\/graban-a-monton-de-moscas-de-mayo-volando-por-calles-de-bielorrusia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Graban a mont\u00f3n de moscas de mayo volando por calles de Bielorrusia"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/eade03a5d4a96f9b557ac266e3d63718","name":"Actualidad RT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/443e88260a6a7111cf83d7014ab1894f91a4053ffd4e9da37d79effad3a35c81?s=96&d=mm&r=g","caption":"Actualidad RT"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/actualidad\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/8724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=8724"}],"version-history":[{"count":3,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/8724\/revisions"}],"predecessor-version":[{"id":8737,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/8724\/revisions\/8737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/8735"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=8724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=8724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=8724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}