{"id":82722,"date":"2024-05-29T06:29:29","date_gmt":"2024-05-29T13:29:29","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=82722"},"modified":"2024-05-29T06:29:29","modified_gmt":"2024-05-29T13:29:29","slug":"detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/","title":{"rendered":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n"},"content":{"rendered":"\n<p><strong><em>La Fiscal\u00eda General del Estado inform\u00f3 que la detenci\u00f3n se logr\u00f3 la madrugada de este martes<\/em><\/strong><\/p>\n\n\n\n<p>Culiac\u00e1n, Sin.- La Fiscal\u00eda General del Estado ejecut\u00f3 una orden de aprehensi\u00f3n contra el presunto asesino de tres personas, dos de ellas del sexo femenino, en una vivienda de la colonia San Ferm\u00edn, en la capital del estado.<\/p>\n\n\n\n<p>A trav\u00e9s de redes sociales, el \u00f3rgano aut\u00f3nomo de justicia revel\u00f3 que la madrugada de este martes se logr\u00f3 la detenci\u00f3n de una persona de sexo masculino, presunto homicida de dos jovencitas y un joven dentro de una vivienda, de acuerdo a la causa penal 520\/2024.<\/p>\n\n\n\n<p>Seg\u00fan las investigaciones la tarde del pasado 21 de mayo, los ocupantes de una unidad color blanco, con armas de fuego, subieron hasta un segundo piso de un conjunto habitacional, ubicado en la colonia San Ferm\u00edn, se introdujeron en forma violenta a una de las viviendas y privaron de la vida a tres personas.<\/p>\n\n\n\n<p>Los datos que se conocen de este hecho es que las v\u00edctimas fueron identificadas como Dulce \u201cN\u201d de 18 a\u00f1os, Jocelyn \u201cN\u201d de 22 a\u00f1os y el joven Alejandro \u201cN\u201d de 23 a\u00f1os, por lo que se abri\u00f3 una carpeta de investigaci\u00f3n.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General del Estado inform\u00f3 que la detenci\u00f3n se logr\u00f3 la madrugada de este martes Culiac\u00e1n, Sin.- La Fiscal\u00eda General del Estado ejecut\u00f3 una orden de aprehensi\u00f3n contra el presunto asesino de tres personas, dos de ellas del sexo femenino, en una vivienda de la colonia San Ferm\u00edn, en la capital del estado. A [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":49244,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":{"0":"post-82722","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nota-principal"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La Fiscal\u00eda General del Estado inform\u00f3 que la detenci\u00f3n se logr\u00f3 la madrugada de este martes Culiac\u00e1n, Sin.- La Fiscal\u00eda General del Estado ejecut\u00f3 una orden de aprehensi\u00f3n contra el presunto asesino de tres personas, dos de ellas del sexo femenino, en una vivienda de la colonia San Ferm\u00edn, en la capital del estado. A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T13:29:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Universal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Universal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/\"},\"author\":{\"name\":\"El Universal\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/fee3882e65fd0510d292c43a346d35d7\"},\"headline\":\"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n\",\"datePublished\":\"2024-05-29T13:29:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/\"},\"wordCount\":221,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/CARCEL.jpeg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/\",\"name\":\"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/CARCEL.jpeg\",\"datePublished\":\"2024-05-29T13:29:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/CARCEL.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/CARCEL.jpeg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/05\\\/29\\\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/fee3882e65fd0510d292c43a346d35d7\",\"name\":\"El Universal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"caption\":\"El Universal\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/el-universal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/","og_locale":"es_MX","og_type":"article","og_title":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas","og_description":"La Fiscal\u00eda General del Estado inform\u00f3 que la detenci\u00f3n se logr\u00f3 la madrugada de este martes Culiac\u00e1n, Sin.- La Fiscal\u00eda General del Estado ejecut\u00f3 una orden de aprehensi\u00f3n contra el presunto asesino de tres personas, dos de ellas del sexo femenino, en una vivienda de la colonia San Ferm\u00edn, en la capital del estado. A [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-05-29T13:29:29+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg","type":"image\/jpeg"}],"author":"El Universal","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Universal","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/"},"author":{"name":"El Universal","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/fee3882e65fd0510d292c43a346d35d7"},"headline":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n","datePublished":"2024-05-29T13:29:29+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/"},"wordCount":221,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/","name":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg","datePublished":"2024-05-29T13:29:29+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/CARCEL.jpeg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/05\/29\/detienen-a-presunto-asesino-de-dos-mujeres-y-un-hombre-en-culiacan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Detienen a presunto asesino de dos mujeres y un hombre en Culiac\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/fee3882e65fd0510d292c43a346d35d7","name":"El Universal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","caption":"El Universal"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/el-universal\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/82722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=82722"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/82722\/revisions"}],"predecessor-version":[{"id":82724,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/82722\/revisions\/82724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/49244"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=82722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=82722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=82722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}