{"id":80512,"date":"2024-04-30T07:03:02","date_gmt":"2024-04-30T14:03:02","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=80512"},"modified":"2024-04-30T07:03:02","modified_gmt":"2024-04-30T14:03:02","slug":"banda-el-recodo-80-anos-de-historia","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/","title":{"rendered":"Banda El Recodo, 80 a\u00f1os de historia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Material Exclusivo para Fuentes Fidedignas<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recientemente se present\u00f3 en Sinaloa el libro \u201cEl Recodo, 80 a\u00f1os de trayectoria entre amigos\u201d, durante la Feria del Libro de la Universidad Aut\u00f3noma de Sinaloa, celebrada en Mazatl\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior me hizo recordar una de tantas entrevistas realizadas por un servidor al propio fundador de la madre de todas las bandas, Don Cruz Liz\u00e1rraga, justo en la d\u00e9cada de los 90&#8217;s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese entonces fui testigo de la gran sencillez y humildad de un gran m\u00fasico, quien nos present\u00f3 en ese entonces con el vocalista Julio Preciado y sus herederos, Germ\u00e1n, Alfonso y Joel Liz\u00e1rraga.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"493\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-1024x493.jpeg\" alt=\"\" class=\"wp-image-80513\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-1024x493.jpeg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-300x144.jpeg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-768x370.jpeg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-1536x739.jpeg 1536w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-873x420.jpeg 873w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-600x289.jpeg 600w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-696x335.jpeg 696w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-1392x670.jpeg 1392w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2-1068x514.jpeg 1068w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-2.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Don Cruz naci\u00f3 en 1918, en el poblado de El Recodo, cercano a Mazatl\u00e1n, de ah\u00ed la raz\u00f3n del nombre de la agrupaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por cierto, son la \u00fanica banda que ha pisado los cinco continentes, llevando su m\u00fasica y representando a Sinaloa a millones de personas en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, han acompa\u00f1ado a la selecci\u00f3n mexicana de f\u00fatbol en eventos mundiales, representando as\u00ed a la cultura mexicana.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"714\" height=\"675\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM.jpeg\" alt=\"\" class=\"wp-image-80516\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM.jpeg 714w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM-300x284.jpeg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM-444x420.jpeg 444w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM-600x567.jpeg 600w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.49-AM-696x658.jpeg 696w\" sizes=\"(max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El Recodo, bajo la direcci\u00f3n de Luis Alfonso Liz\u00e1rraga, ha grabado m\u00e1s de 180 \u00e1lbumes y han vendido por arriba de los 20 millones de discos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista con Don Cruz Liz\u00e1rraga, QEPD, jam\u00e1s olvidar\u00e9 su promesa cumplida: \u201cNo descansar\u00e9 hasta que la m\u00fasica de banda se escuche en todos los rincones de la tierra\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por todo lo anterior, muy atinada la publicaci\u00f3n del libro, 80 a\u00f1os de historia.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"518\" height=\"656\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM.jpeg\" alt=\"\" class=\"wp-image-80515\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM.jpeg 518w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-237x300.jpeg 237w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-332x420.jpeg 332w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-300x380.jpeg 300w\" sizes=\"(max-width: 518px) 100vw, 518px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Material Exclusivo para Fuentes Fidedignas Recientemente se present\u00f3 en Sinaloa el libro \u201cEl Recodo, 80 a\u00f1os de trayectoria entre amigos\u201d, durante la Feria del Libro de la Universidad Aut\u00f3noma de Sinaloa, celebrada en Mazatl\u00e1n. Lo anterior me hizo recordar una de tantas entrevistas realizadas por un servidor al propio fundador de la madre de todas [&hellip;]<\/p>\n","protected":false},"author":156,"featured_media":80514,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3064,3092],"tags":[],"class_list":["post-80512","post","type-post","status-publish","format-standard","has-post-thumbnail","category-columnas","category-guiri-guireando"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Material Exclusivo para Fuentes Fidedignas Recientemente se present\u00f3 en Sinaloa el libro \u201cEl Recodo, 80 a\u00f1os de trayectoria entre amigos\u201d, durante la Feria del Libro de la Universidad Aut\u00f3noma de Sinaloa, celebrada en Mazatl\u00e1n. Lo anterior me hizo recordar una de tantas entrevistas realizadas por un servidor al propio fundador de la madre de todas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-30T14:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Fernando Valencia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Fernando Valencia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/\"},\"author\":{\"name\":\"Luis Fernando Valencia\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f76dfc7f6fd76a393e3c7f2ea3edd188\"},\"headline\":\"Banda El Recodo, 80 a\u00f1os de historia\",\"datePublished\":\"2024-04-30T14:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/\"},\"wordCount\":264,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg\",\"articleSection\":[\"COLUMNAS\",\"G\u00dcIRI G\u00dcIREANDO\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/\",\"name\":\"Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg\",\"datePublished\":\"2024-04-30T14:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg\",\"width\":1600,\"height\":1170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/30\\\/banda-el-recodo-80-anos-de-historia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banda El Recodo, 80 a\u00f1os de historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f76dfc7f6fd76a393e3c7f2ea3edd188\",\"name\":\"Luis Fernando Valencia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g\",\"caption\":\"Luis Fernando Valencia\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/luis-fernando-valencia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/","og_locale":"es_MX","og_type":"article","og_title":"Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas","og_description":"Material Exclusivo para Fuentes Fidedignas Recientemente se present\u00f3 en Sinaloa el libro \u201cEl Recodo, 80 a\u00f1os de trayectoria entre amigos\u201d, durante la Feria del Libro de la Universidad Aut\u00f3noma de Sinaloa, celebrada en Mazatl\u00e1n. Lo anterior me hizo recordar una de tantas entrevistas realizadas por un servidor al propio fundador de la madre de todas [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-04-30T14:03:02+00:00","og_image":[{"width":1600,"height":1170,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg","type":"image\/jpeg"}],"author":"Luis Fernando Valencia","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Luis Fernando Valencia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/"},"author":{"name":"Luis Fernando Valencia","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f76dfc7f6fd76a393e3c7f2ea3edd188"},"headline":"Banda El Recodo, 80 a\u00f1os de historia","datePublished":"2024-04-30T14:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/"},"wordCount":264,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg","articleSection":["COLUMNAS","G\u00dcIRI G\u00dcIREANDO"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/","name":"Banda El Recodo, 80 a\u00f1os de historia - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg","datePublished":"2024-04-30T14:03:02+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-30-at-6.16.50-AM-1.jpeg","width":1600,"height":1170},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/30\/banda-el-recodo-80-anos-de-historia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Banda El Recodo, 80 a\u00f1os de historia"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f76dfc7f6fd76a393e3c7f2ea3edd188","name":"Luis Fernando Valencia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/24f95111b9916e20a37129f996dda464c1c3cc8cc4d550f48d57628ed76cbd0d?s=96&d=mm&r=g","caption":"Luis Fernando Valencia"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/luis-fernando-valencia\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/156"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=80512"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80512\/revisions"}],"predecessor-version":[{"id":80517,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80512\/revisions\/80517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80514"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=80512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=80512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=80512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}