{"id":80019,"date":"2024-04-23T15:51:41","date_gmt":"2024-04-23T22:51:41","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=80019"},"modified":"2024-04-23T15:56:51","modified_gmt":"2024-04-23T22:56:51","slug":"luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/","title":{"rendered":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- El diputado Jos\u00e9 Manuel Luque Rojas, integrante del Grupo Parlamentario de Morena, emiti\u00f3 un fuerte posicionamiento ante el pleno, en defensa de la creaci\u00f3n del Fondo de Pensiones para el Bienestar, medida impulsada por el Gobierno Federal para garantizar ingresos dignos a los trabajadores durante su retiro laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador coment\u00f3 que la campa\u00f1a de odio y desprestigio que ha emprendido la oposici\u00f3n en torno a este Fondo, sobre el que han difundido informaci\u00f3n falsa para desinformar a la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luque Rojas explic\u00f3 que el objetivo del Fondo es rescatar a los trabajadores afectados por las reformas de 1997 y 2007 al sistema de pensiones, que pr\u00e1cticamente fueron un robo en despoblado contra el ingreso de las familias mexicanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Lo que se busca es complementar y garantizar que cada trabajador, al alcanzar los a\u00f1os laborados o la edad, se pensione con el 100 por ciento de su salario promedio de los \u00faltimos cinco a\u00f1os, como establece la ley<\/strong>&#8220;, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado morenista ejemplific\u00f3 que, con las reformas de 1997, algunos trabajadores con ingresos mensuales de 10 mil pesos, solo recib\u00edan pensiones de alrededor de 2 mil 700 pesos del anterior sistema de Ahorro para el Retiro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que con la reforma de 2020, fue posible incrementar levemente esas pensiones a 6 mil 700 pesos en casos similares, pero la nueva reforma, permite ahora que ese mismo trabajador perciba una pensi\u00f3n completa de 10,000 pesos al jubilarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luque Rojas aclar\u00f3 que el Fondo aprobado, no sustituye el sistema de cuentas individuales, sino que lo complementa para asegurar pensiones dignas y no de miseria como ocurr\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, mencion\u00f3 que se reintegrar\u00e1n al Fondo unos 40 mil 000 millones de pesos no reclamados desde hace 10 a\u00f1os en las Afores, cantidad que representa solo el 0.66 por ciento del total ahorrado en ese sistema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Es un monto menor, pero los banqueros y empresarios son tan mezquinos que les molesta entregarlo para dignificar el ingreso de los trabajadores<\/strong>&#8220;, denunci\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador exhort\u00f3 a la ciudadan\u00eda a no caer en la &#8220;infodemia&#8221; de las cr\u00edticas opositoras, y apoyar el proyecto de la Cuarta Transformaci\u00f3n para garantizar un retiro digno a todos los trabajadores del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sin.- El diputado Jos\u00e9 Manuel Luque Rojas, integrante del Grupo Parlamentario de Morena, emiti\u00f3 un fuerte posicionamiento ante el pleno, en defensa de la creaci\u00f3n del Fondo de Pensiones para el Bienestar, medida impulsada por el Gobierno Federal para garantizar ingresos dignos a los trabajadores durante su retiro laboral. El legislador coment\u00f3 que la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":50520,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-80019","post","type-post","status-publish","format-standard","has-post-thumbnail","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Culiac\u00e1n, Sin.- El diputado Jos\u00e9 Manuel Luque Rojas, integrante del Grupo Parlamentario de Morena, emiti\u00f3 un fuerte posicionamiento ante el pleno, en defensa de la creaci\u00f3n del Fondo de Pensiones para el Bienestar, medida impulsada por el Gobierno Federal para garantizar ingresos dignos a los trabajadores durante su retiro laboral. El legislador coment\u00f3 que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-23T22:51:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-23T22:56:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"409\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar\",\"datePublished\":\"2024-04-23T22:51:41+00:00\",\"dateModified\":\"2024-04-23T22:56:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/\"},\"wordCount\":379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lluque-e1687299415570.jpg\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/\",\"name\":\"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lluque-e1687299415570.jpg\",\"datePublished\":\"2024-04-23T22:51:41+00:00\",\"dateModified\":\"2024-04-23T22:56:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lluque-e1687299415570.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/lluque-e1687299415570.jpg\",\"width\":600,\"height\":409},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/23\\\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/","og_locale":"es_MX","og_type":"article","og_title":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas","og_description":"Culiac\u00e1n, Sin.- El diputado Jos\u00e9 Manuel Luque Rojas, integrante del Grupo Parlamentario de Morena, emiti\u00f3 un fuerte posicionamiento ante el pleno, en defensa de la creaci\u00f3n del Fondo de Pensiones para el Bienestar, medida impulsada por el Gobierno Federal para garantizar ingresos dignos a los trabajadores durante su retiro laboral. El legislador coment\u00f3 que la [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-04-23T22:51:41+00:00","article_modified_time":"2024-04-23T22:56:51+00:00","og_image":[{"width":600,"height":409,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar","datePublished":"2024-04-23T22:51:41+00:00","dateModified":"2024-04-23T22:56:51+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/"},"wordCount":379,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg","inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/","name":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg","datePublished":"2024-04-23T22:51:41+00:00","dateModified":"2024-04-23T22:56:51+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/06\/lluque-e1687299415570.jpg","width":600,"height":409},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/23\/luque-rojas-defiende-creacion-del-fondo-de-pensiones-para-el-bienestar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Luque Rojas defiende creaci\u00f3n del Fondo de Pensiones para el Bienestar"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=80019"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80019\/revisions"}],"predecessor-version":[{"id":80020,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/80019\/revisions\/80020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/50520"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=80019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=80019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=80019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}