{"id":79774,"date":"2024-04-19T20:15:27","date_gmt":"2024-04-20T03:15:27","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=79774"},"modified":"2024-04-19T20:16:01","modified_gmt":"2024-04-20T03:16:01","slug":"para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/","title":{"rendered":"&#8220;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&#8221;: Cu\u00e9n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;Ag\u00e1rrense porque voy a ser Diputado Federal y desde all\u00e1 voy a impulsar pol\u00edticas p\u00fablicas de desarrollo y sustentabilidad para ofrecer oportunidades a los j\u00f3venes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">GUASAVE.- H\u00e9ctor Melesio Cu\u00e9n Ojeda sostuvo un encuentro con cientos de j\u00f3venes de Guasave, donde se\u00f1al\u00f3 que el gobierno les ha quedado a deber, sobre todo en educaci\u00f3n e inversi\u00f3n para generar oportunidades que pongan a prueba sus conocimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El candidato a Diputado Federal destac\u00f3 sobre el contacto y su experiencia en trabajar con j\u00f3venes; adem\u00e1s, les pidi\u00f3 que fueran responsables y que este 2 de junio salgan a votar, que no se queden de brazos cruzados y de esta manera no ser\u00e1n c\u00f3mplices de la corrupci\u00f3n, de la violencia y de la falta de espacios educativos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cu\u00e9n Ojeda expres\u00f3: &#8220;Ag\u00e1rrense porque voy a ser Diputado Federal y desde all\u00e1 voy a impulsar pol\u00edticas p\u00fablicas de desarrollo y sustentabilidad para ofrecer oportunidades a los j\u00f3venes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Alba Virgen Montes, candidata a la Presidencia Municipal de Guasave, indic\u00f3 que el PAS es un partido que suma a la juventud y que los incluye en la pol\u00edtica al brindar una de cada tres candidaturas en estas elecciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Quiero ser presidenta de Guasave para apoyar a los j\u00f3venes que este gobierno tiene en el olvido, igual que a los ganaderos y pescadores. Guasave es semillero de j\u00f3venes deportistas y a eso le apostamos, al deporte, la educaci\u00f3n y la cultura&#8221;, afirm\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Ag\u00e1rrense porque voy a ser Diputado Federal y desde all\u00e1 voy a impulsar pol\u00edticas p\u00fablicas de desarrollo y sustentabilidad para ofrecer oportunidades a los j\u00f3venes\u201d. GUASAVE.- H\u00e9ctor Melesio Cu\u00e9n Ojeda sostuvo un encuentro con cientos de j\u00f3venes de Guasave, donde se\u00f1al\u00f3 que el gobierno les ha quedado a deber, sobre todo en educaci\u00f3n e inversi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":79775,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[38],"tags":[],"class_list":["post-79774","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-locales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&quot;: Cu\u00e9n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&quot;: Cu\u00e9n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"&#8220;Ag\u00e1rrense porque voy a ser Diputado Federal y desde all\u00e1 voy a impulsar pol\u00edticas p\u00fablicas de desarrollo y sustentabilidad para ofrecer oportunidades a los j\u00f3venes\u201d. GUASAVE.- H\u00e9ctor Melesio Cu\u00e9n Ojeda sostuvo un encuentro con cientos de j\u00f3venes de Guasave, donde se\u00f1al\u00f3 que el gobierno les ha quedado a deber, sobre todo en educaci\u00f3n e inversi\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-20T03:15:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-20T03:16:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"347\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"&#8220;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&#8221;: Cu\u00e9n\",\"datePublished\":\"2024-04-20T03:15:27+00:00\",\"dateModified\":\"2024-04-20T03:16:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/PAS_GVE.jpg\",\"articleSection\":[\"NOTICIAS LOCALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/\",\"name\":\"\\\"Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta\\\": Cu\u00e9n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/PAS_GVE.jpg\",\"datePublished\":\"2024-04-20T03:15:27+00:00\",\"dateModified\":\"2024-04-20T03:16:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/PAS_GVE.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/PAS_GVE.jpg\",\"width\":600,\"height\":347},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/19\\\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&#8221;: Cu\u00e9n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta\": Cu\u00e9n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/","og_locale":"es_MX","og_type":"article","og_title":"\"Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta\": Cu\u00e9n - Fuentes Fidedignas","og_description":"&#8220;Ag\u00e1rrense porque voy a ser Diputado Federal y desde all\u00e1 voy a impulsar pol\u00edticas p\u00fablicas de desarrollo y sustentabilidad para ofrecer oportunidades a los j\u00f3venes\u201d. GUASAVE.- H\u00e9ctor Melesio Cu\u00e9n Ojeda sostuvo un encuentro con cientos de j\u00f3venes de Guasave, donde se\u00f1al\u00f3 que el gobierno les ha quedado a deber, sobre todo en educaci\u00f3n e inversi\u00f3n [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-04-20T03:15:27+00:00","article_modified_time":"2024-04-20T03:16:01+00:00","og_image":[{"width":600,"height":347,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"&#8220;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&#8221;: Cu\u00e9n","datePublished":"2024-04-20T03:15:27+00:00","dateModified":"2024-04-20T03:16:01+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg","articleSection":["NOTICIAS LOCALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/","name":"\"Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta\": Cu\u00e9n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg","datePublished":"2024-04-20T03:15:27+00:00","dateModified":"2024-04-20T03:16:01+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/PAS_GVE.jpg","width":600,"height":347},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/19\/para-construir-un-mejor-mexico-y-un-mejor-sinaloa-la-participacion-de-los-jovenes-cuenta-cuen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"&#8220;Para construir un mejor M\u00e9xico y un mejor Sinaloa, la participaci\u00f3n de los j\u00f3venes cuenta&#8221;: Cu\u00e9n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=79774"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79774\/revisions"}],"predecessor-version":[{"id":79777,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79774\/revisions\/79777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/79775"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=79774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=79774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=79774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}