{"id":79589,"date":"2024-04-18T07:02:40","date_gmt":"2024-04-18T14:02:40","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=79589"},"modified":"2024-04-18T14:39:34","modified_gmt":"2024-04-18T21:39:34","slug":"como-la-vida-imprime-la-realidad-resistencia-al-flautista","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/","title":{"rendered":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista"},"content":{"rendered":"\n<p>Nos sorprende la informaci\u00f3n a la estamos teniendo acceso en estos \u00faltimos a\u00f1os, la Inteligencia Artificial y la Impresi\u00f3n 3D de tejido org\u00e1nico, pero en la naturaleza es un hecho diario y permanente, claro, millones de veces m\u00e1s r\u00e1pido.<\/p>\n\n\n\n<p>El ser humano intenta permanentemente imitar a la naturaleza y en muchos aspectos sustituirla con su propio entorno, un aspecto que parte de la b\u00fasqueda del control.<\/p>\n\n\n\n<p>Al final perdemos la perspectiva, porque buscamos nichos de mercado cada vez m\u00e1s acotados por empresarios que venden lo que est\u00e1 al alcance de todos.<\/p>\n\n\n\n<p>El capitalismo siempre est\u00e1 intentando ganar la siguiente revoluci\u00f3n tecnol\u00f3gica, pero adem\u00e1s ahora afirman que se trata de una nueva realidad con la Inteligencia Artificial Generativa.<\/p>\n\n\n\n<p>La industria 4.0, un concepto alem\u00e1n que imita a la Internet de las Cosas de Jap\u00f3n, es una parte de la Revoluci\u00f3n Tecnol\u00f3gica inicial, como las c\u00e1maras de reconocimiento facial en China a trav\u00e9s de datos biom\u00e9tricos; lo que estamos presenciando es la toma de decisiones aut\u00f3nomas por parte de la IA y el cambio de ruta en pleno proceso de operaci\u00f3n de las acciones, aspecto que intenta imitar de forma m\u00e1s eficiente a la naturaleza.<\/p>\n\n\n\n<p>La programaci\u00f3n de Lenguaje Neuronal, es en los hechos la imitaci\u00f3n del lenguaje humano y la intenci\u00f3n de desarrollar la realidad en un ordenador, una &#8220;nueva econom\u00eda&#8221; de los Datos, la interacci\u00f3n entre el Big Data y la autonom\u00eda en las decisiones, con lo que se busca suplantar a trav\u00e9s de lo artificial la realidad, conformando una realidad virtual en la que los par\u00e1metros de la vida sean predecibles nulificando la autodeterminaci\u00f3n y pautando la especulaci\u00f3n financiera, el sue\u00f1o de un dictador o emperador.<\/p>\n\n\n\n<p>Nos enfrentamos a una suplantaci\u00f3n de la naturaleza, al intento de imprimir la realidad, de deslindar al ser humano de las condiciones espacio-temporales que lo anclan a su condici\u00f3n de consciencia de la naturaleza, comprometiendo aspectos axiol\u00f3gicos y ontol\u00f3gicos de lo humano, intentado y llevando adelante una dependencia artificial de la tecnolog\u00eda en cada acci\u00f3n de la vida, un nuevo futuro, una melod\u00eda del Flautista, un enga\u00f1o por separarnos a\u00fan m\u00e1s de la tierra y vendernos el aire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos sorprende la informaci\u00f3n a la estamos teniendo acceso en estos \u00faltimos a\u00f1os, la Inteligencia Artificial y la Impresi\u00f3n 3D de tejido org\u00e1nico, pero en la naturaleza es un hecho diario y permanente, claro, millones de veces m\u00e1s r\u00e1pido. El ser humano intenta permanentemente imitar a la naturaleza y en muchos aspectos sustituirla con su [&hellip;]<\/p>\n","protected":false},"author":144,"featured_media":79591,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[3064,3088],"tags":[],"class_list":{"0":"post-79589","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-columnas","8":"category-escritos-al-carbon"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Nos sorprende la informaci\u00f3n a la estamos teniendo acceso en estos \u00faltimos a\u00f1os, la Inteligencia Artificial y la Impresi\u00f3n 3D de tejido org\u00e1nico, pero en la naturaleza es un hecho diario y permanente, claro, millones de veces m\u00e1s r\u00e1pido. El ser humano intenta permanentemente imitar a la naturaleza y en muchos aspectos sustituirla con su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T14:02:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-18T21:39:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"FRANCISCO MORALES ZEPEDA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FRANCISCO MORALES ZEPEDA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/\"},\"author\":{\"name\":\"FRANCISCO MORALES ZEPEDA\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/6640c7c8af5ac0bcd172eb834c670df1\"},\"headline\":\"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista\",\"datePublished\":\"2024-04-18T14:02:40+00:00\",\"dateModified\":\"2024-04-18T21:39:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/inteligencia-artificial.jpg\",\"articleSection\":[\"COLUMNAS\",\"ESCRITOS AL CARB\u00d3N\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/\",\"name\":\"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/inteligencia-artificial.jpg\",\"datePublished\":\"2024-04-18T14:02:40+00:00\",\"dateModified\":\"2024-04-18T21:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/inteligencia-artificial.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/inteligencia-artificial.jpg\",\"width\":600,\"height\":427},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/04\\\/18\\\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/6640c7c8af5ac0bcd172eb834c670df1\",\"name\":\"FRANCISCO MORALES ZEPEDA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g\",\"caption\":\"FRANCISCO MORALES ZEPEDA\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/francismo-morales-zepeda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas","og_description":"Nos sorprende la informaci\u00f3n a la estamos teniendo acceso en estos \u00faltimos a\u00f1os, la Inteligencia Artificial y la Impresi\u00f3n 3D de tejido org\u00e1nico, pero en la naturaleza es un hecho diario y permanente, claro, millones de veces m\u00e1s r\u00e1pido. El ser humano intenta permanentemente imitar a la naturaleza y en muchos aspectos sustituirla con su [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-04-18T14:02:40+00:00","article_modified_time":"2024-04-18T21:39:34+00:00","og_image":[{"width":600,"height":427,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg","type":"image\/jpeg"}],"author":"FRANCISCO MORALES ZEPEDA","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"FRANCISCO MORALES ZEPEDA","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/"},"author":{"name":"FRANCISCO MORALES ZEPEDA","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/6640c7c8af5ac0bcd172eb834c670df1"},"headline":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista","datePublished":"2024-04-18T14:02:40+00:00","dateModified":"2024-04-18T21:39:34+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg","articleSection":["COLUMNAS","ESCRITOS AL CARB\u00d3N"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/","name":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg","datePublished":"2024-04-18T14:02:40+00:00","dateModified":"2024-04-18T21:39:34+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/04\/inteligencia-artificial.jpg","width":600,"height":427},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/04\/18\/como-la-vida-imprime-la-realidad-resistencia-al-flautista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo la vida imprime la Realidad? Resistencia al Flautista"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/6640c7c8af5ac0bcd172eb834c670df1","name":"FRANCISCO MORALES ZEPEDA","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/be738775789ce0aa2aeecbfc33425ce3b878acf8b9d6ead9942fcb6500ad1126?s=96&d=mm&r=g","caption":"FRANCISCO MORALES ZEPEDA"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/francismo-morales-zepeda\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/144"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=79589"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79589\/revisions"}],"predecessor-version":[{"id":79590,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/79589\/revisions\/79590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/79591"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=79589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=79589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=79589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}