{"id":73983,"date":"2024-02-15T08:57:11","date_gmt":"2024-02-15T15:57:11","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=73983"},"modified":"2024-02-15T08:57:49","modified_gmt":"2024-02-15T15:57:49","slug":"mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/","title":{"rendered":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>El presidente de M\u00e9xico lament\u00f3 los hechos. Es la segunda v\u00edctima mortal originaria de M\u00e9xico tras tiroteos en Estados Unidos<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kansas City.- La secretaria de Relaciones Exteriores, Alicia B\u00e1rcena, lament\u00f3 la muerte de&nbsp;<strong>Lisa L\u00f3pez-Galv\u00e1n,<\/strong>&nbsp;v\u00edctima del tiroteo ocurrido el mi\u00e9rcoles 14 de febrero en&nbsp;<strong>Kansas City&nbsp;<\/strong>durante el desfile por la victoria de los&nbsp;<strong>Chiefs<\/strong>&nbsp;en el&nbsp;<strong>Super Bowl<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer, hija de padres mexicanos, falleci\u00f3 en el hospital cuando recib\u00eda atenci\u00f3n m\u00e9dica.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Con enorme pesar quiero expresar nuestro sentido p\u00e9same y solidaridad a la familia y amistades de Lisa L\u00f3pez-Galv\u00e1n, destacada integrante con ra\u00edces mexicanas  de Kansas City, quien perdi\u00f3 la vida en los lamentables sucesos del d\u00eda de hoy. Apoyo total de Mexico <a href=\"https:\/\/twitter.com\/ConsulMexKan?ref_src=twsrc%5Etfw\">@ConsulMexKan<\/a><\/p>&mdash; Alicia B\u00e1rcena (@aliciabarcena) <a href=\"https:\/\/twitter.com\/aliciabarcena\/status\/1758134038156746972?ref_src=twsrc%5Etfw\">February 15, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El tradicional desfile de la victoria recorri\u00f3 la ciudad hasta Union Station, donde ocurrieron los disparos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Presidente lamenta fallecimiento<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa desde Acapulco, Guerrero, el presidente de la Rep\u00fablica, Andr\u00e9s Manuel L\u00f3pez Obrador lament\u00f3 el fallecimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs hija de padres mexicanos, es una se\u00f1ora joven. Nos duele\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de la SRE detall\u00f3 que un ni\u00f1o -hijo de mexicanos- tambi\u00e9n result\u00f3 herido, adem\u00e1s de que desde el consulado en Kansas City est\u00e1n atentos de si hay m\u00e1s connacionales entre los 21 heridos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQui\u00e9n era Lisa L\u00f3pez-Galv\u00e1n?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La mujer se dedicaba a la locuci\u00f3n y era conductora del programa \u201cTaste of Tejano\u201d, inform\u00f3 la emisora KKFI al informar sobre su fallecimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lisa L\u00f3pez-Galv\u00e1n comparti\u00f3 en entrevista con&nbsp;<em>Kansas City Hispanic News<\/em>, c\u00f3mo naci\u00f3 su gusto por la m\u00fasica. Narr\u00f3 que su padre Beto L\u00f3pez emigr\u00f3 a Estados Unidos desde el municipio de La Barca, Jalisco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El padre de Lisa se integr\u00f3 a diversas bandas musicales y mariachis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuentes cercanas a L\u00f3pez Galv\u00e1n coincidieron en describirla como una madre de familia extrovertida. Asisti\u00f3 al festejo del equipo de f\u00fatbol americano junto a su esposo quien tambi\u00e9n result\u00f3 herido.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Presidente de EU exige prohibir venta de armas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Esta tragedia llev\u00f3 al presidente estadounidense Joe Biden a clamar por la prohibici\u00f3n de las armas de asalto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El suceso de hoy (mi\u00e9rcoles) deber\u00eda movilizarnos, chocarnos, avergonzarnos para que actuemos&#8221;, dijo Biden en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario inst\u00f3 a los estadounidenses a &#8220;hacer o\u00edr su voz en el Congreso, para as\u00ed poder al fin actuar y prohibir las armas de asalto, limitar los cargadores de gran capacidad, reforzar los controles de antecedentes, y mantener las armas fuera del alcance de quienes no tienen por qu\u00e9 poseerlas o manejarlas&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ocho personas en riesgo de muerte fueron llevadas al hospital en los primeros diez minutos despu\u00e9s del tiroteo, indic\u00f3 Ross Grundyson, jefe de bomberos de esta&nbsp;<strong><em>ciudad<\/em><\/strong>&nbsp;del estado de Misuri (centro de Estados Unidos).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hay ocho personas que se encuentran en riesgo de muerte, siete con heridas graves y seis con lesiones leves&#8221;, detall\u00f3 en una rueda de prensa Grundyson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jefa de la polic\u00eda local Stacey Graves confirm\u00f3 la muerte de una persona por el tiroteo que ocurri\u00f3 en las proximidades de la estaci\u00f3n Union Station, a metros apenas del lugar en el cual los Chiefs celebraron con los fan\u00e1ticos su triunfo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta ahora hay tres detenidos, indicaron las autoridades.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Segundo mexicano fallecido<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Con la muerte de Lisa, suman dos connacionales que forman parte de las v\u00edctimas mortales por hechos violentos en EU. El martes 13 de enero, el c\u00f3nsul general de M\u00e9xico en Nueva York, Jorge Islas, confirm\u00f3 que&nbsp;<a class=\"Link\" href=\"https:\/\/politica.expansion.mx\/mexico\/2024\/02\/13\/mexicano-fallece-tiroteo-metro-nueva-york\" target=\"_blank\" rel=\"noreferrer noopener\">la persona que falleci\u00f3 ayer en un tiroteo en el Metro de la ciudad, era mexicana<\/a>&nbsp;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLamentablemente el d\u00eda de ayer por la tarde, falleci\u00f3 por una bala perdida, un connacional oriundo de Tehuac\u00e1n, Puebla en la estaci\u00f3n de metro Mount Eden, del Brox\u201d, public\u00f3 en su cuenta de \ud835\udd4f.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mexicano fue identificado como Obed Beltr\u00e1n-S\u00e1nchez de aproximadamente 35 a\u00f1os y muri\u00f3 el lunes 12 de febrero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de M\u00e9xico lament\u00f3 los hechos. Es la segunda v\u00edctima mortal originaria de M\u00e9xico tras tiroteos en Estados Unidos Kansas City.- La secretaria de Relaciones Exteriores, Alicia B\u00e1rcena, lament\u00f3 la muerte de&nbsp;Lisa L\u00f3pez-Galv\u00e1n,&nbsp;v\u00edctima del tiroteo ocurrido el mi\u00e9rcoles 14 de febrero en&nbsp;Kansas City&nbsp;durante el desfile por la victoria de los&nbsp;Chiefs&nbsp;en el&nbsp;Super Bowl. La mujer, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":73982,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-73983","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El presidente de M\u00e9xico lament\u00f3 los hechos. Es la segunda v\u00edctima mortal originaria de M\u00e9xico tras tiroteos en Estados Unidos Kansas City.- La secretaria de Relaciones Exteriores, Alicia B\u00e1rcena, lament\u00f3 la muerte de&nbsp;Lisa L\u00f3pez-Galv\u00e1n,&nbsp;v\u00edctima del tiroteo ocurrido el mi\u00e9rcoles 14 de febrero en&nbsp;Kansas City&nbsp;durante el desfile por la victoria de los&nbsp;Chiefs&nbsp;en el&nbsp;Super Bowl. La mujer, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-15T15:57:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T15:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"314\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reuters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reuters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/\"},\"author\":{\"name\":\"Reuters\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\"},\"headline\":\"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos\",\"datePublished\":\"2024-02-15T15:57:11+00:00\",\"dateModified\":\"2024-02-15T15:57:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/\"},\"wordCount\":657,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/img_1160.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/\",\"name\":\"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/img_1160.jpg\",\"datePublished\":\"2024-02-15T15:57:11+00:00\",\"dateModified\":\"2024-02-15T15:57:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/img_1160.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/img_1160.jpg\",\"width\":600,\"height\":314},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/15\\\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\",\"name\":\"Reuters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"caption\":\"Reuters\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/reuters\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/","og_locale":"es_MX","og_type":"article","og_title":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas","og_description":"El presidente de M\u00e9xico lament\u00f3 los hechos. Es la segunda v\u00edctima mortal originaria de M\u00e9xico tras tiroteos en Estados Unidos Kansas City.- La secretaria de Relaciones Exteriores, Alicia B\u00e1rcena, lament\u00f3 la muerte de&nbsp;Lisa L\u00f3pez-Galv\u00e1n,&nbsp;v\u00edctima del tiroteo ocurrido el mi\u00e9rcoles 14 de febrero en&nbsp;Kansas City&nbsp;durante el desfile por la victoria de los&nbsp;Chiefs&nbsp;en el&nbsp;Super Bowl. La mujer, [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-02-15T15:57:11+00:00","article_modified_time":"2024-02-15T15:57:49+00:00","og_image":[{"width":600,"height":314,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg","type":"image\/jpeg"}],"author":"Reuters","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Reuters","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/"},"author":{"name":"Reuters","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f"},"headline":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos","datePublished":"2024-02-15T15:57:11+00:00","dateModified":"2024-02-15T15:57:49+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/"},"wordCount":657,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/","name":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg","datePublished":"2024-02-15T15:57:11+00:00","dateModified":"2024-02-15T15:57:49+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/img_1160.jpg","width":600,"height":314},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/15\/mexicana-murio-tras-tiroteo-en-kansas-city-hay-un-nino-mexicano-entre-heridos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Mexicana muri\u00f3 tras tiroteo en Kansas City; hay un ni\u00f1o mexicano entre los heridos"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f","name":"Reuters","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","caption":"Reuters"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/reuters\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73983"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73983\/revisions"}],"predecessor-version":[{"id":73985,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73983\/revisions\/73985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/73982"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}