{"id":73582,"date":"2024-02-11T19:47:03","date_gmt":"2024-02-12T02:47:03","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=73582"},"modified":"2024-02-11T19:47:03","modified_gmt":"2024-02-12T02:47:03","slug":"hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/","title":{"rendered":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas"},"content":{"rendered":"\n<p><strong><em>El aseguramiento fue resultado de un operativo conjunto entre soldados de la Secretar\u00eda de Marina-Armada de M\u00e9xico (Semar), agentes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) y autoridades estatales de Sonora<\/em><\/strong><\/p>\n\n\n\n<p>Autoridades mexicanas descubrieron en Sonora, cerca de la frontera con Estados Unidos, un enorme laboratorio para la producci\u00f3n de droga sint\u00e9tica donde decomisaron 80 toneladas de metanfetaminas, con un valor en el mercado superior a los 600 millones de d\u00f3lares.<\/p>\n\n\n\n<p>En el mega laboratorio clandestino, los oficiales encontraron 72 reactores, 102 condensadores, 32 centrifugadoras, as\u00ed como veh\u00edculos, motocicletas, remolques y diverso material relacionado con la producci\u00f3n de drogas sint\u00e9ticas.<\/p>\n\n\n\n<p>El descubrimiento, que ocurri\u00f3 esta semana en la comunidad de Rancho Viejo, municipio del Quiriego, al sur de Sonora, a unos 650 kil\u00f3metros de la frontera con Arizona, fue reportado este domingo por autoridades<\/p>\n\n\n\n<p>El aseguramiento fue resultado de un operativo conjunto entre soldados de la Secretar\u00eda de Marina-Armada de M\u00e9xico (Semar), agentes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) y autoridades estatales de Sonora.<\/p>\n\n\n\n<p>Entre los objetos asegurados tambi\u00e9n se encontraron 35 toneladas y 250 kilogramos de droga lista para su venta, es decir, metanfetamina en su forma m\u00e1s comercial que son las piedras de cristal.<\/p>\n\n\n\n<p>Adem\u00e1s de 5 toneladas y 750 kilogramos en precursores qu\u00edmicos, que servir\u00edan para producir unas 41 toneladas de metanfetaminas.<\/p>\n\n\n\n<p>Los agentes de la Marina incautaron grandes cantidades de qu\u00edmicos y sustancias de uso dual, con un valor estimado de m\u00e1s de 5 millones de d\u00f3lares, lo que, de acuerdo con el Gobierno de Sonora representa un golpe a las finanzas de la delincuencia organizada superior a 600 millones de d\u00f3lares.<\/p>\n\n\n\n<p>El gobernador del Estado, Alfonso Durazo, y el titular de la Secretar\u00eda de Marina, Jos\u00e9 Rafael Ojeda, dijeron que, para poner en perspectiva, la dimensi\u00f3n del narcolaboratorio m\u00e1s grande encontrado hasta ahora estaba en Sinaloa y ten\u00eda 13 reactores, mientras que, el localizado en Sonora consta de 72 reactores, 102 condensadores y 32 centrifugadoras.<\/p>\n\n\n\n<p>Las autoridades afirman que con estas acciones se contribuye a la reducci\u00f3n de las tendencias de consumo, especialmente en j\u00f3venes de entre los 19 y 27 a\u00f1os de edad, adem\u00e1s de que se evita que estas sustancias tengan como destino, los mercados de Australia, Canad\u00e1, China, Espa\u00f1a, Estados Unidos, Jap\u00f3n y diversos pa\u00edses europeos en donde los precios pueden llegar a triplicarse.<\/p>\n\n\n\n<p>En esta regi\u00f3n de la sierra, entre Sonora y Chihuahua operan c\u00e9lulas del C\u00e1rtel del Sinaloa, identificadas como la Chapiza, \u201cGente Nueva de los Salazar\u201d, facciones que obedecen a los hijos de Joaqu\u00edn Guzm\u00e1n Loera.<\/p>\n\n\n\n<p>Las autoridades no reportan la detenci\u00f3n de ning\u00fan sospechoso en el sitio, tampoco encontraron armamento, ni dinero en efectivo.<\/p>\n\n\n\n<p>El jueves, M\u00e9xico, Estados Unidos y Canad\u00e1 reafirmaron que trabajar\u00e1n conjuntamente para contrarrestar los flujos de drogas sint\u00e9ticas il\u00edcitas, en especial el tr\u00e1fico del fentanilo, y armas de fuego ilegales en Am\u00e9rica del Norte.<\/p>\n\n\n\n<p>En una declaraci\u00f3n conjunta apuntaron que tras la reuni\u00f3n que sostuvieron el mi\u00e9rcoles en Ciudad de M\u00e9xico representantes de seguridad nacional de los tres pa\u00edses, los Gobierno de las tres naciones se comprometieron a \u201cincrementar la colaboraci\u00f3n en el control de precursores qu\u00edmicos y equipos relacionados con la producci\u00f3n de drogas il\u00edcitas\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El aseguramiento fue resultado de un operativo conjunto entre soldados de la Secretar\u00eda de Marina-Armada de M\u00e9xico (Semar), agentes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) y autoridades estatales de Sonora Autoridades mexicanas descubrieron en Sonora, cerca de la frontera con Estados Unidos, un enorme laboratorio para la producci\u00f3n de droga sint\u00e9tica donde decomisaron [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":73583,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-73582","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El aseguramiento fue resultado de un operativo conjunto entre soldados de la Secretar\u00eda de Marina-Armada de M\u00e9xico (Semar), agentes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) y autoridades estatales de Sonora Autoridades mexicanas descubrieron en Sonora, cerca de la frontera con Estados Unidos, un enorme laboratorio para la producci\u00f3n de droga sint\u00e9tica donde decomisaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-12T02:47:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L\u00f3pez D\u00f3riga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00f3pez D\u00f3riga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/\"},\"author\":{\"name\":\"L\u00f3pez D\u00f3riga\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/67d852f0557c8509146a4b9ddebd543a\"},\"headline\":\"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas\",\"datePublished\":\"2024-02-12T02:47:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/\"},\"wordCount\":573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LABORATORIO_SON.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/\",\"name\":\"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LABORATORIO_SON.jpg\",\"datePublished\":\"2024-02-12T02:47:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LABORATORIO_SON.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/LABORATORIO_SON.jpg\",\"width\":850,\"height\":442},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/11\\\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/67d852f0557c8509146a4b9ddebd543a\",\"name\":\"L\u00f3pez D\u00f3riga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g\",\"caption\":\"L\u00f3pez D\u00f3riga\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/doriga\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/","og_locale":"es_MX","og_type":"article","og_title":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas","og_description":"El aseguramiento fue resultado de un operativo conjunto entre soldados de la Secretar\u00eda de Marina-Armada de M\u00e9xico (Semar), agentes de la Fiscal\u00eda General de la Rep\u00fablica (FGR) y autoridades estatales de Sonora Autoridades mexicanas descubrieron en Sonora, cerca de la frontera con Estados Unidos, un enorme laboratorio para la producci\u00f3n de droga sint\u00e9tica donde decomisaron [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-02-12T02:47:03+00:00","og_image":[{"width":850,"height":442,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg","type":"image\/jpeg"}],"author":"L\u00f3pez D\u00f3riga","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"L\u00f3pez D\u00f3riga","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/"},"author":{"name":"L\u00f3pez D\u00f3riga","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/67d852f0557c8509146a4b9ddebd543a"},"headline":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas","datePublished":"2024-02-12T02:47:03+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/"},"wordCount":573,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/","name":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg","datePublished":"2024-02-12T02:47:03+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/LABORATORIO_SON.jpg","width":850,"height":442},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/11\/hallan-en-sonora-un-enorme-laboratorio-con-80-toneladas-de-metanfetaminas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Hallan en Sonora un enorme laboratorio con 80 toneladas de metanfetaminas"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/67d852f0557c8509146a4b9ddebd543a","name":"L\u00f3pez D\u00f3riga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e525b06574ca18b33cded59dfe5778d6c823b9513154eff47da551b0551bdd1e?s=96&d=mm&r=g","caption":"L\u00f3pez D\u00f3riga"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/doriga\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73582","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73582"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73582\/revisions"}],"predecessor-version":[{"id":73584,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73582\/revisions\/73584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/73583"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73582"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73582"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73582"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}