{"id":73177,"date":"2024-02-09T06:30:22","date_gmt":"2024-02-09T13:30:22","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=73177"},"modified":"2024-02-09T07:11:01","modified_gmt":"2024-02-09T14:11:01","slug":"legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/","title":{"rendered":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>\u00a0\u201cLos discursos de odio se llevan vidas, marcan a las personas mediante denostaciones, conflictos, se\u00f1alamientos y discriminaci\u00f3n\u201d, lament\u00f3<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- El Congreso del Estado legisl\u00f3 para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n se\u00f1al\u00f3 la diputada Almendra Ernestina Negrete S\u00e1nchez, presidenta de la Comisi\u00f3n de Igualdad, G\u00e9nero, Diversidad Sexual e Inclusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al participar en el programa <strong>El Congreso Informa<\/strong> en <strong>Radio Upes<\/strong> precis\u00f3 que en la ense\u00f1anza los especialistas pedagogos deben abordar la inclusi\u00f3n y las diversidades que forman parte de Sinaloa y que no s\u00f3lo se enfoquen en erradicar los discursos de odio sino la discriminaci\u00f3n en todas sus formas e implantar el respeto a todas las diferencias que deben ser factor de uni\u00f3n y no de separaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3 que m\u00e1s importante que las penas establecidas es la obligaci\u00f3n de los servidores p\u00fablicos y el personal educativo de que en los planteles escolares se eduque, al exponer que con la educaci\u00f3n se busca crear nuevas realidades formando juventudes diversas desde el respeto y la tolerancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLegislamos no s\u00f3lo para prohibir sino para educar<\/strong>\u201d, apunt\u00f3 al destacar la obligaci\u00f3n de los tres niveles de gobierno para crear pol\u00edticas p\u00fablicas incluyentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que por tal motivo legislaron para avanzar hacia un Sinaloa de Paz donde el com\u00fan denominador de las y los sinaloenses sea manejarse y conducirse con respeto del uno al otro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Revel\u00f3 que del estudio de las denuncias interpuestas en los \u00d3rganos Internos de Control y las solicitudes de transparencia encontraron que lo que m\u00e1s da\u00f1a son los discursos de odio. \u201c<strong>Los discursos de odio se llevan vidas, marcan a las personas mediante denostaciones, conflictos, se\u00f1alamientos y discriminaci\u00f3n<\/strong>\u201d, lament\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que las diputadas y los diputados le entraron de lleno a legislar no s\u00f3lo para prohibir los discursos de odio, sino para ense\u00f1ar la educaci\u00f3n y el respeto en las aulas educativas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-1024x682.jpg\" alt=\"\" class=\"wp-image-73178\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-1024x682.jpg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-300x200.jpg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-768x512.jpg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-1536x1023.jpg 1536w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-696x464.jpg 696w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-1068x712.jpg 1068w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1-630x420.jpg 630w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/06c256c0-1de7-42c8-8a06-7aa43817365b-1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Expuso que ella misma ha sido v\u00edctima de discursos de odio y ha enfrentado ataques locales que se transforman en reconocimientos nacionales cada vez que aborda y avanza en un tema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>Lo mismo pas\u00f3 con el matrimonio igualitario, la tipificaci\u00f3n de los cr\u00edmenes de odio, la despenalizaci\u00f3n del aborto, interrupci\u00f3n legal del embarazo y la identidad de g\u00e9nero incluida las infancias trans<\/strong>\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asever\u00f3 que se trata de un entretejido legal pues una ley sustancia a la que sigue y est\u00e1n concatenadas. \u201c<em>Anteriormente ten\u00edamos la idea de que donde empieza mi derecho termina el tuyo, pero actualmente hemos entendido que los derechos humanos no tienen inicio ni final porque son universales, progresivos y concatenados uno con el otro<\/em>\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que ese es el punto de partida de la igualdad sustantiva, a trav\u00e9s de la equidad. \u201cEso solamente se logra cuando aceptas a la diversidad en una sociedad democr\u00e1tica donde las voces de todos deben de ser escuchadas\u201d, subray\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respecto a la prohibici\u00f3n de los discursos de odio destac\u00f3 la capacitaci\u00f3n de los personales docentes dentro del contexto educativo que tendr\u00e1 que hacerse una vez que se baje la ley secundaria a los municipios para realizar Jornadas de Capacitaci\u00f3n en los temas de inclusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que es una reforma general que tambi\u00e9n va contra los discursos xenof\u00f3bicos y racistas en cuesti\u00f3n del color de la piel y la edad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLo que buscamos es educar en el ambiente escolar, para que esa segunda casa tambi\u00e9n sea un lugar seguro y de respeto<\/strong>\u201d, enfatiz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Ir educ\u00e1ndonos como sociedad para poco a poco ir garantizando el acceso a las libertades que antes hab\u00edan sido negadas<\/em>\u201d, subray\u00f3. Afirm\u00f3 que todos los seres humanos somos iguales y no existe una diferencia, no debe haber un se\u00f1alamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Congreso del Estado ha impulsado una Agenda Legislativa que incluye todos los colores y partidos. As\u00ed ha avanzado la Agenda P\u00farpura, la agenda LGBTIQ+ y la protecci\u00f3n de todas las familias diversas que existen en Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostuvo que este esfuerzo se debe llevar a todos los niveles educativos porque tambi\u00e9n pueden ser v\u00edctimas el personal magisterial o de apoyo administrativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afirm\u00f3 que los maestros deben profesionalizarse en estos temas a trav\u00e9s de la capacitaci\u00f3n para poder ir dejando semillas que no sean de odio, sino semillas que sean fundamentalmente de valores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cA trav\u00e9s de la profesionalizaci\u00f3n y el entendimiento de c\u00f3mo podemos realmente avanzar como sociedad es como verdaderamente vamos a ver los cambios positivos<\/strong>\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que fue cambiado el concepto de discriminaci\u00f3n para incluirlo desde su literalidad y lo que sigue ahora es la implementaci\u00f3n de pol\u00edticas p\u00fablicas incluyentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Inform\u00f3 que como legisladora se ha reunido con doce presidencias municipales de los veinte municipios para impulsar un \u00e1rea de coordinaci\u00f3n en atenci\u00f3n a la diversidad sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asever\u00f3 que Sinaloa es plural y diverso por lo que es fundamental capacitar al personal docente y de apoyo que educa a las futuras generaciones en temas de diversidad sexual para erradicar la violencia, los se\u00f1alamientos y el bullying escolar, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u201cLos discursos de odio se llevan vidas, marcan a las personas mediante denostaciones, conflictos, se\u00f1alamientos y discriminaci\u00f3n\u201d, lament\u00f3 Culiac\u00e1n, Sin.- El Congreso del Estado legisl\u00f3 para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n se\u00f1al\u00f3 la diputada Almendra Ernestina Negrete S\u00e1nchez, presidenta de la Comisi\u00f3n de Igualdad, G\u00e9nero, Diversidad Sexual e Inclusi\u00f3n. Al [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73179,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-73177","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"\u00a0\u201cLos discursos de odio se llevan vidas, marcan a las personas mediante denostaciones, conflictos, se\u00f1alamientos y discriminaci\u00f3n\u201d, lament\u00f3 Culiac\u00e1n, Sin.- El Congreso del Estado legisl\u00f3 para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n se\u00f1al\u00f3 la diputada Almendra Ernestina Negrete S\u00e1nchez, presidenta de la Comisi\u00f3n de Igualdad, G\u00e9nero, Diversidad Sexual e Inclusi\u00f3n. Al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-09T13:30:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T14:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"681\" \/>\n\t<meta property=\"og:image:height\" content=\"437\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete\",\"datePublished\":\"2024-02-09T13:30:22+00:00\",\"dateModified\":\"2024-02-09T14:11:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/\"},\"wordCount\":894,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/dip.-almendra.jpeg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/\",\"name\":\"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/dip.-almendra.jpeg\",\"datePublished\":\"2024-02-09T13:30:22+00:00\",\"dateModified\":\"2024-02-09T14:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/dip.-almendra.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/dip.-almendra.jpeg\",\"width\":681,\"height\":437},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/02\\\/09\\\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/","og_locale":"es_MX","og_type":"article","og_title":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas","og_description":"\u00a0\u201cLos discursos de odio se llevan vidas, marcan a las personas mediante denostaciones, conflictos, se\u00f1alamientos y discriminaci\u00f3n\u201d, lament\u00f3 Culiac\u00e1n, Sin.- El Congreso del Estado legisl\u00f3 para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n se\u00f1al\u00f3 la diputada Almendra Ernestina Negrete S\u00e1nchez, presidenta de la Comisi\u00f3n de Igualdad, G\u00e9nero, Diversidad Sexual e Inclusi\u00f3n. Al [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-02-09T13:30:22+00:00","article_modified_time":"2024-02-09T14:11:01+00:00","og_image":[{"width":681,"height":437,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete","datePublished":"2024-02-09T13:30:22+00:00","dateModified":"2024-02-09T14:11:01+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/"},"wordCount":894,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/","name":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg","datePublished":"2024-02-09T13:30:22+00:00","dateModified":"2024-02-09T14:11:01+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/02\/dip.-almendra.jpeg","width":681,"height":437},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/02\/09\/legislamos-para-erradicar-los-discursos-de-odio-a-traves-de-la-educacion-almendra-negrete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Legislamos para erradicar los discursos de odio a trav\u00e9s de la educaci\u00f3n: Almendra Negrete"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73177"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73177\/revisions"}],"predecessor-version":[{"id":73182,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/73177\/revisions\/73182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/73179"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}