{"id":7264,"date":"2021-07-12T10:11:21","date_gmt":"2021-07-12T17:11:21","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=7264"},"modified":"2021-07-12T10:11:23","modified_gmt":"2021-07-12T17:11:23","slug":"dictan-auto-de-formal-prision-a-luis-cardenas-palomino","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/","title":{"rendered":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino"},"content":{"rendered":"\n<p><strong><em>El exmando de la Polic\u00eda Federal, fue detenido hace una semana y es acusado de tortura en el caso de Florence Cassez<\/em><\/strong><br><br>Ciudad de M\u00e9xico. Un juez federal dict\u00f3 auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino, exmando de la Polic\u00eda Federal (PF), por la tortura de cuatro personas, entre ellas dos familiares de Israel Vallarta Cisneros, expareja de Florence Cassez, quienes fueron acusados de ser integrantes de la banda de secuestradores de Los Zodiaco.<\/p>\n\n\n\n<p>\u201cA trav\u00e9s de #FEMDH, se obtuvo auto de formal prisi\u00f3n de un Juez de Distrito, en contra de Luis \u201cC\u201d por su probable responsabilidad en el delito de tortura. En breve m\u00e1s informaci\u00f3n\u201d, inform\u00f3 la Fiscal\u00eda General de la Rep\u00fablica (FGR).<\/p>\n\n\n\n<p>El exmando de la Polic\u00eda Federal y brazo derecho de Genaro Garc\u00eda Luna, exsecretario de Seguridad P\u00fablica detenido en Estados Unidos, apareci\u00f3 en el montaje de la supuesta captura de Israel Vallarta y Florence Cassez transmitido por Televisa, en el noticiero de Carlos Loret de Mola. <\/p>\n\n\n\n<p>Luis C\u00e1rdenas Palomino fue yerno de Marcos Castillejos Escobar, ex subprocurador general de la Rep\u00fablica y abogado de los hijos de Martha Sahag\u00fan.<\/p>\n\n\n\n<p>El hijo de Castillejos Escobar, Humberto Castillejos Cervantes, fue coordinador de asesores de Eduardo Medina Mora cuando fue procurador general de la Rep\u00fablica y durante el gobierno de Enrique Pe\u00f1a Nieto fue consejero jur\u00eddico de la Presidencia de la Rep\u00fablica.<\/p>\n\n\n\n<p>C\u00e1rdenas Palomino fue uno de los hombres m\u00e1s cercanos de Genaro Garc\u00eda Luna, secretario de Seguridad durante el gobierno de Felipe Calder\u00f3n (2006-2012) y quien hoy enfrenta preso cinco cargos vinculados al narcotr\u00e1fico en Estados Unidos.<\/p>\n\n\n\n<p>El expolic\u00eda estudi\u00f3 la licenciatura en Derecho en la Universidad del Valle, as\u00ed como fue director de Seguridad Regional de la Polic\u00eda Federal.<\/p>\n\n\n\n<p>Antes, trabaj\u00f3 varios a\u00f1os en el entonces Centro de Investigaci\u00f3n y Seguridad Nacional (Cisen) y alrededor de una d\u00e9cada en la Procuradur\u00eda General de la Rep\u00fablica (PGR), donde asumi\u00f3 importantes cargos como el de director de Investigaci\u00f3n Policial de la Agencia Federal de Investigaci\u00f3n (AFI).<\/p>\n\n\n\n<p>Con la llegada del Felipe Calder\u00f3n a la Presidencia de M\u00e9xico en 2006, C\u00e1rdenas Palomino asumi\u00f3 varios cargos dentro de la Secretar\u00eda de Seguridad P\u00fablica federal.<\/p>\n\n\n\n<p>Entre ellos, el cargo de Seguridad Regional o el de coordinador de Inteligencia para la Prevenci\u00f3n del Delito.<\/p>\n\n\n\n<p>El 5 de julio de 2021, la Fiscal\u00eda General de la Rep\u00fablica detuvo a Luis C\u00e1rdenas Palomino en un fraccionamiento de Naucalpan, Estado de M\u00e9xico.<\/p>\n\n\n\n<p>\u201cEste d\u00eda se cumpliment\u00f3 orden de aprehensi\u00f3n por el delito de tortura en contra de Luis \u2018C\u2019, en la Ciudad de M\u00e9xico, con el apoyo de la Secretar\u00eda de Marina, la Coordinaci\u00f3n Nacional Antisecuestro (Conase) y el Centro Nacional de Inteligencia\u201d, inform\u00f3 la entidad a cargo de Alejandro Gertz Manero.<\/p>\n\n\n\n<p>En julio de 2020, Luis C\u00e1rdenas Palomino y Ram\u00f3n Peque\u00f1o Garc\u00eda, dos ex altos oficiales de seguridad p\u00fablica de M\u00e9xico, fueron acusados en una corte federal en Nueva York de tres cargos de conspirar para el tr\u00e1fico de coca\u00edna, en colaboraci\u00f3n con el C\u00e1rtel de Sinaloa.<\/p>\n\n\n\n<p>D\u00edas despu\u00e9s, el gobierno mexicano congel\u00f3 las cuentas de Luis C\u00e1rdenas Palomino y Ram\u00f3n Peque\u00f1o Garc\u00eda, seg\u00fan inform\u00f3 la Unidad de Inteligencia Financiera (UIF).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exmando de la Polic\u00eda Federal, fue detenido hace una semana y es acusado de tortura en el caso de Florence Cassez Ciudad de M\u00e9xico. Un juez federal dict\u00f3 auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino, exmando de la Polic\u00eda Federal (PF), por la tortura de cuatro personas, entre ellas dos familiares de Israel [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-7264","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El exmando de la Polic\u00eda Federal, fue detenido hace una semana y es acusado de tortura en el caso de Florence Cassez Ciudad de M\u00e9xico. Un juez federal dict\u00f3 auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino, exmando de la Polic\u00eda Federal (PF), por la tortura de cuatro personas, entre ellas dos familiares de Israel [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-12T17:11:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-12T17:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"432\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Forbes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Forbes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/\"},\"author\":{\"name\":\"Forbes\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/5623d53fe2e579d825b1679734abcc44\"},\"headline\":\"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino\",\"datePublished\":\"2021-07-12T17:11:21+00:00\",\"dateModified\":\"2021-07-12T17:11:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/\"},\"wordCount\":592,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/\",\"name\":\"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg\",\"datePublished\":\"2021-07-12T17:11:21+00:00\",\"dateModified\":\"2021-07-12T17:11:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg\",\"width\":768,\"height\":432,\"caption\":\"MEX6288. CIUDAD DE M\u00c9XICO (M\u00c9XICO), 05\\\/07\\\/2021.- Fotograf\u00eda de archivo fechada el 6 de julio de 2012 que muestra al jefe de divisi\u00f3n de Seguridad Regional de la Polic\u00eda Federal, Luis C\u00e1rdenas Palomino, durante una rueda de prensa en Ciudad de M\u00e9xico (M\u00e9xico). Las autoridades mexicanas detuvieron este lunes acusado de tortura en el caso Florence Cassez a Luis C\u00e1rdenas Palomino, un ex altomando estrechamente vinculado a Genaro Garc\u00eda Luna, exministro de Seguridad, hoy preso en Estados Unidos acusado de v\u00ednculos con el narcotr\u00e1fico. EFE\\\/ Mario Guzm\u00e1n\\\/Archivo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/07\\\/12\\\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/5623d53fe2e579d825b1679734abcc44\",\"name\":\"Forbes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g\",\"caption\":\"Forbes\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/forbes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/","og_locale":"es_MX","og_type":"article","og_title":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas","og_description":"El exmando de la Polic\u00eda Federal, fue detenido hace una semana y es acusado de tortura en el caso de Florence Cassez Ciudad de M\u00e9xico. Un juez federal dict\u00f3 auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino, exmando de la Polic\u00eda Federal (PF), por la tortura de cuatro personas, entre ellas dos familiares de Israel [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-07-12T17:11:21+00:00","article_modified_time":"2021-07-12T17:11:23+00:00","og_image":[{"width":768,"height":432,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg","type":"image\/jpeg"}],"author":"Forbes","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Forbes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/"},"author":{"name":"Forbes","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/5623d53fe2e579d825b1679734abcc44"},"headline":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino","datePublished":"2021-07-12T17:11:21+00:00","dateModified":"2021-07-12T17:11:23+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/"},"wordCount":592,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/","name":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg","datePublished":"2021-07-12T17:11:21+00:00","dateModified":"2021-07-12T17:11:23+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/07\/bb228e80c98b05d776cf3d7a58326d5e8a890287-768x432-1.jpg","width":768,"height":432,"caption":"MEX6288. CIUDAD DE M\u00c9XICO (M\u00c9XICO), 05\/07\/2021.- Fotograf\u00eda de archivo fechada el 6 de julio de 2012 que muestra al jefe de divisi\u00f3n de Seguridad Regional de la Polic\u00eda Federal, Luis C\u00e1rdenas Palomino, durante una rueda de prensa en Ciudad de M\u00e9xico (M\u00e9xico). Las autoridades mexicanas detuvieron este lunes acusado de tortura en el caso Florence Cassez a Luis C\u00e1rdenas Palomino, un ex altomando estrechamente vinculado a Genaro Garc\u00eda Luna, exministro de Seguridad, hoy preso en Estados Unidos acusado de v\u00ednculos con el narcotr\u00e1fico. EFE\/ Mario Guzm\u00e1n\/Archivo"},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/07\/12\/dictan-auto-de-formal-prision-a-luis-cardenas-palomino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Dictan auto de formal prisi\u00f3n a Luis C\u00e1rdenas Palomino"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/5623d53fe2e579d825b1679734abcc44","name":"Forbes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/87ce3dd4e41e60c22a79c758614f01a6bc2469255fc936ec7b15efb9bb5cb66f?s=96&d=mm&r=g","caption":"Forbes"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/forbes\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7264"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7264\/revisions"}],"predecessor-version":[{"id":7266,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/7264\/revisions\/7266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/7265"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}