{"id":71507,"date":"2024-01-22T15:19:25","date_gmt":"2024-01-22T22:19:25","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=71507"},"modified":"2024-01-22T15:19:58","modified_gmt":"2024-01-22T22:19:58","slug":"asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/","title":{"rendered":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Fiscal\u00eda General de Justicia de Sonora inform\u00f3 que&nbsp;<strong>abri\u00f3 una investigaci\u00f3n<\/strong>&nbsp;por el homicidio del m\u00e9dico e influencer&nbsp;<strong>Carlos L\u00f3pez Carrillo.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las autoridades, el m\u00e9dico fue privado de la vida y su cuerpo fue hallado este domingo 21 de enero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las autoridades precisaron que el&nbsp;<strong>hallazgo de L\u00f3pez Carrillo<\/strong>&nbsp;ocurri\u00f3 en un inmueble en Residencial Clima, al norte de la ciudad de Hermosillo.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, la fiscal\u00eda indic\u00f3 que, seg\u00fan sus primeras investigaciones, se indaga una \u201chip\u00f3tesis de trabajo relacionada con un&nbsp;<strong>posible entorno personal<\/strong>\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlos L\u00f3pez<\/strong>&nbsp;colaboraba en programas de televisi\u00f3n local y a trav\u00e9s de sus redes sociales compart\u00eda informaci\u00f3n sobre procesos est\u00e9ticos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\u00a0<strong>Cruz Roja Mexicana en Hermosillo<\/strong>\u00a0lament\u00f3 la muerte del doctor, a quien le reconoci\u00f3 su labor en eventos de dicha instituci\u00f3n.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan su sitio web, el&nbsp;<strong>doctor L\u00f3pez Carrillo<\/strong>&nbsp;se gradu\u00f3 de la Universidad Aut\u00f3noma de Guadalajara y contaba con nueve a\u00f1os de experiencia en procedimientos est\u00e9ticos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Carlos L\u00f3pez<\/strong>\u00a0tambi\u00e9n se presentaba como presidente y fundador de la Asociaci\u00f3n de M\u00e9dicos Est\u00e9ticos de Sonora<a href=\"https:\/\/twitter.com\/latinus_us\" target=\"_blank\" rel=\"noreferrer noopener\">.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@drlopezcarrillo\/video\/7206523823447952646\" data-video-id=\"7206523823447952646\" data-embed-from=\"oembed\" style=\"max-width: 605px;min-width: 325px;\" > <section> <a target=\"_blank\" title=\"@drlopezcarrillo\" href=\"https:\/\/www.tiktok.com\/@drlopezcarrillo?refer=embed\">@drlopezcarrillo<\/a> <p>Mitos y realidades del <a title=\"botox\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/botox?refer=embed\">#botox<\/a> escuchanos en Spotify <\/p> <a target=\"_blank\" title=\"\u266c sonido original - Carlos L\u00f3pez Carrillo\" href=\"https:\/\/www.tiktok.com\/music\/sonido-original-7206523846237162246?refer=embed\">\u266c sonido original &#8211; Carlos L\u00f3pez Carrillo<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el informe diario de la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) durante este fin de semana se registraron cuatro homicidios en Sonora.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este s\u00e1bado tambi\u00e9n se registr\u00f3 un enfrentamiento en una carretera en Hermosillo por la detenci\u00f3n del hijo de un l\u00edder criminal, conocido como \u201cChubeto\u201d en el que fueron abatidos 12 agresores, seg\u00fan la fiscal\u00eda.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras que la semana pasada se report\u00f3 otro&nbsp;<strong>enfrentamiento<\/strong>, pero este en&nbsp;el poblado de&nbsp;<strong>Magdalena de Kino<\/strong>, el cual dej\u00f3 como saldo a dos agresores fallecidos, uno de ellos fue identificado como un \u201cobjetivo criminal prioritario\u201d<a href=\"https:\/\/twitter.com\/Amicsonora\">.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Fiscal\u00eda General de Justicia de Sonora inform\u00f3 que&nbsp;abri\u00f3 una investigaci\u00f3n&nbsp;por el homicidio del m\u00e9dico e influencer&nbsp;Carlos L\u00f3pez Carrillo.&nbsp; De acuerdo con las autoridades, el m\u00e9dico fue privado de la vida y su cuerpo fue hallado este domingo 21 de enero. Las autoridades precisaron que el&nbsp;hallazgo de L\u00f3pez Carrillo&nbsp;ocurri\u00f3 en un inmueble en Residencial Clima, [&hellip;]<\/p>\n","protected":false},"author":85,"featured_media":71508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-71507","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La Fiscal\u00eda General de Justicia de Sonora inform\u00f3 que&nbsp;abri\u00f3 una investigaci\u00f3n&nbsp;por el homicidio del m\u00e9dico e influencer&nbsp;Carlos L\u00f3pez Carrillo.&nbsp; De acuerdo con las autoridades, el m\u00e9dico fue privado de la vida y su cuerpo fue hallado este domingo 21 de enero. Las autoridades precisaron que el&nbsp;hallazgo de L\u00f3pez Carrillo&nbsp;ocurri\u00f3 en un inmueble en Residencial Clima, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T22:19:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T22:19:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Latinus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Latinus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/\"},\"author\":{\"name\":\"Latinus\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\"},\"headline\":\"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo\",\"datePublished\":\"2024-01-22T22:19:25+00:00\",\"dateModified\":\"2024-01-22T22:19:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/\"},\"wordCount\":365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abren-investigacion-medico-estetico-1024x529-1.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/\",\"name\":\"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abren-investigacion-medico-estetico-1024x529-1.jpg\",\"datePublished\":\"2024-01-22T22:19:25+00:00\",\"dateModified\":\"2024-01-22T22:19:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abren-investigacion-medico-estetico-1024x529-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/abren-investigacion-medico-estetico-1024x529-1.jpg\",\"width\":1024,\"height\":529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/22\\\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\",\"name\":\"Latinus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"caption\":\"Latinus\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/latinus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/","og_locale":"es_MX","og_type":"article","og_title":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas","og_description":"La Fiscal\u00eda General de Justicia de Sonora inform\u00f3 que&nbsp;abri\u00f3 una investigaci\u00f3n&nbsp;por el homicidio del m\u00e9dico e influencer&nbsp;Carlos L\u00f3pez Carrillo.&nbsp; De acuerdo con las autoridades, el m\u00e9dico fue privado de la vida y su cuerpo fue hallado este domingo 21 de enero. Las autoridades precisaron que el&nbsp;hallazgo de L\u00f3pez Carrillo&nbsp;ocurri\u00f3 en un inmueble en Residencial Clima, [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-01-22T22:19:25+00:00","article_modified_time":"2024-01-22T22:19:58+00:00","og_image":[{"width":1024,"height":529,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg","type":"image\/jpeg"}],"author":"Latinus","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Latinus","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/"},"author":{"name":"Latinus","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde"},"headline":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo","datePublished":"2024-01-22T22:19:25+00:00","dateModified":"2024-01-22T22:19:58+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/"},"wordCount":365,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/","name":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg","datePublished":"2024-01-22T22:19:25+00:00","dateModified":"2024-01-22T22:19:58+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/abren-investigacion-medico-estetico-1024x529-1.jpg","width":1024,"height":529},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/22\/asesinan-en-hermosillo-al-cirujano-plastico-carlos-lopez-carrillo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Asesinan en Hermosillo al famoso cirujano pl\u00e1stico Carlos L\u00f3pez Carrillo"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde","name":"Latinus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","caption":"Latinus"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/latinus\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/71507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=71507"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/71507\/revisions"}],"predecessor-version":[{"id":71510,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/71507\/revisions\/71510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/71508"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=71507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=71507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=71507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}