{"id":70455,"date":"2024-01-12T05:16:31","date_gmt":"2024-01-12T12:16:31","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=70455"},"modified":"2024-01-11T21:17:14","modified_gmt":"2024-01-12T04:17:14","slug":"obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/","title":{"rendered":"Obispos consideran &#8220;inapropiadas&#8221; bendiciones a parejas homosexuales en \u00c1frica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La iniciativa vaticana a favor de la comunidad homosexual se top\u00f3 con una oposici\u00f3n especialmente fuerte en Malaui, Nigeria, Zambia y Rep\u00fablica Democr\u00e1tica del Congo. En cambio, obispos ya bendec\u00edan a parejas del mismo sexo en pa\u00edses como B\u00e9lgica y Alemania.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En \u00c1frica los obispos cat\u00f3licos afirmaron que la reciente aprobaci\u00f3n por parte del Vaticano de las bendiciones a parejas del mismo sexo eran &#8220;inapropiadas&#8221; en el contexto cultural de ese continente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La homosexualidad sigue siendo ilegal en muchos pa\u00edses africanos, que la reprimen en muchos casos alentados por los sectores m\u00e1s conservadores del cristianismo y el islam.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un documento llamado Fiducia suplicans (La confianza suplicante), la Santa Sede autoriz\u00f3 el mes pasado, con la aprobaci\u00f3n del papa Francisco, la bendici\u00f3n de parejas &#8220;irregulares&#8221; a ojos de la Iglesia, incluidas las de divorciados y las de personas del mismo sexo, siempre que esa bendici\u00f3n se llevara a cabo fuera de los rituales lit\u00fargicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esa iniciativa fue rechazada por obispos, principalmente de pa\u00edses africanos, y llev\u00f3 al Vaticano a aclarar que no supon\u00eda ning\u00fan cambio de doctrina y a destacar la necesidad de mantener la &#8220;prudencia&#8221; en algunos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La doctrina de la Iglesia sobre el matrimonio cristiano y la sexualidad permanece sin cambios&#8221;, destac\u00f3 igualmente este jueves el Simposio de las Conferencias Episcopales de \u00c1frica y Madagascar (SECAM) en un comunicado emitido en Accra, la capital de Ghana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Por esta raz\u00f3n, nosotros, los obispos africanos, consideramos inapropiado bendecir uniones homosexuales o parejas del mismo sexo en \u00c1frica porque, en nuestro contexto, esto causar\u00eda confusi\u00f3n y estar\u00eda en contradicci\u00f3n directa con el ethos cultural de las comunidades africanas&#8221;, agrega el documento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa vaticana a favor de la comunidad homosexual se top\u00f3 con una oposici\u00f3n especialmente fuerte en Malaui, Nigeria, Zambia y Rep\u00fablica Democr\u00e1tica del Congo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Costa de Marfil, los obispos y arzobispos alertaron que la bendici\u00f3n del parejas del mismo sexo podr\u00eda generar &#8220;confusi\u00f3n&#8221; y &#8220;esc\u00e1ndalo&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en Nigeria, la Conferencia episcopal se\u00f1al\u00f3 en diciembre que esa bendici\u00f3n &#8220;ir\u00eda en contra de la ley de Dios, de las ense\u00f1anzas de la Iglesia, de las leyes [del pa\u00eds] y de las sensibilidades culturales&#8221; de la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cambio, en otras zonas, los curas ya hab\u00edan dado pasos en la l\u00ednea del &#8220;Fiducia suplicans&#8221;, antes incluso de que se publicase. Algunos sacerdotes ya bendec\u00edan a parejas del mismo sexo en pa\u00edses como B\u00e9lgica y Alemania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su elecci\u00f3n en 2013, el Papa Francisco, de 87 a\u00f1os, ha tratado de abrir las puertas de la Iglesia a todos los fieles, incluida la comunidad LGTBQ, sin vencer las resistencias de los cat\u00f3licos m\u00e1s conservadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa vaticana a favor de la comunidad homosexual se top\u00f3 con una oposici\u00f3n especialmente fuerte en Malaui, Nigeria, Zambia y Rep\u00fablica Democr\u00e1tica del Congo. En cambio, obispos ya bendec\u00edan a parejas del mismo sexo en pa\u00edses como B\u00e9lgica y Alemania. En \u00c1frica los obispos cat\u00f3licos afirmaron que la reciente aprobaci\u00f3n por parte del Vaticano [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":70456,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-70455","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obispos consideran &quot;inapropiadas&quot; bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obispos consideran &quot;inapropiadas&quot; bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La iniciativa vaticana a favor de la comunidad homosexual se top\u00f3 con una oposici\u00f3n especialmente fuerte en Malaui, Nigeria, Zambia y Rep\u00fablica Democr\u00e1tica del Congo. En cambio, obispos ya bendec\u00edan a parejas del mismo sexo en pa\u00edses como B\u00e9lgica y Alemania. En \u00c1frica los obispos cat\u00f3licos afirmaron que la reciente aprobaci\u00f3n por parte del Vaticano [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-12T12:16:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exc\u00e9lsior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exc\u00e9lsior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/\"},\"author\":{\"name\":\"Exc\u00e9lsior\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\"},\"headline\":\"Obispos consideran &#8220;inapropiadas&#8221; bendiciones a parejas homosexuales en \u00c1frica\",\"datePublished\":\"2024-01-12T12:16:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/\"},\"wordCount\":484,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/obispos-africanosjpg.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/\",\"name\":\"Obispos consideran \\\"inapropiadas\\\" bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/obispos-africanosjpg.jpg\",\"datePublished\":\"2024-01-12T12:16:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/obispos-africanosjpg.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/obispos-africanosjpg.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2024\\\/01\\\/12\\\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obispos consideran &#8220;inapropiadas&#8221; bendiciones a parejas homosexuales en \u00c1frica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\",\"name\":\"Exc\u00e9lsior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"caption\":\"Exc\u00e9lsior\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/excelsior\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obispos consideran \"inapropiadas\" bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/","og_locale":"es_MX","og_type":"article","og_title":"Obispos consideran \"inapropiadas\" bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas","og_description":"La iniciativa vaticana a favor de la comunidad homosexual se top\u00f3 con una oposici\u00f3n especialmente fuerte en Malaui, Nigeria, Zambia y Rep\u00fablica Democr\u00e1tica del Congo. En cambio, obispos ya bendec\u00edan a parejas del mismo sexo en pa\u00edses como B\u00e9lgica y Alemania. En \u00c1frica los obispos cat\u00f3licos afirmaron que la reciente aprobaci\u00f3n por parte del Vaticano [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2024-01-12T12:16:31+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg","type":"image\/jpeg"}],"author":"Exc\u00e9lsior","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Exc\u00e9lsior","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/"},"author":{"name":"Exc\u00e9lsior","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780"},"headline":"Obispos consideran &#8220;inapropiadas&#8221; bendiciones a parejas homosexuales en \u00c1frica","datePublished":"2024-01-12T12:16:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/"},"wordCount":484,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/","name":"Obispos consideran \"inapropiadas\" bendiciones a parejas homosexuales en \u00c1frica - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg","datePublished":"2024-01-12T12:16:31+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/01\/obispos-africanosjpg.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2024\/01\/12\/obispos-consideran-inapropiadas-bendiciones-a-parejas-homosexuales-en-africa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Obispos consideran &#8220;inapropiadas&#8221; bendiciones a parejas homosexuales en \u00c1frica"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780","name":"Exc\u00e9lsior","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","caption":"Exc\u00e9lsior"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/excelsior\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/70455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=70455"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/70455\/revisions"}],"predecessor-version":[{"id":70457,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/70455\/revisions\/70457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/70456"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=70455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=70455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=70455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}