{"id":69486,"date":"2023-12-29T05:54:11","date_gmt":"2023-12-29T12:54:11","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=69486"},"modified":"2023-12-28T19:55:07","modified_gmt":"2023-12-29T02:55:07","slug":"israel-aprueba-la-adopcion-homoparental-sin-restricciones","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/","title":{"rendered":"Israel aprueba la adopci\u00f3n homoparental sin restricciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Aguda Israel, la entidad representativa de la comunidad LGBT, celebr\u00f3 el hecho tras tres a\u00f1os de lucha para que esto fuera posible y lo catalog\u00f3 como una &#8220;gota de esperanza en estos d\u00edas dif\u00edciles&#8221;<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- Este jueves, el Tribunal Supremo de Israel dictamin\u00f3 que las parejas del mismo sexo pueden adoptar ni\u00f1os en igualdad de condiciones a las parejas heterosexuales, una decisi\u00f3n que se ve como &#8220;una victoria hist\u00f3rica&#8221; para el colectivo LGTB del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de su cuenta de &#8216;X&#8217;, Aguda Israel, la entidad representativa de la comunidad LGBT en Israel, celebr\u00f3 el hecho tras tres a\u00f1os de lucha para que esto fuera posible y lo catalog\u00f3 como una &#8220;gota de esperanza en estos d\u00edas dif\u00edciles&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Tras a\u00f1os de lucha, el Tribunal Superior de Justicia cancela la discriminaci\u00f3n contra las parejas LGTB en el proceso de adopci\u00f3n&#8221;, celebr\u00f3 la entidad, que present\u00f3 un recurso ante la Justicia junto a la ONG Centro de Reforma y Casa Abierta para el Orgullo y la Tolerancia de Jerusal\u00e9n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Durante a\u00f1os hemos estado luchando y peleando para ser vistos como iguales a la hora de adoptar ni\u00f1os y formar una familia en Israel, mientras que los gobiernos israel\u00edes durante generaciones nos han discriminado e incitado s\u00f3lo por lo que somos, el Tribunal Supremo demuestra una vez m\u00e1s su importancia en la protecci\u00f3n de nuestros derechos&#8221;.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"iw\" dir=\"rtl\">\u05d0\u05d7\u05e8\u05d9 \u05e9\u05e0\u05d9\u05dd \u05e9\u05dc \u05de\u05d0\u05d1\u05e7, \u05d1\u05d2\u05f4\u05e5 \u05de\u05d1\u05d8\u05dc \u05d0\u05ea \u05d4\u05d0\u05e4\u05dc\u05d9\u05d4 \u05d1\u05d0\u05d9\u05de\u05d5\u05e5 \u05e0\u05d2\u05d3 \u05d6\u05d5\u05d2\u05d5\u05ea \u05dc\u05d4\u05d8\u05f4\u05d1 \u05d1\u05e2\u05ea\u05d9\u05e8\u05d4 \u05e9\u05d4\u05d2\u05e9\u05e0\u05d5 \u05d9\u05d7\u05d3 \u05e2\u05dd \u05d4\u05de\u05e8\u05db\u05d6 \u05d4\u05e8\u05e4\u05d5\u05e8\u05de\u05d9 \u05d5\u05d4\u05d1\u05d9\u05ea \u05d4\u05e4\u05ea\u05d5\u05d7 \u05dc\u05d2\u05d0\u05d5\u05d5\u05d4 \u05d5\u05dc\u05e1\u05d5\u05d1\u05dc\u05e0\u05d5\u05ea \u05d1\u05d9\u05e8\u05d5\u05e9\u05dc\u05d9\u05dd! \ud83c\udff3\ufe0f\u200d\ud83c\udf08\ud83c\udff3\ufe0f\u200d\u26a7\ufe0f<br><br>\u05d6\u05d4 \u05e0\u05d9\u05e6\u05d7\u05d5\u05df \u05d4\u05d9\u05e1\u05d8\u05d5\u05e8\u05d9 \u05d5\u05d4\u05d9\u05e9\u05d2 \u05e4\u05d5\u05e8\u05e5 \u05d3\u05e8\u05da \u05e9\u05e0\u05d5\u05ea\u05df \u05d8\u05d9\u05e4\u05d4 \u05e9\u05dc \u05d0\u05d5\u05e8 \u05d5\u05ea\u05e7\u05d5\u05d5\u05d4 \u05d1\u05d9\u05de\u05d9\u05dd \u05e7\u05e9\u05d9\u05dd \u05d0\u05dc\u05d5. \u05db\u05d1\u05e8 \u05e9\u05e0\u05d9\u05dd \u05e9\u05d0\u05e0\u05d7\u05e0\u05d5 \u05e0\u05d0\u05d1\u05e7\u05d9\u05dd \u05d5\u05e0\u05d0\u05d1\u05e7\u05d5\u05ea \u05e9\u05d9\u05e8\u05d0\u05d5 \u05d1\u05e0\u05d5 \u05e9\u05d5\u05d5\u05d9\u05dd \u05d5\u05e9\u05d5\u05d5\u05ea \u05d1\u05d0\u05d9\u05de\u05d5\u05e5\u2026<\/p>&mdash; \u05d4\u05d0\u05d2\u05d5\u05d3\u05d4 \u05dc\u05de\u05e2\u05df \u05d4\u05dc\u05d4\u05d8&quot;\u05d1 \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc | The Aguda (@AgudaIsraelLGBT) <a href=\"https:\/\/twitter.com\/AgudaIsraelLGBT\/status\/1740376072263197043?ref_src=twsrc%5Etfw\">December 28, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;S\u00f3lo un hombre y su esposa juntos&#8221;<br>Hasta ahora, la legislaci\u00f3n establec\u00eda que s\u00f3lo &#8220;un hombre y su esposa juntos&#8221; pod\u00edan adoptar, y las parejas del mismo sexo pod\u00edan hacerlo solamente bajo dos criterios excepcionales: si uno de los c\u00f3nyuges era padre biol\u00f3gico del ni\u00f1o, o si los padres hab\u00edan muerto y el menor a adoptar era un pariente, seg\u00fan el diario local Haaretz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante ello, en su sentencia de hoy, el Supremo dictamin\u00f3 que las parejas heterosexuales no tendr\u00e1n prioridad en el proceso de adopci\u00f3n, en una decisi\u00f3n tomada de forma un\u00e1nime que marca una nueva interpretaci\u00f3n de la ley sobre el \u00e1mbito vigente desde 1981.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Aguda Israel, la decisi\u00f3n de hoy es tambi\u00e9n una &#8220;respuesta a la homofobia y el odio&#8221; que releg\u00f3 a los homosexuales a &#8220;ciudadanos de segunda clase&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Este d\u00eda es la respuesta a la homofobia, el odio, la oscuridad y los ministros de bienestar que durante a\u00f1os negaron nuestra filiaci\u00f3n, dej\u00e1ndonos como ciudadanos de segunda clase&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;La guerra s\u00f3lo puso de relieve lo desconectada que est\u00e1 la desigualdad de la vida misma. Ha llegado la hora de la igualdad de derechos en la legislaci\u00f3n primaria de la Knesset: en la paternidad, en la seguridad, en el matrimonio, sin incitaci\u00f3n ni discriminaci\u00f3n, y seguiremos marchando con orgullo hasta que lo consigamos&#8221;.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"iw\" dir=\"rtl\">\u05e9\u05de\u05d5\u05d0\u05dc \u05d4\u05d2\u05d9\u05e2 \u05dc\u05d1\u05e7\u05e8 \u05d1\u05d1\u05e1\u05d9\u05e1 \u05d0\u05ea \u05d1\u05df \u05d6\u05d5\u05d2\u05d5 \u05d3\u05e0\u05d9\u05e1 \u05e9\u05de\u05e9\u05e8\u05ea \u05db\u05de\u05f4\u05e4 \u05d1\u05de\u05d9\u05dc\u05d5\u05d0\u05d9\u05dd, \u05db\u05e8\u05e2 \u05d1\u05e8\u05da \u05d5\u05d4\u05e6\u05d9\u05e2 \u05dc\u05d5 \u05e0\u05d9\u05e9\u05d5\u05d0\u05d9\u05dd. <br>\u05f4\u05e0\u05d9\u05e6\u05d7\u05e0\u05d5 \u05d0\u05ea \u05d4\u05e8\u05d5\u05d7 \u05e9\u05d7\u05de\u05d0\u05e1 \u05e0\u05d9\u05e1\u05d4 \u05dc\u05e9\u05d1\u05d5\u05e8, \u05e0\u05d9\u05e6\u05d7\u05e0\u05d5 \u05d0\u05ea \u05d4\u05d0\u05d5\u05e4\u05dc \u05d5\u05d4\u05d7\u05e9\u05db\u05d4, \u05d5\u05d0\u05d7\u05e8\u05d9 \u05d4\u05de\u05dc\u05d7\u05de\u05d4 \u05d0\u05e0\u05d7\u05e0\u05e0\u05d5 \u05e0\u05dc\u05d7\u05dd \u05e2\u05d3 \u05e9\u05db\u05dc \u05d4\u05d6\u05db\u05d5\u05d9\u05d5\u05ea \u05e9\u05dc\u05e0\u05d5 \u05d9\u05d4\u05d9\u05d5 \u05de\u05dc\u05d0\u05d5\u05ea \u05d1\u05de\u05d3\u05d9\u05e0\u05d4 \u05e9\u05dc\u05e0\u05d5 &#8211; \u05d5\u05e0\u05e0\u05e6\u05d7.\u05f4 <br>\u05de\u05d6\u05dc \u05d8\u05d5\u05d1 \u05e9\u05de\u05d5\u05d0\u05dc \u05d5\u05d3\u05e0\u05d9\u05e1 \u05d4\u05d9\u05e7\u05e8\u05d9\u05dd-\u05d4\u05d0\u05d4\u05d1\u05d4 \u05e9\u05dc\u05db\u05dd \u05de\u05e0\u05e6\u05d7\u05ea. \u05d0\u05d7\u05e8\u05d9 \u05d4\u05de\u05dc\u05d7\u05de\u05d4\u2026 <a href=\"https:\/\/t.co\/I47vAHp4b0\">pic.twitter.com\/I47vAHp4b0<\/a><\/p>&mdash; \u05d4\u05d0\u05d2\u05d5\u05d3\u05d4 \u05dc\u05de\u05e2\u05df \u05d4\u05dc\u05d4\u05d8&quot;\u05d1 \u05d1\u05d9\u05e9\u05e8\u05d0\u05dc | The Aguda (@AgudaIsraelLGBT) <a href=\"https:\/\/twitter.com\/AgudaIsraelLGBT\/status\/1733803416831328718?ref_src=twsrc%5Etfw\">December 10, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Lleg\u00f3 el momento de la igualdad de derechos en la paternidad, la seguridad, el matrimonio, sin incitaci\u00f3n ni discriminaci\u00f3n, y seguiremos marchando con orgullo hasta llegar ah\u00ed&#8221;, agreg\u00f3 Aguda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Israel es considerado como el pa\u00eds m\u00e1s abierto en la regi\u00f3n hacia la comunidad LGBT, aunque a su vez tiene sectores religiosos jud\u00edos fuertemente conservadores que se oponen a este colectivo, a\u00fan sometido a muchas limitaciones en cuesti\u00f3n de derechos civiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su vez, la coalici\u00f3n de gobierno de Benjam\u00edn Netanyahu, formada en parte por ministros de ultraderecha y abiertamente hom\u00f3fobos, es considerada de las m\u00e1s contrarias al colectivo LGTB en la historia reciente de Israel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aguda Israel, la entidad representativa de la comunidad LGBT, celebr\u00f3 el hecho tras tres a\u00f1os de lucha para que esto fuera posible y lo catalog\u00f3 como una &#8220;gota de esperanza en estos d\u00edas dif\u00edciles&#8221; Ciudad de M\u00e9xico.- Este jueves, el Tribunal Supremo de Israel dictamin\u00f3 que las parejas del mismo sexo pueden adoptar ni\u00f1os en [&hellip;]<\/p>\n","protected":false},"author":15,"featured_media":69487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-69486","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Aguda Israel, la entidad representativa de la comunidad LGBT, celebr\u00f3 el hecho tras tres a\u00f1os de lucha para que esto fuera posible y lo catalog\u00f3 como una &#8220;gota de esperanza en estos d\u00edas dif\u00edciles&#8221; Ciudad de M\u00e9xico.- Este jueves, el Tribunal Supremo de Israel dictamin\u00f3 que las parejas del mismo sexo pueden adoptar ni\u00f1os en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-29T12:54:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Silla Rota\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Silla Rota\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/\"},\"author\":{\"name\":\"La Silla Rota\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/62ca416a4f36e3bbaa81ca03c42a24de\"},\"headline\":\"Israel aprueba la adopci\u00f3n homoparental sin restricciones\",\"datePublished\":\"2023-12-29T12:54:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/ANILLOS_LGBT.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/\",\"name\":\"Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/ANILLOS_LGBT.jpg\",\"datePublished\":\"2023-12-29T12:54:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/ANILLOS_LGBT.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/ANILLOS_LGBT.jpg\",\"width\":960,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/29\\\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Israel aprueba la adopci\u00f3n homoparental sin restricciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/62ca416a4f36e3bbaa81ca03c42a24de\",\"name\":\"La Silla Rota\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g\",\"caption\":\"La Silla Rota\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/lasillarota\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/","og_locale":"es_MX","og_type":"article","og_title":"Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas","og_description":"Aguda Israel, la entidad representativa de la comunidad LGBT, celebr\u00f3 el hecho tras tres a\u00f1os de lucha para que esto fuera posible y lo catalog\u00f3 como una &#8220;gota de esperanza en estos d\u00edas dif\u00edciles&#8221; Ciudad de M\u00e9xico.- Este jueves, el Tribunal Supremo de Israel dictamin\u00f3 que las parejas del mismo sexo pueden adoptar ni\u00f1os en [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-12-29T12:54:11+00:00","og_image":[{"width":960,"height":540,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg","type":"image\/jpeg"}],"author":"La Silla Rota","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Silla Rota","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/"},"author":{"name":"La Silla Rota","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/62ca416a4f36e3bbaa81ca03c42a24de"},"headline":"Israel aprueba la adopci\u00f3n homoparental sin restricciones","datePublished":"2023-12-29T12:54:11+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/","name":"Israel aprueba la adopci\u00f3n homoparental sin restricciones - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg","datePublished":"2023-12-29T12:54:11+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/ANILLOS_LGBT.jpg","width":960,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/29\/israel-aprueba-la-adopcion-homoparental-sin-restricciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Israel aprueba la adopci\u00f3n homoparental sin restricciones"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/62ca416a4f36e3bbaa81ca03c42a24de","name":"La Silla Rota","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c473d6857904ee40ef78411891b0c3f6ea4a9f84fb03dd3f5dde7ae7c097430?s=96&d=mm&r=g","caption":"La Silla Rota"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/lasillarota\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=69486"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69486\/revisions"}],"predecessor-version":[{"id":69488,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69486\/revisions\/69488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/69487"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=69486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=69486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=69486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}