{"id":69210,"date":"2023-12-21T13:14:24","date_gmt":"2023-12-21T20:14:24","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=69210"},"modified":"2023-12-21T13:14:26","modified_gmt":"2023-12-21T20:14:26","slug":"reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/","title":{"rendered":"Reconocen a &#8216;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em><br>Por medio de un video, el equipo de b\u00e9isbol que participa en la LMP rindi\u00f3 homenaje al exestrella de los Dodgers de Los \u00c1ngeles en las Grandes Ligas<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La noche de ayer fue muy especial para los sonorenses y en particular para el<strong>\u00a0hijo pr\u00f3digo<\/strong>\u00a0de dicho estado, el beisbolista\u00a0<strong>Fernando Valenzuela<\/strong>, quien fue reconocido en su tierra natal al nombrar al estadio de los Naranjeros de Hermosillo con su nombre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por medio de un video, el equipo de b\u00e9isbol que participa en la Liga Mexicana del Pac\u00edfico (LMP) rindi\u00f3 homenaje al exestrella de los Dodgers de Los \u00c1ngeles en las Grandes Ligas, para despu\u00e9s ser el encargado de lanzar la primera bola en el encuentro que disput\u00f3 Naranjeros ante Mayos de Navojoa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el acto,<strong>&nbsp;la afici\u00f3n reconoci\u00f3 al tambi\u00e9n llamado \u2018Toro\u2019<\/strong>, quien es originario de Etchohuaquila, Navojoa,<a href=\"https:\/\/www.excelsior.com.mx\/sonora\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;Sonora<\/a>&nbsp;y cuyo palmar\u00e9s es infinito, pues sin duda alguna Fernando es el&nbsp;<strong>pelotero m\u00e1s destacado&nbsp;<\/strong>en la historia de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u2018El Toro\u2019, de 63 a\u00f1os, fue miembro de dos equipos campeones de la Serie Mundial (1981 y 1988) y es el \u00fanico lanzador en la historia de las Grandes Ligas en ganar los premios Novato del A\u00f1o y Cy Young en la misma temporada (1981). Fue seleccionado para seis All-Star y gan\u00f3 dos premios Silver Slugger (1981, 1983) durante sus 11 temporadas con los Dodgers de 1980 a 1990.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">La leyenda se hizo presente \ud83d\udc4f Fernando Valenzuela, esta es tu casa \u2b50\ud83c\udfdf\ufe0f<a href=\"https:\/\/twitter.com\/hashtag\/NaranjerosFlow?src=hash&amp;ref_src=twsrc%5Etfw\">#NaranjerosFlow<\/a> <a href=\"https:\/\/t.co\/3mn9FaNmA7\">pic.twitter.com\/3mn9FaNmA7<\/a><\/p>&mdash; Naranjeros de \ud835\udc07ermosillo (@ClubNaranjeros) <a href=\"https:\/\/twitter.com\/ClubNaranjeros\/status\/1737713937905520767?ref_src=twsrc%5Etfw\">December 21, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Valenzuela recibi\u00f3 llave del estadio<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alfonso Durazo, gobernador del estado hizo la entrega oficial a Fernando Valenzuela de la llave del estadio de Sonora, el cual ya lleva el nombre del exlanzador mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un video publicado en su cuenta oficial de&nbsp;<a href=\"https:\/\/www.excelsior.com.mx\/x\" target=\"_blank\" rel=\"noreferrer noopener\">X&nbsp;<\/a>de Durazo, declar\u00f3 que \u201chonor a quien honor merece\u201d, honrando con la entrega de la llave simb\u00f3lica del nuevo inmueble al \u201cm\u00e1s grande beisbolista en la historia de M\u00e9xico\u201d, cuyo \u201cnombre representa la grandeza de Sonora\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u00a1Honor a quien honor merece! Hoy entregamos la llave del estadio Fernando Valenzuela al m\u00e1s grande beisbolista en la historia de M\u00e9xico. Tu nombre representa la grandeza de Sonora. <a href=\"https:\/\/t.co\/49KmU1Y7vC\">pic.twitter.com\/49KmU1Y7vC<\/a><\/p>&mdash; Alfonso Durazo (@AlfonsoDurazo) <a href=\"https:\/\/twitter.com\/AlfonsoDurazo\/status\/1737650491675517300?ref_src=twsrc%5Etfw\">December 21, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por medio de un video, el equipo de b\u00e9isbol que participa en la LMP rindi\u00f3 homenaje al exestrella de los Dodgers de Los \u00c1ngeles en las Grandes Ligas La noche de ayer fue muy especial para los sonorenses y en particular para el\u00a0hijo pr\u00f3digo\u00a0de dicho estado, el beisbolista\u00a0Fernando Valenzuela, quien fue reconocido en su tierra [&hellip;]<\/p>\n","protected":false},"author":123,"featured_media":69211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-69210","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reconocen a &#039;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reconocen a &#039;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Por medio de un video, el equipo de b\u00e9isbol que participa en la LMP rindi\u00f3 homenaje al exestrella de los Dodgers de Los \u00c1ngeles en las Grandes Ligas La noche de ayer fue muy especial para los sonorenses y en particular para el\u00a0hijo pr\u00f3digo\u00a0de dicho estado, el beisbolista\u00a0Fernando Valenzuela, quien fue reconocido en su tierra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T20:14:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T20:14:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"664\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adrenalina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrenalina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/\"},\"author\":{\"name\":\"Adrenalina\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\"},\"headline\":\"Reconocen a &#8216;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre\",\"datePublished\":\"2023-12-21T20:14:24+00:00\",\"dateModified\":\"2023-12-21T20:14:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3051627.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/\",\"name\":\"Reconocen a 'El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3051627.jpg\",\"datePublished\":\"2023-12-21T20:14:24+00:00\",\"dateModified\":\"2023-12-21T20:14:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3051627.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/3051627.jpg\",\"width\":664,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/12\\\/21\\\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reconocen a &#8216;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\",\"name\":\"Adrenalina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"caption\":\"Adrenalina\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/adrenalina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reconocen a 'El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/","og_locale":"es_MX","og_type":"article","og_title":"Reconocen a 'El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas","og_description":"Por medio de un video, el equipo de b\u00e9isbol que participa en la LMP rindi\u00f3 homenaje al exestrella de los Dodgers de Los \u00c1ngeles en las Grandes Ligas La noche de ayer fue muy especial para los sonorenses y en particular para el\u00a0hijo pr\u00f3digo\u00a0de dicho estado, el beisbolista\u00a0Fernando Valenzuela, quien fue reconocido en su tierra [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-12-21T20:14:24+00:00","article_modified_time":"2023-12-21T20:14:26+00:00","og_image":[{"width":664,"height":498,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg","type":"image\/jpeg"}],"author":"Adrenalina","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Adrenalina","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/"},"author":{"name":"Adrenalina","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3"},"headline":"Reconocen a &#8216;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre","datePublished":"2023-12-21T20:14:24+00:00","dateModified":"2023-12-21T20:14:26+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/","name":"Reconocen a 'El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg","datePublished":"2023-12-21T20:14:24+00:00","dateModified":"2023-12-21T20:14:26+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/12\/3051627.jpg","width":664,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/12\/21\/reconocen-a-el-toro-valenzuela-en-sonora-estadio-de-naranjeros-llevara-su-nombre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Reconocen a &#8216;El Toro\u2019 Valenzuela en Sonora; estadio de Naranjeros llevar\u00e1 su nombre"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3","name":"Adrenalina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","caption":"Adrenalina"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/adrenalina\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=69210"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69210\/revisions"}],"predecessor-version":[{"id":69212,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/69210\/revisions\/69212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/69211"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=69210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=69210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=69210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}