{"id":6252,"date":"2021-06-29T15:44:39","date_gmt":"2021-06-29T22:44:39","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=6252"},"modified":"2021-06-29T15:44:40","modified_gmt":"2021-06-29T22:44:40","slug":"sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/","title":{"rendered":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La AMDA solicit\u00f3 una audiencia con el presidente L\u00f3pez Obrador para solicitarle que todo auto que ingrese cumpla el procedimiento aduanero.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- La Asociaci\u00f3n Mexicana de Distribuidores de Automotores (AMDA) solicit\u00f3 una audiencia con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para pedirle que no regularice los autos usados importados de Estados Unidos de manera ilegal, com\u00fanmente llamados \u201cchocolate\u201d, porque tendr\u00eda repercusiones negativas en la econom\u00eda y medio ambiente del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la conferencia de la ma\u00f1ana, el mandatario dijo que ven importante esta situaci\u00f3n principalmente en municipios de la frontera con Estados Unidos porque son las personas m\u00e1s humildes las que son afectadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEntonces, vamos a regularizar, que no sea mucho el tr\u00e1mite, que se simplifique, que se puedan entregar las placas o el reconocimiento de la propiedad del veh\u00edculo y que se pague una cantidad justa por el tr\u00e1mite, y que todo eso que se obtenga se le devuelva a la gente en programas de bienestar, ya sea en salud, en educaci\u00f3n, en servicios p\u00fablicos; por ejemplo, estuvimos en Rosarito y es una demanda sentida\u201d, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo cual la AMDA respondi\u00f3 que la introducci\u00f3n y comercializaci\u00f3n de veh\u00edculos usados procedentes de Estados Unidos sin cumplir las formalidades del procedimiento aduanero es un delito que se ha pretendido resolver sin \u00e9xito mediante disposiciones del Poder Ejecutivo y el Legislativo, tal como lo acredita la existencia de 19 procesos de regularizaci\u00f3n en el periodo de 1979 a 2011.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs importante anotar que la importaci\u00f3n de veh\u00edculos usados es factible realizarse de conformidad al decreto por el que se modifica y prorroga el diverso por el que se regula la importaci\u00f3n definitiva de veh\u00edculos usados, publicado por sus instrucciones en el Diario Oficial de la Federaci\u00f3n el 24 de diciembre de 2020\u201d, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En lo que respecta a la utilizaci\u00f3n de veh\u00edculos en los actos criminales, la AMDA apunt\u00f3 que es notoria la utilizaci\u00f3n de veh\u00edculos con condiciones mec\u00e1nicas que les aseguren su objetivo y proceden generalmente del robo de unidades de modelo reciente que son f\u00e1cilmente desechados despu\u00e9s de su uso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa regularizaci\u00f3n de veh\u00edculos ilegales afectar\u00e1 en primer t\u00e9rmino el patrimonio de los ciudadanos propietarios de veh\u00edculos en el pa\u00eds, quienes cumplen con sus obligaciones fiscales, al disminuir el valor de los mismos ante la saturaci\u00f3n de la oferta que se dar\u00e1 con la regularizaci\u00f3n (\u2026) La regularizaci\u00f3n de los veh\u00edculos que se encuentran en calidad de contrabando ser\u00e1 la oportunidad para incrementar la basura automotriz circulando en nuestro pa\u00eds, y para introducir tantos o m\u00e1s veh\u00edculos de los que actualmente circulan ilegalmente\u201d, destacaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La AMDA solicit\u00f3 una audiencia con el presidente L\u00f3pez Obrador para solicitarle que todo auto que ingrese cumpla el procedimiento aduanero. Ciudad de M\u00e9xico.- La Asociaci\u00f3n Mexicana de Distribuidores de Automotores (AMDA) solicit\u00f3 una audiencia con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para pedirle que no regularice los autos usados importados de Estados [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":6253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[1156,1157],"class_list":["post-6252","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales","tag-auto-chocolate","tag-sector-automotriz"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La AMDA solicit\u00f3 una audiencia con el presidente L\u00f3pez Obrador para solicitarle que todo auto que ingrese cumpla el procedimiento aduanero. Ciudad de M\u00e9xico.- La Asociaci\u00f3n Mexicana de Distribuidores de Automotores (AMDA) solicit\u00f3 una audiencia con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para pedirle que no regularice los autos usados importados de Estados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-29T22:44:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-29T22:44:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1116\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Financiero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Financiero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/\"},\"author\":{\"name\":\"El Financiero\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/494f7e0dce8dfaaec5b64f16615b78e9\"},\"headline\":\"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019\",\"datePublished\":\"2021-06-29T22:44:39+00:00\",\"dateModified\":\"2021-06-29T22:44:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/\"},\"wordCount\":488,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AUTO_CHOCOLATE.jpg\",\"keywords\":[\"Auto chocolate\",\"Sector automotriz\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/\",\"name\":\"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AUTO_CHOCOLATE.jpg\",\"datePublished\":\"2021-06-29T22:44:39+00:00\",\"dateModified\":\"2021-06-29T22:44:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AUTO_CHOCOLATE.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/AUTO_CHOCOLATE.jpg\",\"width\":1116,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/29\\\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/494f7e0dce8dfaaec5b64f16615b78e9\",\"name\":\"El Financiero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"caption\":\"El Financiero\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/financiero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/","og_locale":"es_MX","og_type":"article","og_title":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas","og_description":"La AMDA solicit\u00f3 una audiencia con el presidente L\u00f3pez Obrador para solicitarle que todo auto que ingrese cumpla el procedimiento aduanero. Ciudad de M\u00e9xico.- La Asociaci\u00f3n Mexicana de Distribuidores de Automotores (AMDA) solicit\u00f3 una audiencia con el presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, para pedirle que no regularice los autos usados importados de Estados [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-06-29T22:44:39+00:00","article_modified_time":"2021-06-29T22:44:40+00:00","og_image":[{"width":1116,"height":628,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg","type":"image\/jpeg"}],"author":"El Financiero","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Financiero","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/"},"author":{"name":"El Financiero","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/494f7e0dce8dfaaec5b64f16615b78e9"},"headline":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019","datePublished":"2021-06-29T22:44:39+00:00","dateModified":"2021-06-29T22:44:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/"},"wordCount":488,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg","keywords":["Auto chocolate","Sector automotriz"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/","name":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019 - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg","datePublished":"2021-06-29T22:44:39+00:00","dateModified":"2021-06-29T22:44:40+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/AUTO_CHOCOLATE.jpg","width":1116,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/29\/sector-automotriz-pide-a-amlo-no-regularizar-autos-chocolate-un-dano-al-ambiente-y-la-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Sector automotriz pide a AMLO no regularizar autos chocolate; \u2018un da\u00f1o al ambiente y la econom\u00eda\u2019"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/494f7e0dce8dfaaec5b64f16615b78e9","name":"El Financiero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","caption":"El Financiero"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/financiero\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6252"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6252\/revisions"}],"predecessor-version":[{"id":6254,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/6252\/revisions\/6254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/6253"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}