{"id":62422,"date":"2023-10-14T16:05:37","date_gmt":"2023-10-14T23:05:37","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=62422"},"modified":"2023-10-14T16:08:06","modified_gmt":"2023-10-14T23:08:06","slug":"sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/","title":{"rendered":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br \/><strong><em>Barbara Lango, mexicana y m\u00e9dica que radica en Gaza, est\u00e1 atrapada, junto con su esposo, en la zona sur de la guerra y busca salir por la frontera con Egipto<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gaza. Barbara Lango, sinaloense que radica en la Franja de Gaza desde 2022, est\u00e1 atrapada, junto con su esposo, en la zona de guerra y busca salir por la frontera con Egipto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con Porfirio Lango, padre de la m\u00e9dica mazatleca, su hija actualmente se encuentra al sur de Gaza, con la esperanza de abandonar el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista, Porfirio explic\u00f3 que su hija es anestesi\u00f3logo y lleg\u00f3 a esta regi\u00f3n luego de pertenecer al equipo M\u00e9dicos sin Fronteras: \u201cDesde hace dos a\u00f1os ha estado en diversas misiones, en \u00c1frica, Hait\u00ed y, el a\u00f1o pasado, estuvo en la<strong>&nbsp;Franja de Gaza como m\u00e9dico sin fronteras<\/strong>\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, detall\u00f3 que B\u00e1rbara se encarg\u00f3 de abrir dos unidades de quemados en los principales hospitales de la&nbsp;<strong>Franja de Gaza<\/strong>; sin embargo, con los recientes bombardeos de Israel, la joven abandon\u00f3 su trabajo y domicilio cuando los ataques los alcanzaron a ella y a su esposo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La secretaria de Relaciones Exteriores,<strong>&nbsp;Alicia Barcena<\/strong>, exigi\u00f3 este s\u00e1bado al gobierno de&nbsp;<strong>Israel<\/strong>&nbsp;permitir a la mexicana&nbsp;<strong>B\u00e1rbara Lango&nbsp;<\/strong>salir de&nbsp;<strong>Gaza<\/strong>&nbsp;en medio de la ofensiva israel\u00ed y la prohibici\u00f3n a los civiles de salir de la&nbsp;<strong>ciudad palestina.&nbsp;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHe tomado contacto con UNRWA, oficina de refugiados de&nbsp;<strong>ONU<\/strong>&nbsp;en Gaza, para apoyar a&nbsp;<strong>B\u00e1rbara Lango<\/strong>. Estamos intentando que salga por&nbsp;<strong>Egipto<\/strong>, pero&nbsp;<strong>Israel<\/strong>&nbsp;no autoriza un&nbsp;<strong>cord\u00f3n humanitario<\/strong>&nbsp;ni permite la salida de nadie. Es urgente hacer un llamado a Israel porque aun la guerra tiene reglas\u201d, critic\u00f3 la canciller en redes sociales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En redes sociales,&nbsp;<strong>familiares<\/strong>&nbsp;pidieron ayuda internacional y del presidente<strong>&nbsp;Andr\u00e9s Manuel L\u00f3pez Obrador&nbsp;<\/strong>para que&nbsp;<strong>B\u00e1rbara Lango&nbsp;<\/strong>pueda salir de la Franja de Gaza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMi prima B\u00e1rbara Lango, as\u00ed como miles de personas necesitan ayuda, hago un&nbsp;<strong>llamado internacional&nbsp;<\/strong>y a L\u00f3pez Obrador para poder extraerla de la&nbsp;<strong>Franja<\/strong>&nbsp;con bien\u201d, exigi\u00f3 una familiar.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista para&nbsp;<em>Radio F\u00f3rmula<\/em>, Porfirio Lango detall\u00f3 que su hija B\u00e1rbara es&nbsp;<strong>anestesiologa<\/strong>&nbsp;y trabaj\u00f3 para&nbsp;<strong>M\u00e9dicos Sin Fronteras<\/strong>&nbsp;en misiones en \u00c1frica, Yem\u00e9n y Hait\u00ed, pero desde el a\u00f1o pasado labora en la&nbsp;<strong>Franja de Gaza.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que, ante los bombardeos israel\u00eds, B\u00e1rbara y su esposo se desplazaron a la ciudad de Jan Yunis, en la frontera con&nbsp;<strong>Egipto<\/strong>, donde piden que les permitan salir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el 13 de octubre, la Embajada de M\u00e9xico en&nbsp;<strong>Tel Aviv&nbsp;<\/strong>solicit\u00f3 a Israel que permita la evacuaci\u00f3n humanitaria de la pareja en Gaza a trav\u00e9s de la frontera de Rafah a&nbsp;<strong>Egipto<\/strong>, sin embargo, no han obtenido respuesta, se\u00f1al\u00f3 el pap\u00e1 de la joven.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barbara Lango, mexicana y m\u00e9dica que radica en Gaza, est\u00e1 atrapada, junto con su esposo, en la zona sur de la guerra y busca salir por la frontera con Egipto Gaza. Barbara Lango, sinaloense que radica en la Franja de Gaza desde 2022, est\u00e1 atrapada, junto con su esposo, en la zona de guerra y [&hellip;]<\/p>\n","protected":false},"author":85,"featured_media":62424,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-62422","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-principal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Barbara Lango, mexicana y m\u00e9dica que radica en Gaza, est\u00e1 atrapada, junto con su esposo, en la zona sur de la guerra y busca salir por la frontera con Egipto Gaza. Barbara Lango, sinaloense que radica en la Franja de Gaza desde 2022, est\u00e1 atrapada, junto con su esposo, en la zona de guerra y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-14T23:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-14T23:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Latinus\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Latinus\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/\"},\"author\":{\"name\":\"Latinus\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\"},\"headline\":\"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019\",\"datePublished\":\"2023-10-14T23:05:37+00:00\",\"dateModified\":\"2023-10-14T23:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/\"},\"wordCount\":535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/\",\"name\":\"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg\",\"datePublished\":\"2023-10-14T23:05:37+00:00\",\"dateModified\":\"2023-10-14T23:08:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg\",\"width\":1024,\"height\":529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/10\\\/14\\\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2bf81f85e8b5d89dbb825a184aa39dde\",\"name\":\"Latinus\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g\",\"caption\":\"Latinus\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/latinus\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/","og_locale":"es_MX","og_type":"article","og_title":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas","og_description":"Barbara Lango, mexicana y m\u00e9dica que radica en Gaza, est\u00e1 atrapada, junto con su esposo, en la zona sur de la guerra y busca salir por la frontera con Egipto Gaza. Barbara Lango, sinaloense que radica en la Franja de Gaza desde 2022, est\u00e1 atrapada, junto con su esposo, en la zona de guerra y [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-10-14T23:05:37+00:00","article_modified_time":"2023-10-14T23:08:06+00:00","og_image":[{"width":1024,"height":529,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg","type":"image\/jpeg"}],"author":"Latinus","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Latinus","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/"},"author":{"name":"Latinus","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde"},"headline":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019","datePublished":"2023-10-14T23:05:37+00:00","dateModified":"2023-10-14T23:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/"},"wordCount":535,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/","name":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019 - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg","datePublished":"2023-10-14T23:05:37+00:00","dateModified":"2023-10-14T23:08:06+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/10\/mexico-israel-salir-mexicana-barbara-lango-gaza-1024x529-1.jpg","width":1024,"height":529},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/10\/14\/sinloense-queda-atrapada-gaza-sre-pide-israel-dejarla-salir-la-guerra-tiene-reglas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Doctora sinaloense queda atrapada en Gaza; SRE pide a Israel dejarla salir: \u2018La guerra tiene reglas\u2019"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2bf81f85e8b5d89dbb825a184aa39dde","name":"Latinus","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/333f6d932ce645348bb256f0b554d58398c56212134ea658df4ac492d6eba412?s=96&d=mm&r=g","caption":"Latinus"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/latinus\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/62422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/85"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=62422"}],"version-history":[{"count":4,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/62422\/revisions"}],"predecessor-version":[{"id":62427,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/62422\/revisions\/62427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/62424"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=62422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=62422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=62422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}