{"id":59283,"date":"2023-09-16T10:49:18","date_gmt":"2023-09-16T17:49:18","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=59283"},"modified":"2023-09-16T10:50:21","modified_gmt":"2023-09-16T17:50:21","slug":"sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/","title":{"rendered":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><em><strong>Sergio P\u00e9rez reiter\u00f3 que siguen los problemas en su auto. Para este domingo, espera el \u2018contragolpe\u2019 y otros factores<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Singapur. Red Bull no la pas\u00f3 nada bien en la calificaci\u00f3n del Gran Premio de Singapur 2023 de la F\u00f3rmula Uno. Sergio \u2018Checo\u2019 P\u00e9rez fue eliminado en la Q2 y, al final, se mostr\u00f3 molesto, adem\u00e1s de admitir que \u2018fue un desastre\u2019 y que \u2018estamos bastante perdidos\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo encontr\u00e1bamos el agarre, tratamos todo con los neum\u00e1ticos, en el primer sector resbalamos bastante. De la Q1 a la Q2 las cosas empeoraron\u201d, indic\u00f3 a los micr\u00f3fonos de&nbsp;<em>Fox Sports<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El piloto mexicano tuvo un problema en el turbo \u201cy luego me peg\u00f3 muy fuerte la potencia, perd\u00ed el auto, luego al frenarlo en la parte sucia&nbsp;<strong>fue un desastre<\/strong>, creo que podr\u00edamos haber entrado en la Q3, pero m\u00e1s que eso hoy no parecemos tener nada de ritmo, estamos bastante perdidos tambi\u00e9n\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">And we&#39;re out \ud83d\ude1e P11 for Max and P13 for Checo, that&#39;s the end of Qualifying for us in Sinagpore \ud83c\udfc1 <a href=\"https:\/\/t.co\/LXZ0dFzwdf\">pic.twitter.com\/LXZ0dFzwdf<\/a><\/p>&mdash; Oracle Red Bull Racing (@redbullracing) <a href=\"https:\/\/twitter.com\/redbullracing\/status\/1703048931108663671?ref_src=twsrc%5Etfw\">September 16, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2018Checo\u2019 P\u00e9rez<\/strong>&nbsp;apunt\u00f3 que el balance en la calificaci\u00f3n no fue positivo, al contrario, de la Q1 a la Q2 tomaron un paso hacia atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn mi \u00faltimo intento para pasar a Q3, no tuvimos nada de agarre y\u00a0 tuve ese problema con el motor. Tambi\u00e9n hemos tenido un poco de problemas en la parte del motor, cuando aceleramos, tenemos algunos brincos en la aceleraci\u00f3n que nos hace perder tracci\u00f3n\u201d, apunt\u00f3 el tapat\u00edo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u2018Checo\u2019 P\u00e9rez<\/strong>&nbsp;no mostr\u00f3 esperanzas como en otras ocasiones que ha quedado eliminado en la calificaci\u00f3n de un Gran Premio. Esperar\u00e1 el \u2018contragolpe\u2019 y otros factores en el circuito de Marina Bay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMuy dif\u00edcil aqu\u00ed hacer algo, esperar safety car, otros factores, pasar aqu\u00ed ser\u00e1 complicado. Sab\u00edamos que la calificaci\u00f3n iba a ser importante y no pudimos hacer nada\u201d, mencion\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergio P\u00e9rez saldr\u00e1 este domingo en el sitio 13 del Gran Premio de Singapur 2023 de la F1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sergio P\u00e9rez reiter\u00f3 que siguen los problemas en su auto. Para este domingo, espera el \u2018contragolpe\u2019 y otros factores Singapur. Red Bull no la pas\u00f3 nada bien en la calificaci\u00f3n del Gran Premio de Singapur 2023 de la F\u00f3rmula Uno. Sergio \u2018Checo\u2019 P\u00e9rez fue eliminado en la Q2 y, al final, se mostr\u00f3 molesto, adem\u00e1s [&hellip;]<\/p>\n","protected":false},"author":123,"featured_media":59285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-59283","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Sergio P\u00e9rez reiter\u00f3 que siguen los problemas en su auto. Para este domingo, espera el \u2018contragolpe\u2019 y otros factores Singapur. Red Bull no la pas\u00f3 nada bien en la calificaci\u00f3n del Gran Premio de Singapur 2023 de la F\u00f3rmula Uno. Sergio \u2018Checo\u2019 P\u00e9rez fue eliminado en la Q2 y, al final, se mostr\u00f3 molesto, adem\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-16T17:49:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-16T17:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"664\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Adrenalina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Adrenalina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/\"},\"author\":{\"name\":\"Adrenalina\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\"},\"headline\":\"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019\",\"datePublished\":\"2023-09-16T17:49:18+00:00\",\"dateModified\":\"2023-09-16T17:50:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/\"},\"wordCount\":350,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3006735.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/\",\"name\":\"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3006735.jpg\",\"datePublished\":\"2023-09-16T17:49:18+00:00\",\"dateModified\":\"2023-09-16T17:50:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3006735.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/3006735.jpg\",\"width\":664,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/16\\\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2d428574a5422b6bceea38751c96d3d3\",\"name\":\"Adrenalina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g\",\"caption\":\"Adrenalina\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/adrenalina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/","og_locale":"es_MX","og_type":"article","og_title":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas","og_description":"Sergio P\u00e9rez reiter\u00f3 que siguen los problemas en su auto. Para este domingo, espera el \u2018contragolpe\u2019 y otros factores Singapur. Red Bull no la pas\u00f3 nada bien en la calificaci\u00f3n del Gran Premio de Singapur 2023 de la F\u00f3rmula Uno. Sergio \u2018Checo\u2019 P\u00e9rez fue eliminado en la Q2 y, al final, se mostr\u00f3 molesto, adem\u00e1s [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-09-16T17:49:18+00:00","article_modified_time":"2023-09-16T17:50:21+00:00","og_image":[{"width":664,"height":498,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg","type":"image\/jpeg"}],"author":"Adrenalina","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Adrenalina","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/"},"author":{"name":"Adrenalina","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3"},"headline":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019","datePublished":"2023-09-16T17:49:18+00:00","dateModified":"2023-09-16T17:50:21+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/"},"wordCount":350,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/","name":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019 - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg","datePublished":"2023-09-16T17:49:18+00:00","dateModified":"2023-09-16T17:50:21+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/3006735.jpg","width":664,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/16\/sorpresa-checo-y-verstappen-eliminados-en-la-q2-de-singapur-fue-un-desastre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00a1Sorpresa! Checo y Verstappen eliminados en la Q2 de Singapur: \u2018fue un desastre\u2019"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2d428574a5422b6bceea38751c96d3d3","name":"Adrenalina","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16314b67761a38fa2534276f5eaca1785bf1af123d37aca3bbd9f504af51c00a?s=96&d=mm&r=g","caption":"Adrenalina"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/adrenalina\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/123"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=59283"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59283\/revisions"}],"predecessor-version":[{"id":59284,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/59283\/revisions\/59284"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/59285"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=59283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=59283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=59283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}