{"id":58659,"date":"2023-09-12T06:46:15","date_gmt":"2023-09-12T13:46:15","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=58659"},"modified":"2023-09-12T06:47:34","modified_gmt":"2023-09-12T13:47:34","slug":"inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/","title":{"rendered":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">LIBIA.- Las inundaciones provocadas por una enorme tormenta que revent\u00f3 represas devastaron la ciudad de Derna, en el este de Libia, dejando m\u00e1s de 2 mil 300 muertos y se teme que al menos 10 mil personas est\u00e9n desaparecieran despu\u00e9s de que las aguas arrasaron edificios yhasta una cuarta parte de la localidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00f3lo en Derna ya se hab\u00edan recuperado m\u00e1s de mil cad\u00e1veres, y los funcionarios esperaban que la cifra de muertos fuera mucho mayor, despu\u00e9s de que la tormenta Daniel atraves\u00f3 el Mediterr\u00e1neo hacia un pa\u00eds que ha estado en crisis tras m\u00e1s de una d\u00e9cada de conflicto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prensa observ\u00f3 en Derna, una ciudad costera de unos 125 mil habitantes, vio veh\u00edculos volcados en los bordes de las carreteras, \u00e1rboles derribados y casas abandonadas e inundadas.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"en\" dir=\"ltr\">My heart goes out to the people of Libya who are going through catastrophic flooding caused by Storm Daniel.<br><br>More than 2000 people killed in the floods, 6000 missing. From Israel, we pray for you. \ud83c\uddf1\ud83c\uddfe\ud83c\uddee\ud83c\uddf1 <a href=\"https:\/\/twitter.com\/hashtag\/Libya?src=hash&amp;ref_src=twsrc%5Etfw\">#Libya<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/StormDaniel?src=hash&amp;ref_src=twsrc%5Etfw\">#StormDaniel<\/a> <a href=\"https:\/\/t.co\/J1aUBfdVth\">pic.twitter.com\/J1aUBfdVth<\/a><\/p>&mdash; Hananya Naftali (@HananyaNaftali) <a href=\"https:\/\/twitter.com\/HananyaNaftali\/status\/1701494484859547860?ref_src=twsrc%5Etfw\">September 12, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Regres\u00e9 de Derna. Es muy desastroso. Hay cad\u00e1veres por todas partes: en el mar, en los valles, debajo de los edificios&#8221;, dijo Hichem Abu Chkiouat, ministro de Aviaci\u00f3n Civil y miembro del comit\u00e9 de emergencia de la administraci\u00f3n que controla el este del pa\u00eds, dijo a la agencia Reuters por tel\u00e9fono. &#8220;El n\u00famero de cad\u00e1veres recuperados en Derna supera los mil&#8221;, afirm\u00f3. &#8220;No exagero cuando digo que el 25% de la ciudad ha desaparecido. Muchos, muchos edificios se han derrumbado&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Usama Ali, vocero de estos servicios, que disponen de un equipo en Derna, indic\u00f3 que las inundaciones causadas por la tormenta Daniel causaron &#8220;m\u00e1s de 2 mil 300 muertos&#8221; y unos 7 mil heridos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tamer Ramadan, jefe de una delegaci\u00f3n de la Federaci\u00f3n Internacional de Sociedades de la Cruz Roja y de la Media Luna Roja (FICR), dijo a los periodistas en Ginebra a trav\u00e9s de un enlace de v\u00eddeo desde T\u00fanez: &#8220;Podemos confirmar a partir de nuestras fuentes de informaci\u00f3n independientes que el n\u00famero de personas desaparecidas es Llegando a 10 mik hasta ahora.&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los v\u00eddeos mostraban un gran torrente que atravesaba el centro de la ciudad de Derna despu\u00e9s de la rotura de las represas. A ambos lados hab\u00eda edificios en ruinas. Otro v\u00eddeo compartido en Facebook, que Reuters no pudo verificar de forma independiente, parec\u00eda mostrar decenas de cuerpos cubiertos con mantas en las aceras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las im\u00e1genes transmitidas por la estaci\u00f3n de televisi\u00f3n libia al-Masar mostraban a personas buscando cad\u00e1veres y a hombres en un bote de goma recuperando uno del mar.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"en\" dir=\"ltr\">\ud83c\uddf1\ud83c\uddfe Libyan National Army Spokesperson: Dam Collapses Trigger Devastating Flood in Derna <a href=\"https:\/\/twitter.com\/hashtag\/Libya?src=hash&amp;ref_src=twsrc%5Etfw\">#Libya<\/a> <a href=\"https:\/\/t.co\/PcYta0zaA5\">pic.twitter.com\/PcYta0zaA5<\/a><\/p>&mdash; D\u0113miurg\u00f2s (@DemiurgosCaen) <a href=\"https:\/\/twitter.com\/DemiurgosCaen\/status\/1701560837155029407?ref_src=twsrc%5Etfw\">September 12, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No tenemos nada para salvar a la gente\u2026 ni m\u00e1quinas\u2026 estamos pidiendo ayuda urgente&#8221;, dijo Khalifah Touil, un trabajador de ambulancia, en un informe de al-Masar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Derna est\u00e1 atravesada por un r\u00edo estacional que fluye desde las tierras altas hacia el sur y normalmente est\u00e1 protegido de las inundaciones por represas. Un v\u00eddeo publicado en las redes sociales muestra los restos de una presa colapsada 11.5 kil\u00f3metros r\u00edo arriba de la ciudad, donde converg\u00edan dos valles fluviales, ahora rodeados por enormes charcos de agua de color barro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Antes hab\u00eda una presa&#8221;, se escucha decir una voz en el v\u00eddeo. Reuters confirm\u00f3 la ubicaci\u00f3n bas\u00e1ndose en las im\u00e1genes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Convoyes de ayuda y asistencia se dirig\u00edan hacia la ciudad. Libia est\u00e1 pol\u00edticamente dividida entre el este y el oeste y los servicios p\u00fablicos se han desmoronado desde un levantamiento respaldado por la OTAN contra el entonces l\u00edder Muamar Gadafi en 2011 que provoc\u00f3 a\u00f1os de conflicto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno internacionalmente reconocido de Tr\u00edpoli no controla las zonas orientales, pero ha enviado ayuda a Derna, y al menos un vuelo de ayuda parti\u00f3 de la ciudad occidental de Misrata el martes, dijo un periodista de la agencia Reuters en el avi\u00f3n.<\/p>\n\n\n\n<blockquote class=\"twitter-tweet\"><p class=\"wp-block-paragraph\" lang=\"ar\" dir=\"rtl\">\u0631\u0628\u064a \u064a\u0631\u062d\u0645\u0647\u0645 \u0648\u064a\u063a\u0641\u0631 \u0644\u0647\u0645 \u0648\u064a\u0635\u0628\u0631 \u0627\u0647\u0644\u0647\u0645 \u0625\u0646 \u0634\u0627\u0621 \u0627\u0644\u0644\u0647<br><br>\u0644\u0627 \u062d\u0648\u0644 \u0648\u0644\u0627\u0642\u0648\u0629 \u0625\u0644\u0627 \u0628\u0627\u0644\u0644\u0647 \u0627\u0644\u0639\u0644\u064a \u0627\u0644\u0639\u0638\u064a\u0645 \ud83c\uddf1\ud83c\uddfe\ud83d\udc94<a href=\"https:\/\/twitter.com\/hashtag\/Libya?src=hash&amp;ref_src=twsrc%5Etfw\">#Libya<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D8%A5%D8%B9%D8%B5%D8%A7%D8%B1_%D8%AF%D8%A7%D9%86%D9%8A%D8%A7%D9%84?src=hash&amp;ref_src=twsrc%5Etfw\">#\u0625\u0639\u0635\u0627\u0631_\u062f\u0627\u0646\u064a\u0627\u0644<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D9%84%D9%8A%D8%A8%D9%8A%D8%A7_%D8%AA%D8%B3%D8%AA%D8%BA%D9%8A%D8%AB?src=hash&amp;ref_src=twsrc%5Etfw\">#\u0644\u064a\u0628\u064a\u0627_\u062a\u0633\u062a\u063a\u064a\u062b<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D8%A7%D9%86%D9%82%D8%B0%D9%88%D8%A7_%D8%A7%D9%84%D8%B4%D8%B1%D9%82_%D8%A7%D9%84%D9%84%D9%8A%D8%A8%D9%8A?src=hash&amp;ref_src=twsrc%5Etfw\">#\u0627\u0646\u0642\u0630\u0648\u0627_\u0627\u0644\u0634\u0631\u0642_\u0627\u0644\u0644\u064a\u0628\u064a<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/%D9%84%D9%8A%D8%A8%D9%8A%D8%A7?src=hash&amp;ref_src=twsrc%5Etfw\">#\u0644\u064a\u0628\u064a\u0627<\/a> <a href=\"https:\/\/t.co\/AmVQT8XbNE\">pic.twitter.com\/AmVQT8XbNE<\/a><\/p>&mdash; \ud83c\udde9\ud83c\uddff \u0641\u0631\u064a\u0627\u0644 (@Ferial999) <a href=\"https:\/\/twitter.com\/Ferial999\/status\/1701531804740550936?ref_src=twsrc%5Etfw\">September 12, 2023<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n\n\n\n<p class=\"wp-block-paragraph\">Calificada por los expertos como un fen\u00f3meno &#8220;extremo en t\u00e9rminos de cantidad de agua ca\u00edda&#8221;, la tormenta Daniel afect\u00f3 en los \u00faltimos d\u00edas Grecia, Turqu\u00eda y Bulgaria, con un saldo de 27 muertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El este de Libia alberga los principales yacimientos y terminales petrol\u00edferas. La Compa\u00f1\u00eda Nacional de Petr\u00f3leo (NOC) ha declarado el &#8220;estado de m\u00e1xima alerta&#8221; y &#8220;suspendido los vuelos&#8221; entre los centros de producci\u00f3n, donde la actividad se ha reducido dr\u00e1sticamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos LIBIA.- Las inundaciones provocadas por una enorme tormenta que revent\u00f3 represas devastaron la ciudad de Derna, en el este de Libia, dejando m\u00e1s de 2 mil 300 muertos y se teme que al menos 10 mil personas est\u00e9n desaparecieran despu\u00e9s [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":58660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-58659","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos LIBIA.- Las inundaciones provocadas por una enorme tormenta que revent\u00f3 represas devastaron la ciudad de Derna, en el este de Libia, dejando m\u00e1s de 2 mil 300 muertos y se teme que al menos 10 mil personas est\u00e9n desaparecieran despu\u00e9s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-12T13:46:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-12T13:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reuters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reuters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/\"},\"author\":{\"name\":\"Reuters\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\"},\"headline\":\"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos\",\"datePublished\":\"2023-09-12T13:46:15+00:00\",\"dateModified\":\"2023-09-12T13:47:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/\"},\"wordCount\":815,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIBIA_INUNDACIONES.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/\",\"name\":\"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIBIA_INUNDACIONES.jpg\",\"datePublished\":\"2023-09-12T13:46:15+00:00\",\"dateModified\":\"2023-09-12T13:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIBIA_INUNDACIONES.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/LIBIA_INUNDACIONES.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/09\\\/12\\\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\",\"name\":\"Reuters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"caption\":\"Reuters\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/reuters\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/","og_locale":"es_MX","og_type":"article","og_title":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas","og_description":"Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos LIBIA.- Las inundaciones provocadas por una enorme tormenta que revent\u00f3 represas devastaron la ciudad de Derna, en el este de Libia, dejando m\u00e1s de 2 mil 300 muertos y se teme que al menos 10 mil personas est\u00e9n desaparecieran despu\u00e9s [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-09-12T13:46:15+00:00","article_modified_time":"2023-09-12T13:47:34+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg","type":"image\/jpeg"}],"author":"Reuters","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Reuters","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/"},"author":{"name":"Reuters","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f"},"headline":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos","datePublished":"2023-09-12T13:46:15+00:00","dateModified":"2023-09-12T13:47:34+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/"},"wordCount":815,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/","name":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg","datePublished":"2023-09-12T13:46:15+00:00","dateModified":"2023-09-12T13:47:34+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/09\/LIBIA_INUNDACIONES.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/09\/12\/inundaciones-en-libia-arrasan-con-una-ciudad-y-dejan-mas-de-2-mil-300-muertos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"VIDEOS | Inundaciones en Libia arrasan con una ciudad y dejan m\u00e1s de 2 mil 300 muertos"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f","name":"Reuters","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","caption":"Reuters"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/reuters\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58659"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58659\/revisions"}],"predecessor-version":[{"id":58662,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/58659\/revisions\/58662"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/58660"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}