{"id":55067,"date":"2023-08-11T01:10:00","date_gmt":"2023-08-11T08:10:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=55067"},"modified":"2023-08-11T12:55:23","modified_gmt":"2023-08-11T19:55:23","slug":"ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/","title":{"rendered":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>En d\u00edas pasados, el Congreso del Estado de Sinaloa aprob\u00f3 penalizar las terapias de conversi\u00f3n y a quien anule o suprima la orientaci\u00f3n sexual<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- &#8220;No hay nada que curar&#8221; porque desde hace m\u00e1s de 30 a\u00f1os, la Organizaci\u00f3n Mundial de la Salud (OMS) descart\u00f3 la homosexualidad como una enfermedad. Sin embargo, los Esfuerzos para Corregir la Orientaci\u00f3n Sexual o Identidad de G\u00e9nero (ECOSIG) lastiman y han orillado a miembros de la comunidad LGBT+ a tomar la decisi\u00f3n de quitarse la vida, advirti\u00f3 la diputada&nbsp;<strong>Almendra Ernestina Negrete S\u00e1nchez.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La presidenta de la&nbsp;<strong>Comisi\u00f3n de Igualdad de G\u00e9nero y Familia<\/strong> lament\u00f3 que, estos tipos de tratamiento, lejos se ayudar pueden&nbsp;causar a las v\u00edctimas da\u00f1os psicol\u00f3gicos y f\u00edsicos que pueden llegar a ser permanentes, incluso llegando a autoflagelarse o cometer suicidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Negrete S\u00e1nchez critic\u00f3 la postura de algunos grupos religiosos y otros conocidos como pro-familia, los cuales durante el proceso de la reforma para penalizar estos tratamientos optaron por el camino de lo se\u00f1alamientos y en &#8220;defender&#8221; por qu\u00e9 estaba mal el hecho tener preferencias sexuales diferentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ECOSIG son penalizados en Sinaloa<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En d\u00edas pasados, el Congreso del Estado de Sinaloa aprob\u00f3 penalizar las terapias de conversi\u00f3n y quien realice, imparta, aplique, obligue o financie cualquier tipo de tratamiento, servicio o pr\u00e1ctica que obstaculice, restrinja, impida, menoscabe, anule o suprima la orientaci\u00f3n sexual, identidad de g\u00e9nero o expresi\u00f3n de g\u00e9nero de una persona y derivado de estos se afecte su integridad f\u00edsica, moral o psicoemocional, <em>se le impondr\u00e1 de dos a seis a\u00f1os de prisi\u00f3n y de doscientos a cuatrocientos d\u00edas multa<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La legisladora morenista detall\u00f3 que para seguir este delito, ser\u00e1 necesario presentar una denuncia de por medio, pero se perseguir\u00e1 de oficio cuando la v\u00edctima sea ni\u00f1a, ni\u00f1o o adolescente, persona con discapacidad, o adulto mayor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 es un ECOSIG?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se entiende por ECOGIEG o tambi\u00e9n conocidos como terapias de conversi\u00f3n, a los tratamientos, servicios, o pr\u00e1cticas cualquiera que sea su denominaci\u00f3n a las sesiones psicol\u00f3gicas, psiqui\u00e1tricas, m\u00e9todos o tratamientos que tengan por objeto anular, obstaculizar, reprimir o menoscabar la expresi\u00f3n de g\u00e9nero o identidad de g\u00e9nero, as\u00ed como la orientaci\u00f3n sexual de la persona, en las que se emplea violencia f\u00edsica, moral o psicoemocional, mediante tratos crueles, inhumanos o degradantes que atenten contra la dignidad humana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En d\u00edas pasados, el Congreso del Estado de Sinaloa aprob\u00f3 penalizar las terapias de conversi\u00f3n y a quien anule o suprima la orientaci\u00f3n sexual Culiac\u00e1n, Sin.- &#8220;No hay nada que curar&#8221; porque desde hace m\u00e1s de 30 a\u00f1os, la Organizaci\u00f3n Mundial de la Salud (OMS) descart\u00f3 la homosexualidad como una enfermedad. Sin embargo, los Esfuerzos [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":55087,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-55067","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"En d\u00edas pasados, el Congreso del Estado de Sinaloa aprob\u00f3 penalizar las terapias de conversi\u00f3n y a quien anule o suprima la orientaci\u00f3n sexual Culiac\u00e1n, Sin.- &#8220;No hay nada que curar&#8221; porque desde hace m\u00e1s de 30 a\u00f1os, la Organizaci\u00f3n Mundial de la Salud (OMS) descart\u00f3 la homosexualidad como una enfermedad. Sin embargo, los Esfuerzos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-11T08:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T19:55:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marissa Palafox\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marissa Palafox\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/\"},\"author\":{\"name\":\"Marissa Palafox\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2c10028b4a30078c05a056a215342ab9\"},\"headline\":\"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+\",\"datePublished\":\"2023-08-11T08:10:00+00:00\",\"dateModified\":\"2023-08-11T19:55:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/\",\"name\":\"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg\",\"datePublished\":\"2023-08-11T08:10:00+00:00\",\"dateModified\":\"2023-08-11T19:55:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/08\\\/11\\\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/2c10028b4a30078c05a056a215342ab9\",\"name\":\"Marissa Palafox\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g\",\"caption\":\"Marissa Palafox\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/marissa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/","og_locale":"es_MX","og_type":"article","og_title":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas","og_description":"En d\u00edas pasados, el Congreso del Estado de Sinaloa aprob\u00f3 penalizar las terapias de conversi\u00f3n y a quien anule o suprima la orientaci\u00f3n sexual Culiac\u00e1n, Sin.- &#8220;No hay nada que curar&#8221; porque desde hace m\u00e1s de 30 a\u00f1os, la Organizaci\u00f3n Mundial de la Salud (OMS) descart\u00f3 la homosexualidad como una enfermedad. Sin embargo, los Esfuerzos [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-08-11T08:10:00+00:00","article_modified_time":"2023-08-11T19:55:23+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg","type":"image\/jpeg"}],"author":"Marissa Palafox","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Marissa Palafox","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/"},"author":{"name":"Marissa Palafox","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2c10028b4a30078c05a056a215342ab9"},"headline":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+","datePublished":"2023-08-11T08:10:00+00:00","dateModified":"2023-08-11T19:55:23+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/","name":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+ - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg","datePublished":"2023-08-11T08:10:00+00:00","dateModified":"2023-08-11T19:55:23+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/08\/terapias-de-conversion-nota1-1024x683-1-e1691720032857.jpeg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/08\/11\/ecosig-terapias-de-conversion-pueden-orillar-al-suicidio-en-la-comunidad-lgbt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"ECOSIG: Terapias de conversi\u00f3n pueden orillar al suicidio en la comunidad LGBT+"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/2c10028b4a30078c05a056a215342ab9","name":"Marissa Palafox","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/20a43bdb2f2db10f20b22d4e98b96eb027faf98f7f76d29854dc5fab46d1cf71?s=96&d=mm&r=g","caption":"Marissa Palafox"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/marissa\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=55067"}],"version-history":[{"count":5,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55067\/revisions"}],"predecessor-version":[{"id":56281,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/55067\/revisions\/56281"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/55087"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=55067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=55067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=55067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}