{"id":5080,"date":"2021-06-15T10:12:46","date_gmt":"2021-06-15T17:12:46","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=5080"},"modified":"2021-06-15T10:12:47","modified_gmt":"2021-06-15T17:12:47","slug":"se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/","title":{"rendered":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes"},"content":{"rendered":"\n<p><strong><em>Dicha vigencia fue modificada una vez m\u00e1s para que los electores con estas fechas de vigencia puedan participar en la consulta popular programada para el 1 de agosto 2021<\/em><\/strong><\/p>\n\n\n\n<p>Ciudad de M\u00e9xico.- El Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 extender el plazo de vigencia de las credenciales vencidas en los a\u00f1os 2019 y 2020 hasta el 1 de agosto del 2021 para participar en la consulta popular.<\/p>\n\n\n\n<p>En un principio, el organismo electoral decidi\u00f3 que por motivos de la contingencia y ante los comicios electorales del d\u00eda 6 de junio, se extender\u00eda la vigencia de las credenciales vencidas en el a\u00f1o 2019 y 2020<\/p>\n\n\n\n<p>Dicha vigencia fue modificada una vez m\u00e1s para que los electores con estas fechas de vigencia puedan participar en la consulta popular programada para el 1 de agosto 2021.<\/p>\n\n\n\n<p>Estas resoluciones se dan luego de la propuesta realizada por el presidente Andr\u00e9s Manuel L\u00f3pez Obrador y que fue aprobada por el Senado.<\/p>\n\n\n\n<p>Este pr\u00f3ximo 1 de agosto, los ciudadanos responder\u00e1n una pregunta en la que se plantea el emprender procesos contra ex funcionarios, los mexicanos mayores de 18 a\u00f1os participar\u00e1n con su INE ya sea vencida en los 2 a\u00f1os anteriores o bien estando vigente.<\/p>\n\n\n\n<p>La pregunta que deber\u00e1n contestar los participantes en la consulta ser\u00e1 &#8220;\u00bfEst\u00e1s de acuerdo o no en que se lleven a cabo las acciones pertinentes, con apego al marco constitucional y legal, para emprender un proceso de esclarecimiento de las decisiones pol\u00edticas tomadas en los a\u00f1os pasados por los actores pol\u00edticos encaminado a garantizar la justicia y los derechos de las posibles v\u00edctimas?&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dicha vigencia fue modificada una vez m\u00e1s para que los electores con estas fechas de vigencia puedan participar en la consulta popular programada para el 1 de agosto 2021 Ciudad de M\u00e9xico.- El Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 extender el plazo de vigencia de las credenciales vencidas en los a\u00f1os 2019 y [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":5081,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[247,297,784,785,264,263],"class_list":{"0":"post-5080","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales","8":"tag-amlo","9":"tag-andres-manuel-lopez-obrador","10":"tag-consejo-general-del-instituto-nacional-electoral","11":"tag-consulta-popular","12":"tag-ine","13":"tag-instituto-nacional-electoral"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Dicha vigencia fue modificada una vez m\u00e1s para que los electores con estas fechas de vigencia puedan participar en la consulta popular programada para el 1 de agosto 2021 Ciudad de M\u00e9xico.- El Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 extender el plazo de vigencia de las credenciales vencidas en los a\u00f1os 2019 y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T17:12:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T17:12:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanguardia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanguardia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/\"},\"author\":{\"name\":\"Vanguardia\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\"},\"headline\":\"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes\",\"datePublished\":\"2021-06-15T17:12:46+00:00\",\"dateModified\":\"2021-06-15T17:12:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/\"},\"wordCount\":282,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CREDENCIAL_INE.jpg\",\"keywords\":[\"AMLO\",\"Andr\u00e9s Manuel L\u00f3pez Obrador\",\"Consejo General del Instituto Nacional Electoral\",\"Consulta Popular\",\"INE\",\"Instituto Nacional Electoral\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/\",\"name\":\"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CREDENCIAL_INE.jpg\",\"datePublished\":\"2021-06-15T17:12:46+00:00\",\"dateModified\":\"2021-06-15T17:12:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CREDENCIAL_INE.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/CREDENCIAL_INE.jpg\",\"width\":980,\"height\":601},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/06\\\/15\\\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\",\"name\":\"Vanguardia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"caption\":\"Vanguardia\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/vanguardia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/","og_locale":"es_MX","og_type":"article","og_title":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas","og_description":"Dicha vigencia fue modificada una vez m\u00e1s para que los electores con estas fechas de vigencia puedan participar en la consulta popular programada para el 1 de agosto 2021 Ciudad de M\u00e9xico.- El Consejo General del Instituto Nacional Electoral (INE) aprob\u00f3 extender el plazo de vigencia de las credenciales vencidas en los a\u00f1os 2019 y [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-06-15T17:12:46+00:00","article_modified_time":"2021-06-15T17:12:47+00:00","og_image":[{"width":980,"height":601,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg","type":"image\/jpeg"}],"author":"Vanguardia","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Vanguardia","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/"},"author":{"name":"Vanguardia","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b"},"headline":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes","datePublished":"2021-06-15T17:12:46+00:00","dateModified":"2021-06-15T17:12:47+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/"},"wordCount":282,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg","keywords":["AMLO","Andr\u00e9s Manuel L\u00f3pez Obrador","Consejo General del Instituto Nacional Electoral","Consulta Popular","INE","Instituto Nacional Electoral"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/","name":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg","datePublished":"2021-06-15T17:12:46+00:00","dateModified":"2021-06-15T17:12:47+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/06\/CREDENCIAL_INE.jpg","width":980,"height":601},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/06\/15\/se-extendera-la-vigencia-de-credenciales-ine-para-consulta-de-expresidentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Se extender\u00e1 la vigencia de credenciales INE para consulta de expresidentes"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b","name":"Vanguardia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","caption":"Vanguardia"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/vanguardia\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5080"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5080\/revisions"}],"predecessor-version":[{"id":5082,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/5080\/revisions\/5082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/5081"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5080"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5080"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}