{"id":47134,"date":"2023-05-14T01:00:00","date_gmt":"2023-05-14T07:00:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=47134"},"modified":"2023-05-13T14:25:12","modified_gmt":"2023-05-13T20:25:12","slug":"por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/","title":{"rendered":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La mujer cont\u00f3 estar cansada de que el novio de su hija se la viv\u00eda en su casa y no ayudaba en nada<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kevin Correo tuvo que ser hospitalizado luego de que su suegra le lanzara agua hirviendo, provoc\u00e1ndole quemaduras de gravedad en el brazo y la espalda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con informaci\u00f3n, la se\u00f1ora de 61 a\u00f1os relat\u00f3 sentirse cansada de que su yerno llegara todas las ma\u00f1anas a desayunar a su casa con el pretexto de visitar a su hija.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00abEn varias ocasiones le ped\u00ed a Kevin para comprar un hielo y nunca ten\u00eda plata, siempre me dec\u00eda: Caramba suegra, con la pensi\u00f3n que usted tiene y no le da para comprar un hielo. \u00bfC\u00f3mo les parece el descaro de este tipo? Imag\u00ednense que despu\u00e9s de haber comido lo que le serv\u00eda se paraba a pedir el cucayo, y en ocasiones m\u00e1s comida porque dec\u00eda que le hab\u00eda servido muy poquito\u201d,<\/em><\/strong>&nbsp;relat\u00f3 la mujer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hecho ocurrido en Colombia ha llamado la atenci\u00f3n de varias personas, ya que algunos han apoyado y defendido la acci\u00f3n de la se\u00f1ora, mientras que otros comentaron que la situaci\u00f3n no era tan grave para actuar de esa manera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mujer cont\u00f3 estar cansada de que el novio de su hija se la viv\u00eda en su casa y no ayudaba en nada Kevin Correo tuvo que ser hospitalizado luego de que su suegra le lanzara agua hirviendo, provoc\u00e1ndole quemaduras de gravedad en el brazo y la espalda. De acuerdo con informaci\u00f3n, la se\u00f1ora de [&hellip;]<\/p>\n","protected":false},"author":119,"featured_media":47135,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[40],"tags":[],"class_list":["post-47134","post","type-post","status-publish","format-standard","has-post-thumbnail","category-las-asombrosas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La mujer cont\u00f3 estar cansada de que el novio de su hija se la viv\u00eda en su casa y no ayudaba en nada Kevin Correo tuvo que ser hospitalizado luego de que su suegra le lanzara agua hirviendo, provoc\u00e1ndole quemaduras de gravedad en el brazo y la espalda. De acuerdo con informaci\u00f3n, la se\u00f1ora de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-14T07:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Judith Su\u00e1rez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Judith Su\u00e1rez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/\"},\"author\":{\"name\":\"Judith Su\u00e1rez\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f9ef4b58e604d94a7e6488115cc40195\"},\"headline\":\"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno\",\"datePublished\":\"2023-05-14T07:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg\",\"articleSection\":[\"LAS ASOMBROSAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/\",\"name\":\"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg\",\"datePublished\":\"2023-05-14T07:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg\",\"width\":780,\"height\":470},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/14\\\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f9ef4b58e604d94a7e6488115cc40195\",\"name\":\"Judith Su\u00e1rez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g\",\"caption\":\"Judith Su\u00e1rez\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/judith\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/","og_locale":"es_MX","og_type":"article","og_title":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas","og_description":"La mujer cont\u00f3 estar cansada de que el novio de su hija se la viv\u00eda en su casa y no ayudaba en nada Kevin Correo tuvo que ser hospitalizado luego de que su suegra le lanzara agua hirviendo, provoc\u00e1ndole quemaduras de gravedad en el brazo y la espalda. De acuerdo con informaci\u00f3n, la se\u00f1ora de [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-05-14T07:00:00+00:00","og_image":[{"width":780,"height":470,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg","type":"image\/jpeg"}],"author":"Judith Su\u00e1rez","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Judith Su\u00e1rez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/"},"author":{"name":"Judith Su\u00e1rez","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f9ef4b58e604d94a7e6488115cc40195"},"headline":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno","datePublished":"2023-05-14T07:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg","articleSection":["LAS ASOMBROSAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/","name":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg","datePublished":"2023-05-14T07:00:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-13-at-2.23.32-PM.jpeg","width":780,"height":470},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/14\/por-gorron-suegra-le-lanza-agua-hirviendo-a-su-yerno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00a1Por gorr\u00f3n! Suegra le lanza agua hirviendo a su yerno"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f9ef4b58e604d94a7e6488115cc40195","name":"Judith Su\u00e1rez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/635dd19e433134ba191ee8b63b75fa6d2880c00c60a86dcd1fd23dd9cdd215e9?s=96&d=mm&r=g","caption":"Judith Su\u00e1rez"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/judith\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/47134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=47134"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/47134\/revisions"}],"predecessor-version":[{"id":47136,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/47134\/revisions\/47136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/47135"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=47134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=47134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=47134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}