{"id":46900,"date":"2023-05-11T12:47:24","date_gmt":"2023-05-11T18:47:24","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=46900"},"modified":"2023-05-11T12:47:31","modified_gmt":"2023-05-11T18:47:31","slug":"dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/","title":{"rendered":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em><strong>El peso cotizaba en 17.6727 unidades, con una p\u00e9rdida de 0.72% frente al precio de referencia de Reuters del mi\u00e9rcoles<\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- \u00a0El peso se depreciaba el jueves ante un fortalecimiento global del d\u00f3lar tras la divulgaci\u00f3n de cifras del empleo y la inflaci\u00f3n estadounidense que avivaron las perspectivas de que el ciclo de ajuste monetario de la Reserva Federal (Fed) habr\u00eda llegado a su fin.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peso cotizaba en 17.6727 unidades, con una p\u00e9rdida de 0.72% frente al precio de referencia de&nbsp;<em>Reuters<\/em>&nbsp;del mi\u00e9rcoles, luego de avanzar previamente a 17.5270 por d\u00f3lar, un nivel no visto desde julio de 2017.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<strong>La divisa mexicana se vio afectada por indicadores que muestran que la actividad econ\u00f3mica se est\u00e1 desacelerando en Estados Unidos\u201d, dijo Monex Grupo Financiero. \u201cEstos resultados apoyan las apuestas de que el ciclo de ajustes al alza de la tasa de los fondos federales concluy\u00f3 en mayo\u201d<\/strong>, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Analistas tambi\u00e9n mencionaron que en el \u00e1nimo de los inversores pesaban adem\u00e1s renovadas preocupaciones en torno a algunos bancos regionales estadounidenses, as\u00ed como la creciente incertidumbre por el techo de la deuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el resto de la jornada, se esperaba que el peso oscile en un rango de 17.55 a 17.70 por d\u00f3lar, seg\u00fan proyecciones de la firma Banco Base.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso cotizaba en 17.6727 unidades, con una p\u00e9rdida de 0.72% frente al precio de referencia de Reuters del mi\u00e9rcoles Ciudad de M\u00e9xico.- \u00a0El peso se depreciaba el jueves ante un fortalecimiento global del d\u00f3lar tras la divulgaci\u00f3n de cifras del empleo y la inflaci\u00f3n estadounidense que avivaron las perspectivas de que el ciclo de [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":46901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-46900","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El peso cotizaba en 17.6727 unidades, con una p\u00e9rdida de 0.72% frente al precio de referencia de Reuters del mi\u00e9rcoles Ciudad de M\u00e9xico.- \u00a0El peso se depreciaba el jueves ante un fortalecimiento global del d\u00f3lar tras la divulgaci\u00f3n de cifras del empleo y la inflaci\u00f3n estadounidense que avivaron las perspectivas de que el ciclo de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-11T18:47:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-11T18:47:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reuters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reuters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/\"},\"author\":{\"name\":\"Reuters\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\"},\"headline\":\"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades\",\"datePublished\":\"2023-05-11T18:47:24+00:00\",\"dateModified\":\"2023-05-11T18:47:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/\"},\"wordCount\":234,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/peso-red.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/\",\"name\":\"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/peso-red.jpg\",\"datePublished\":\"2023-05-11T18:47:24+00:00\",\"dateModified\":\"2023-05-11T18:47:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/peso-red.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/peso-red.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/11\\\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\",\"name\":\"Reuters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"caption\":\"Reuters\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/reuters\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/","og_locale":"es_MX","og_type":"article","og_title":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas","og_description":"El peso cotizaba en 17.6727 unidades, con una p\u00e9rdida de 0.72% frente al precio de referencia de Reuters del mi\u00e9rcoles Ciudad de M\u00e9xico.- \u00a0El peso se depreciaba el jueves ante un fortalecimiento global del d\u00f3lar tras la divulgaci\u00f3n de cifras del empleo y la inflaci\u00f3n estadounidense que avivaron las perspectivas de que el ciclo de [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-05-11T18:47:24+00:00","article_modified_time":"2023-05-11T18:47:31+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg","type":"image\/jpeg"}],"author":"Reuters","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Reuters","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/"},"author":{"name":"Reuters","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f"},"headline":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades","datePublished":"2023-05-11T18:47:24+00:00","dateModified":"2023-05-11T18:47:31+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/"},"wordCount":234,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/","name":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg","datePublished":"2023-05-11T18:47:24+00:00","dateModified":"2023-05-11T18:47:31+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/peso-red.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/11\/dolar-se-la-devuelve-al-superpeso-se-cotiza-en-las-17-62-unidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"D\u00f3lar se la \u2018devuelve\u2019 al \u2018superpeso\u2019: se cotiza en las 17.62 unidades"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f","name":"Reuters","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","caption":"Reuters"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/reuters\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=46900"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46900\/revisions"}],"predecessor-version":[{"id":46902,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46900\/revisions\/46902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/46901"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=46900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=46900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=46900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}