{"id":46360,"date":"2023-05-05T01:53:00","date_gmt":"2023-05-05T07:53:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=46360"},"modified":"2023-05-05T07:40:57","modified_gmt":"2023-05-05T13:40:57","slug":"uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/","title":{"rendered":"Uganda ajusta una dura ley contra comunidad LGBTQ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Un sospechoso condenado por \u201cintento de homosexualidad agravada\u201d puede ser encarcelado 14 a\u00f1os<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">KAMPALA, Uganda (AP) \u2014 Parlamentarios ugandeses aprobaron el martes una nueva versi\u00f3n de una ley para eliminar una cl\u00e1usula que parec\u00eda criminalizar a los que se identifican como LGBTQ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente, Yoweri Museveni, devolvi\u00f3 el mes pasado la iniciativa a la asamblea nacional y pidi\u00f3 cambios para diferenciar entre identificarse como LGBTQ y participar en actos homosexuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La homosexualidad ya es ilegal en el pa\u00eds del este de \u00c1frica seg\u00fan una ley de la era colonial que criminaliza las relaciones sexuales \u201ccontra el orden natural\u201d. La pena por ese delito es cadena perpetua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La nueva norma prescribe la pena de muerte por \u201chomosexualidad agravada\u201d, definida como casos de relaciones sexuales con personas infectadas de VIH, menores o cualquier otra categor\u00eda de personas vulnerables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un sospechoso condenado por \u201cintento de homosexualidad agravada\u201d puede ser encarcelado 14 a\u00f1os, mientras que el delito de \u201cintento de homosexualidad\u201d es sancionable con hasta 10 a\u00f1os de c\u00e1rcel, seg\u00fan el texto de la ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque la norma ya no penalizar\u00eda a los que se identifican como LGBTQ, propone penas de c\u00e1rcel de hasta 20 a\u00f1os para los que defiendan o fomenten los derechos de personas LGBTQ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los parlamentarios aprobaron la norma el martes y la devolvieron a Museveni, que pod\u00eda firmarla o vetarla. En un primer momento no estaba claro qu\u00e9 otros cambios se hab\u00edan hecho a la propuesta en una larga sesi\u00f3n plenaria en la capital, Kampala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Museveni ha recibido presiones internacionales para que vete la propuesta de ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos ha advertido de consecuencias econ\u00f3micas si la legislaci\u00f3n se aprueba, y un grupo de expertos de Naciones Unidas describi\u00f3 el texto aprobado antes por los legisladores como una \u201cviolaci\u00f3n descarada de los derechos humanos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un sospechoso condenado por \u201cintento de homosexualidad agravada\u201d puede ser encarcelado 14 a\u00f1os KAMPALA, Uganda (AP) \u2014 Parlamentarios ugandeses aprobaron el martes una nueva versi\u00f3n de una ley para eliminar una cl\u00e1usula que parec\u00eda criminalizar a los que se identifican como LGBTQ. El presidente, Yoweri Museveni, devolvi\u00f3 el mes pasado la iniciativa a la asamblea [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":46361,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-46360","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Un sospechoso condenado por \u201cintento de homosexualidad agravada\u201d puede ser encarcelado 14 a\u00f1os KAMPALA, Uganda (AP) \u2014 Parlamentarios ugandeses aprobaron el martes una nueva versi\u00f3n de una ley para eliminar una cl\u00e1usula que parec\u00eda criminalizar a los que se identifican como LGBTQ. El presidente, Yoweri Museveni, devolvi\u00f3 el mes pasado la iniciativa a la asamblea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-05T07:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-05T13:40:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"AP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"AP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/\"},\"author\":{\"name\":\"AP\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f60dc42c98af4d2079046d414cccced3\"},\"headline\":\"Uganda ajusta una dura ley contra comunidad LGBTQ\",\"datePublished\":\"2023-05-05T07:53:00+00:00\",\"dateModified\":\"2023-05-05T13:40:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/UGANDA_LGBT.jpeg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/\",\"name\":\"Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/UGANDA_LGBT.jpeg\",\"datePublished\":\"2023-05-05T07:53:00+00:00\",\"dateModified\":\"2023-05-05T13:40:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/UGANDA_LGBT.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/UGANDA_LGBT.jpeg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2023\\\/05\\\/05\\\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uganda ajusta una dura ley contra comunidad LGBTQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f60dc42c98af4d2079046d414cccced3\",\"name\":\"AP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g\",\"caption\":\"AP\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/ap\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/","og_locale":"es_MX","og_type":"article","og_title":"Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas","og_description":"Un sospechoso condenado por \u201cintento de homosexualidad agravada\u201d puede ser encarcelado 14 a\u00f1os KAMPALA, Uganda (AP) \u2014 Parlamentarios ugandeses aprobaron el martes una nueva versi\u00f3n de una ley para eliminar una cl\u00e1usula que parec\u00eda criminalizar a los que se identifican como LGBTQ. El presidente, Yoweri Museveni, devolvi\u00f3 el mes pasado la iniciativa a la asamblea [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2023-05-05T07:53:00+00:00","article_modified_time":"2023-05-05T13:40:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg","type":"image\/jpeg"}],"author":"AP","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"AP","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/"},"author":{"name":"AP","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f60dc42c98af4d2079046d414cccced3"},"headline":"Uganda ajusta una dura ley contra comunidad LGBTQ","datePublished":"2023-05-05T07:53:00+00:00","dateModified":"2023-05-05T13:40:57+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/","name":"Uganda ajusta una dura ley contra comunidad LGBTQ - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg","datePublished":"2023-05-05T07:53:00+00:00","dateModified":"2023-05-05T13:40:57+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2023\/05\/UGANDA_LGBT.jpeg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2023\/05\/05\/uganda-ajusta-una-dura-ley-contra-comunidad-lgbtq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Uganda ajusta una dura ley contra comunidad LGBTQ"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f60dc42c98af4d2079046d414cccced3","name":"AP","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/914c563784b53cfd9d6b64319280e11b1d299d85ff3468b20fec3ae1a146c6b3?s=96&d=mm&r=g","caption":"AP"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/ap\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=46360"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46360\/revisions"}],"predecessor-version":[{"id":46362,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/46360\/revisions\/46362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/46361"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=46360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=46360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=46360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}