{"id":43593,"date":"2022-09-30T09:12:15","date_gmt":"2022-09-30T15:12:15","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=43593"},"modified":"2022-09-30T09:12:17","modified_gmt":"2022-09-30T15:12:17","slug":"comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/","title":{"rendered":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Ante el triunfo del partido derechista liderado por Giorgia Meloni en Italia, la comunidad teme por los derechos de los homosexuales<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comunidad de lesbianas, gays, bisexuales y transexuales (LGBT) tiene \u201c<em>temores muy reales<\/em>\u201d despu\u00e9s de que un bloque conservador, dominado por la extrema derecha, gan\u00f3 las elecciones en Italia, dijo a Reuters un destacado activista de los derechos de los homosexuales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El grupo nacionalista Hermanos de Italia, liderado por Giorgia Meloni, se erigi\u00f3 como el mayor partido en las votaciones y dirigir\u00e1 el Gobierno m\u00e1s derechista de Roma desde la Segunda Guerra Mundial.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLamentablemente, hay temores muy reales\u201d&nbsp;<\/strong>sobre una erosi\u00f3n de los derechos civiles bajo el nuevo Gobierno, dijo Fabrizio Marrazzo, del Partido Gay.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meloni est\u00e1 aliada con la Liga, otra fuerza de extrema derecha liderada por Matteo Salvini, y la corriente conservadora Forza Italia del expremier Silvio Berlusconi.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-comunidad-lgbt-tiene-temores-muy-reales-tras-el-triunfo-de-la-extrema-derecha-en-italia\">La comunidad LGBT tiene \u2018temores muy reales\u2019 tras el triunfo de la extrema derecha en Italia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cLa Liga y en parte Hermanos de Italia tienen en sus manifiestos cosas bastante negativas para nuestra comunidad, como subrayar la importancia de proteger s\u00f3lo la familia tradicional\u201d<\/strong>, dijo Marrazzo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Meloni, de 45 a\u00f1os, fue criada por una madre soltera y es soltera con una hija. Se presenta como defensora de los valores cristianos y enemiga de lo que llama \u201cideolog\u00eda de g\u00e9nero\u201d y del \u201clobby LGBT\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para explicar su oposici\u00f3n a los derechos de paternidad de los homosexuales, ha dicho que los \u201cni\u00f1os desafortunados\u201d que est\u00e1n en adopci\u00f3n \u201cmerecen lo mejor\u201d, es decir, un padre y una madre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Meloni ha negado las insinuaciones de que su visi\u00f3n socialmente conservadora se extienda a socavar o abolir la legislaci\u00f3n italiana vigente sobre el derecho al aborto o las parejas del mismo sexo.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo que est\u00e1 ah\u00ed, se queda ah\u00ed\u201d, dijo la semana pasada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante el triunfo del partido derechista liderado por Giorgia Meloni en Italia, la comunidad teme por los derechos de los homosexuales La comunidad de lesbianas, gays, bisexuales y transexuales (LGBT) tiene \u201ctemores muy reales\u201d despu\u00e9s de que un bloque conservador, dominado por la extrema derecha, gan\u00f3 las elecciones en Italia, dijo a Reuters un destacado [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":43594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-43593","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Ante el triunfo del partido derechista liderado por Giorgia Meloni en Italia, la comunidad teme por los derechos de los homosexuales La comunidad de lesbianas, gays, bisexuales y transexuales (LGBT) tiene \u201ctemores muy reales\u201d despu\u00e9s de que un bloque conservador, dominado por la extrema derecha, gan\u00f3 las elecciones en Italia, dijo a Reuters un destacado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-30T15:12:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-30T15:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reuters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reuters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/\"},\"author\":{\"name\":\"Reuters\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\"},\"headline\":\"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia\",\"datePublished\":\"2022-09-30T15:12:15+00:00\",\"dateModified\":\"2022-09-30T15:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-Orgullo-uno-640x360-1.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/\",\"name\":\"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-Orgullo-uno-640x360-1.jpg\",\"datePublished\":\"2022-09-30T15:12:15+00:00\",\"dateModified\":\"2022-09-30T15:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-Orgullo-uno-640x360-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Dia-del-Orgullo-uno-640x360-1.jpg\",\"width\":640,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/30\\\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\",\"name\":\"Reuters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"caption\":\"Reuters\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/reuters\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/","og_locale":"es_MX","og_type":"article","og_title":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas","og_description":"Ante el triunfo del partido derechista liderado por Giorgia Meloni en Italia, la comunidad teme por los derechos de los homosexuales La comunidad de lesbianas, gays, bisexuales y transexuales (LGBT) tiene \u201ctemores muy reales\u201d despu\u00e9s de que un bloque conservador, dominado por la extrema derecha, gan\u00f3 las elecciones en Italia, dijo a Reuters un destacado [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-09-30T15:12:15+00:00","article_modified_time":"2022-09-30T15:12:17+00:00","og_image":[{"width":640,"height":360,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg","type":"image\/jpeg"}],"author":"Reuters","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Reuters","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/"},"author":{"name":"Reuters","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f"},"headline":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia","datePublished":"2022-09-30T15:12:15+00:00","dateModified":"2022-09-30T15:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/","name":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg","datePublished":"2022-09-30T15:12:15+00:00","dateModified":"2022-09-30T15:12:17+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/Dia-del-Orgullo-uno-640x360-1.jpg","width":640,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/30\/comunidad-lgbt-expresa-temor-tras-triunfo-de-la-derecha-en-italia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Comunidad LGBT expresa \u2018temor\u2019 tras triunfo de la derecha en Italia"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f","name":"Reuters","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","caption":"Reuters"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/reuters\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43593"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43593\/revisions"}],"predecessor-version":[{"id":43595,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43593\/revisions\/43595"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/43594"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}