{"id":43088,"date":"2022-09-23T08:54:20","date_gmt":"2022-09-23T14:54:20","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=43088"},"modified":"2022-09-23T08:54:53","modified_gmt":"2022-09-23T14:54:53","slug":"peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/","title":{"rendered":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><em>El peso cotizaba en 20.1373 por d\u00f3lar, con una p\u00e9rdida de 1.04% frente al precio de referencia del jueves<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico. El peso se depreciaba el viernes en la apertura mientras los inversores temen la llegada de pol\u00edticas monetarias m\u00e1s restrictivas y aumenta tambi\u00e9n el miedo a una posible recesi\u00f3n global.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peso cotizaba en 20.1373 por d\u00f3lar, con una p\u00e9rdida de 1.04% frente al precio de referencia del jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El d\u00f3lar segu\u00eda mostr\u00e1ndose fuerte tras el impulso que recibi\u00f3 esta semana gracias al anuncio de la pol\u00edtica monetaria de la Reserva Federal y al aumento de los rendimientos de los bonos del Tesoro.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso cotizaba en 20.1373 por d\u00f3lar, con una p\u00e9rdida de 1.04% frente al precio de referencia del jueves Ciudad de M\u00e9xico. El peso se depreciaba el viernes en la apertura mientras los inversores temen la llegada de pol\u00edticas monetarias m\u00e1s restrictivas y aumenta tambi\u00e9n el miedo a una posible recesi\u00f3n global. El peso cotizaba [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":43090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-43088","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El peso cotizaba en 20.1373 por d\u00f3lar, con una p\u00e9rdida de 1.04% frente al precio de referencia del jueves Ciudad de M\u00e9xico. El peso se depreciaba el viernes en la apertura mientras los inversores temen la llegada de pol\u00edticas monetarias m\u00e1s restrictivas y aumenta tambi\u00e9n el miedo a una posible recesi\u00f3n global. El peso cotizaba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T14:54:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-23T14:54:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reuters\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reuters\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/\"},\"author\":{\"name\":\"Reuters\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\"},\"headline\":\"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n\",\"datePublished\":\"2022-09-23T14:54:20+00:00\",\"dateModified\":\"2022-09-23T14:54:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/\"},\"wordCount\":129,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2827913.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/\",\"name\":\"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2827913.jpg\",\"datePublished\":\"2022-09-23T14:54:20+00:00\",\"dateModified\":\"2022-09-23T14:54:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2827913.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/2827913.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/09\\\/23\\\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/699c239076aac7aa88ecc3c15c72710f\",\"name\":\"Reuters\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g\",\"caption\":\"Reuters\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/reuters\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/","og_locale":"es_MX","og_type":"article","og_title":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas","og_description":"El peso cotizaba en 20.1373 por d\u00f3lar, con una p\u00e9rdida de 1.04% frente al precio de referencia del jueves Ciudad de M\u00e9xico. El peso se depreciaba el viernes en la apertura mientras los inversores temen la llegada de pol\u00edticas monetarias m\u00e1s restrictivas y aumenta tambi\u00e9n el miedo a una posible recesi\u00f3n global. El peso cotizaba [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-09-23T14:54:20+00:00","article_modified_time":"2022-09-23T14:54:53+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg","type":"image\/jpeg"}],"author":"Reuters","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Reuters","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/"},"author":{"name":"Reuters","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f"},"headline":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n","datePublished":"2022-09-23T14:54:20+00:00","dateModified":"2022-09-23T14:54:53+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/"},"wordCount":129,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/","name":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg","datePublished":"2022-09-23T14:54:20+00:00","dateModified":"2022-09-23T14:54:53+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/09\/2827913.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/09\/23\/peso-cae-ante-fortaleza-del-dolar-y-por-los-temores-de-una-recesion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Peso cae ante fortaleza del d\u00f3lar y por los temores de una recesi\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/699c239076aac7aa88ecc3c15c72710f","name":"Reuters","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/06c46a9bb47e91c2e7c5aa85ad0855c43a11fd5a7b8dd6ec0e8fe8e471140a59?s=96&d=mm&r=g","caption":"Reuters"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/reuters\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=43088"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43088\/revisions"}],"predecessor-version":[{"id":43089,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/43088\/revisions\/43089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/43090"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=43088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=43088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=43088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}