{"id":34602,"date":"2022-06-17T00:26:00","date_gmt":"2022-06-17T06:26:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=34602"},"modified":"2022-06-16T22:29:27","modified_gmt":"2022-06-17T04:29:27","slug":"que-significa-cada-color-de-la-bandera-lgbt","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/","title":{"rendered":"\u00bfQu\u00e9 significa cada color de la bandera LGBT?"},"content":{"rendered":"\n<p>La&nbsp;<strong>bandera LGBT<\/strong>&nbsp;tambi\u00e9n conocida como \u2018<a href=\"https:\/\/www.televisa.com\/noticias\/lgbt-que-significa-la-bandera-del-arcoiris\/\">bandera del arco\u00edris<\/a>\u2018, es un elemento importante para la liberaci\u00f3n de las identidades sexuales, ya que identifica a todas las personas de la comunidad gay y l\u00e9sbica del mundo. Esta est\u00e1 conformada por seis&nbsp;<strong>colores<\/strong>&nbsp;los cu\u00e1les tienen un&nbsp;<strong>significado&nbsp;<\/strong>diferente, de acuerdo con su creador, el artista y activista Gilbert Baker.<\/p>\n\n\n\n<p>Antes de que esta bandera existiera, los movimientos\u00a0<a href=\"https:\/\/www.televisa.com\/noticias\/desde-cuando-se-conmemora-en-mexico-el-orgullo-lgbt\/\">LGBT<\/a>\u00a0utilizaban un tri\u00e1ngulo rosa, el cual usaba Hitler durante la Segunda Guerra Mundial para marcar a las personas homosexuales en los campos de concentraci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 significa cada color de la bandera LGBT?<\/h2>\n\n\n\n<p>Al inicio la propuesta de Baker conten\u00eda ocho colores: rosa, rojo, naranja, amarillo, verde, turquesa, azul y morado; sin embargo, tras el asesinato de Harvey Milk el 27 de noviembre, la demanda por esta bandera aumento, y las empresas textiles no ten\u00edan suficientes telas rosas, por lo que se elimin\u00f3 el color.<\/p>\n\n\n\n<p>Meses despu\u00e9s, la bandera LGBT se comenz\u00f3 a colocar en San Francisco de forma vertical, pero debido a la luz de los postes se confund\u00eda el color turquesa, por lo que se opto quitarlo, quedando as\u00ed en 1979 con solo seis franjas.<\/p>\n\n\n\n<p>Aunque algunas personas piensan que cada color representa cada una de las orientaciones sexuales, esto es err\u00f3neo, ya que el significado de cada color de acuerdo con Baker es el siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Rosa: sexualidad.<\/li><li>Rojo: vida.<\/li><li>Naranja: salud.<\/li><li>Amarillo: luz de sol.<\/li><li>Verde: naturaleza.<\/li><li>Turquesa: magia y arte.<\/li><li>Azul: serenidad.<\/li><li>Morado: esp\u00edritu.<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"640\" height=\"400\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/orgullo-LGBT-que-significa-cada-color-de-la-bandera-LGBT-origen-bandera-de-arcoiris.jpg\" alt=\"\" class=\"wp-image-34603\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/orgullo-LGBT-que-significa-cada-color-de-la-bandera-LGBT-origen-bandera-de-arcoiris.jpg 640w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/orgullo-LGBT-que-significa-cada-color-de-la-bandera-LGBT-origen-bandera-de-arcoiris-300x188.jpg 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p id=\"caption-attachment-100164\">Foto: Getty Images<\/p>\n\n\n\n<p>Con el paso de los a\u00f1os, la&nbsp;<a href=\"https:\/\/www.televisa.com\/noticias\/si-la-comunidad-lgbt-fuera-un-pais-tendria-la-cuarta-economia-mas-grande-del-mundo\/\">comunidad<\/a>&nbsp;LGBT comenz\u00f3 a diversificarse a\u00fan m\u00e1s, por lo que han surgido otras banderas las cuales s\u00ed especifican cada una de las orientaciones sexuales, tales banderas son:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>La del Movimiento del orgullo l\u00e9sbico.<\/li><li>El Orgullo asexual.<\/li><li>Orgullo pansexual.<\/li><li>Ag\u00e9nero.<\/li><li>Orgullo transexual.<\/li><li>G\u00e9nero fluido.<\/li><li>Big\u00e9nero.<\/li><li>Orgullo polisexual.<\/li><\/ul>\n\n\n\n<p>Para conocer el significado de cada una de las siglas LGBTTTIQ+, puedes dar clic&nbsp;<a href=\"https:\/\/www.televisa.com\/noticias\/que-significan-las-siglas-lgbtttiq\/\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La&nbsp;bandera LGBT&nbsp;tambi\u00e9n conocida como \u2018bandera del arco\u00edris\u2018, es un elemento importante para la liberaci\u00f3n de las identidades sexuales, ya que identifica a todas las personas de la comunidad gay y l\u00e9sbica del mundo. Esta est\u00e1 conformada por seis&nbsp;colores&nbsp;los cu\u00e1les tienen un&nbsp;significado&nbsp;diferente, de acuerdo con su creador, el artista y activista Gilbert Baker. Antes de que [&hellip;]<\/p>\n","protected":false},"author":46,"featured_media":34606,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[487],"class_list":{"0":"post-34602","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-amor-es-amor","8":"category-semanales","9":"tag-amor-es-amor"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La&nbsp;bandera LGBT&nbsp;tambi\u00e9n conocida como \u2018bandera del arco\u00edris\u2018, es un elemento importante para la liberaci\u00f3n de las identidades sexuales, ya que identifica a todas las personas de la comunidad gay y l\u00e9sbica del mundo. Esta est\u00e1 conformada por seis&nbsp;colores&nbsp;los cu\u00e1les tienen un&nbsp;significado&nbsp;diferente, de acuerdo con su creador, el artista y activista Gilbert Baker. Antes de que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-17T06:26:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noticieros Televisa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noticieros Televisa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/\"},\"author\":{\"name\":\"Noticieros Televisa\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f030e42657a5a464a8bbd891b1aab6ee\"},\"headline\":\"\u00bfQu\u00e9 significa cada color de la bandera LGBT?\",\"datePublished\":\"2022-06-17T06:26:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/\"},\"wordCount\":350,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg\",\"keywords\":[\"Amor es amor\"],\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/\",\"name\":\"\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg\",\"datePublished\":\"2022-06-17T06:26:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/06\\\/17\\\/que-significa-cada-color-de-la-bandera-lgbt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 significa cada color de la bandera LGBT?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/f030e42657a5a464a8bbd891b1aab6ee\",\"name\":\"Noticieros Televisa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g\",\"caption\":\"Noticieros Televisa\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/noticieros-televisa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/","og_locale":"es_MX","og_type":"article","og_title":"\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas","og_description":"La&nbsp;bandera LGBT&nbsp;tambi\u00e9n conocida como \u2018bandera del arco\u00edris\u2018, es un elemento importante para la liberaci\u00f3n de las identidades sexuales, ya que identifica a todas las personas de la comunidad gay y l\u00e9sbica del mundo. Esta est\u00e1 conformada por seis&nbsp;colores&nbsp;los cu\u00e1les tienen un&nbsp;significado&nbsp;diferente, de acuerdo con su creador, el artista y activista Gilbert Baker. Antes de que [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-06-17T06:26:00+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg","type":"image\/jpeg"}],"author":"Noticieros Televisa","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Noticieros Televisa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/"},"author":{"name":"Noticieros Televisa","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f030e42657a5a464a8bbd891b1aab6ee"},"headline":"\u00bfQu\u00e9 significa cada color de la bandera LGBT?","datePublished":"2022-06-17T06:26:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/"},"wordCount":350,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg","keywords":["Amor es amor"],"articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/","name":"\u00bfQu\u00e9 significa cada color de la bandera LGBT? - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg","datePublished":"2022-06-17T06:26:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/06\/Que-significa-cada-color-de-la-bandera-LGBT-bandera-de-arcoiris-significado-orgullo-LGBT.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/06\/17\/que-significa-cada-color-de-la-bandera-lgbt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 significa cada color de la bandera LGBT?"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/f030e42657a5a464a8bbd891b1aab6ee","name":"Noticieros Televisa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0e47b9e785a628831b8fd9eaf15e090e106760a879abbd4a3306f128ef5d43a9?s=96&d=mm&r=g","caption":"Noticieros Televisa"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/noticieros-televisa\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/34602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=34602"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/34602\/revisions"}],"predecessor-version":[{"id":34604,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/34602\/revisions\/34604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/34606"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=34602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=34602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=34602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}