{"id":29644,"date":"2022-04-29T11:28:39","date_gmt":"2022-04-29T17:28:39","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=29644"},"modified":"2022-04-29T11:59:08","modified_gmt":"2022-04-29T17:59:08","slug":"aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/","title":{"rendered":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente"},"content":{"rendered":"\n<p><strong><em>Fiscal\u00eda traza ruta de \u00faltimos pasos de Debanhi tras declaraciones de amigas y chofer; en carpeta del caso se se\u00f1ala que pudo haber ca\u00eddo a cisterna<\/em><\/strong><\/p>\n\n\n\n<p>Monterrey.\u2014 Aunque la Fiscal\u00eda General de Justicia de Nuevo Le\u00f3n investiga el caso de Debanhi Escobar como un feminicidio, los datos que ha presentado hasta ahora apuntan a que buscan llegar a la conclusi\u00f3n de que la joven fue responsable de su muerte al supuestamente encontrarse \u201cen estado de ebriedad\u201d y caer dentro de una cisterna.<\/p>\n\n\n\n<p>EL UNIVERSAL tuvo acceso a datos de la carpeta de investigaci\u00f3n de la fiscal\u00eda, entre los que destacan las declaraciones de las dos mujeres que acompa\u00f1aban a Debanhi la noche del 8 de abril pasado, quienes dijeron que acudieron a tres reuniones previas a la de la Quinta El Diamante, donde la joven se separ\u00f3 del grupo.<\/p>\n\n\n\n<p>A partir de ello, la fiscal\u00eda traz\u00f3 una ruta sobre los \u00faltimos pasos de Debanhi, la cual se acompa\u00f1a de videos de c\u00e1maras de seguridad y gr\u00e1ficos de lo que pudo ocurrir esa noche, cuyos datos apuntan a afirmar que la joven estaba alcoholizada y cay\u00f3, por accidente, a la cisterna donde fue encontrada 13 d\u00edas despu\u00e9s de su desaparici\u00f3n. La fiscal\u00eda ha informado que aunque todo parece indicar que la joven cay\u00f3 a la cisterna, no se ha cerrado ninguna l\u00ednea de investigaci\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La declaraci\u00f3n de las amigas<\/strong><\/h2>\n\n\n\n<p>Seg\u00fan las declaraciones de Sarah\u00ed \u201cN\u201d e Ivonne \u201cN\u201d, despu\u00e9s de pasar a una tienda de conveniencia a comprar bebidas, ellas y Debanhi acudieron a una reuni\u00f3n en un domicilio ubicado en la calle Sim\u00f3n Bol\u00edvar en el centro de San Nicol\u00e1s, a la que llegaron alrededor de las 23:30 horas, donde participaron en juegos en los que consumieron alcohol.<\/p>\n\n\n\n<p>Sin embargo, decidieron salir del lugar a otra fiesta cerca de donde se encontraban, pero cuando llegaron ya no les abrieron la puerta, por ello decidieron solicitar un taxi a trav\u00e9s de la plataforma DiDi, que asign\u00f3 al chofer Juan David \u201cN\u201d, quien lleg\u00f3 por las chicas a las 0:49 horas y en 10 minutos las llev\u00f3 a una quinta ubicada en V\u00eda Numancia.<\/p>\n\n\n\n<p>Ivonne y Sarah\u00ed declararon que al llegar, a la 1:00 horas del 9 de abril, vieron que la fiesta hab\u00eda terminado y decidieron buscar otro lugar d\u00f3nde continuar la noche, fue as\u00ed como llegaron a la Quinta El Diamante, donde se unieron a otro grupo de j\u00f3venes que tambi\u00e9n iba llegando. A la 1:30 horas, el festejado, cuyo nombre no ha sido revelado, permiti\u00f3 que las j\u00f3venes se unieran a la juerga, pese a que no las conoc\u00eda.<\/p>\n\n\n\n<p>Aproximadamente a las 2:45 horas, seg\u00fan los videos de c\u00e1maras de vigilancia en poder de la fiscal\u00eda, Debanhi sali\u00f3 corriendo de la quinta y atr\u00e1s de ella lleg\u00f3 otro joven que intent\u00f3 detenerla, pero ella lo evadi\u00f3 e incluso le lanz\u00f3 un golpe. Luego lleg\u00f3 otro grupo de j\u00f3venes a tratar de intervenir. Tanto las mujeres que iban con ella como otros invitados a la fiesta declararon ante la fiscal\u00eda que, durante la discusi\u00f3n, la joven llevaba una botella de vodka y estaba en \u201cestado inconveniente\u201d, no permit\u00eda que se acercaran a ayudarla e incluso se qued\u00f3 dormida por unos 15 minutos, raz\u00f3n por la cual Sarah\u00ed e Ivonne decidieron pedir un taxi para llevarla a su casa.<\/p>\n\n\n\n<p>\u201cDeciden enviarla a su casa porque no pueden controlarla y tranquilizarla por el estado de ebriedad en el que se encontraba\u201d, refiri\u00f3 una de las declarantes. Fue as\u00ed como Juan David \u201cN\u201d, quien las llev\u00f3 al lugar, regres\u00f3 entre las 03:29 y las 3:36 horas, pues afirma que cuando las dej\u00f3 inicialmente en la Quinta Diamante les dio su n\u00famero celular por si necesitaban servicio de regreso m\u00e1s tarde.<\/p>\n\n\n\n<p>Sarah\u00ed e Ivonne le pidieron llevar s\u00f3lo a Debanhi a su casa, pero, seg\u00fan la declaraci\u00f3n del chofer, la joven se comport\u00f3 de manera agresiva y le dijo que quer\u00eda regresar a la fiesta.<\/p>\n\n\n\n<p>A las 4:25 horas, una hora despu\u00e9s de que Debanhi subi\u00f3 al auto, la joven descendi\u00f3 del mismo y fue ah\u00ed cuando Juan David \u201cN\u201d decidi\u00f3 tomarle la foto que se viraliz\u00f3 en redes sociales, mientras permanec\u00eda en la carretera Monterrey-Nuevo Laredo.<\/p>\n\n\n\n<p>Seg\u00fan los videos de vigilancia, Debanhi camin\u00f3 por el camell\u00f3n y posteriormente cruz\u00f3 la carretera a la altura de Alcosa, empresa de transportes de carga, pero no ingres\u00f3 al inmueble. Este lugar se encuentra a dos cuadras de la quinta a donde la joven hab\u00eda acudido a la fiesta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Nuevos videos<\/strong><\/h2>\n\n\n\n<p>Ayer, en conferencia de prensa, la fiscal\u00eda estatal dio a conocer im\u00e1genes de las c\u00e1maras de seguridad del Motel Nueva Castilla, en las cuales se distingue a alguien que, aseguran, es Debanhi, quien entra corriendo al inmueble pese a que supuestamente nadie la ven\u00eda persiguiendo.<\/p>\n\n\n\n<p>\u201cPermanece al menos 20 minutos en un rinc\u00f3n del jard\u00edn del restaurante, en esos 23 minutos registrados, no se observa a ninguna persona busc\u00e1ndola o sigui\u00e9ndola\u201d, insisti\u00f3 la fiscal\u00eda.<\/p>\n\n\n\n<p>En el jard\u00edn al que se dirigi\u00f3 Debanhi est\u00e1 la cisterna donde fue hallado su cuerpo, misma que estaba en desuso y consta de tres fosas, dos de ellas abiertas.<\/p>\n\n\n\n<p>En la fosa donde se encontr\u00f3 su cuerpo se recuperaron sus tenis; entre las fosas, su bolsa con algunas pertenencias; en la segunda fosa, un encendedor, llaves, su celular, una bolsa peque\u00f1a y un recipiente de pl\u00e1stico.<\/p>\n\n\n\n<p>Seg\u00fan la fiscal\u00eda, el personal del hotel report\u00f3 olores f\u00e9tidos en la zona de la cisterna el 21 de abril, cuando el cuerpo fue hallado.<\/p>\n\n\n\n<p>En la autopsia realizada por las autoridades, al d\u00eda siguiente del hallazgo, se estableci\u00f3 que su cuerpo estaba en fase enfisematosa de putrefacci\u00f3n, es decir, que llevaba de cinco d\u00edas a dos semanas sin vida, y presentaba diversas lesiones de las cuales concluyeron que Debanhi muri\u00f3 de un golpe en la parte frontal de la cabeza. \u201cSe encontraba inflamada la parte frontal de la cabeza y ten\u00eda una coloraci\u00f3n, un moret\u00f3n por as\u00ed llamarlo, en la regi\u00f3n frontal y en ambos p\u00e1rpados\u201d, se\u00f1al\u00f3 el m\u00e9dico forense Omar Le\u00f3n Maldonado, quien realiz\u00f3 la necropsia.<\/p>\n\n\n\n<p>\u201cAl tener un traumatismo craneoencef\u00e1lico y se encontraba en un lugar con poco ox\u00edgeno y sin atenci\u00f3n m\u00e9dica, todo eso agrav\u00f3 su condici\u00f3n y llev\u00f3 al fallecimiento\u201d, precis\u00f3.<\/p>\n\n\n\n<p>La pesquisa sigue abierta, sin conclusiones y bajo la modalidad de feminicidio. El caso ha tenido varias versiones y las deficiencias derivaron en la destituci\u00f3n de dos funcionarios estatales.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.eluniversal.com.mx\/sites\/default\/files\/upload\/u253772\/28abr2022-elsitio.jpg\" alt=\"28abr2022-elsitio.jpg\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Fiscal\u00eda traza ruta de \u00faltimos pasos de Debanhi tras declaraciones de amigas y chofer; en carpeta del caso se se\u00f1ala que pudo haber ca\u00eddo a cisterna Monterrey.\u2014 Aunque la Fiscal\u00eda General de Justicia de Nuevo Le\u00f3n investiga el caso de Debanhi Escobar como un feminicidio, los datos que ha presentado hasta ahora apuntan a que [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":28954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[2630,2474,1576],"class_list":{"0":"post-29644","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales","8":"tag-debanhi-susana-escobar-bazaldua","9":"tag-feminicidio","10":"tag-nuevo-leon-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Fiscal\u00eda traza ruta de \u00faltimos pasos de Debanhi tras declaraciones de amigas y chofer; en carpeta del caso se se\u00f1ala que pudo haber ca\u00eddo a cisterna Monterrey.\u2014 Aunque la Fiscal\u00eda General de Justicia de Nuevo Le\u00f3n investiga el caso de Debanhi Escobar como un feminicidio, los datos que ha presentado hasta ahora apuntan a que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-29T17:28:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-29T17:59:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Universal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Universal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/\"},\"author\":{\"name\":\"El Universal\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/fee3882e65fd0510d292c43a346d35d7\"},\"headline\":\"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente\",\"datePublished\":\"2022-04-29T17:28:39+00:00\",\"dateModified\":\"2022-04-29T17:59:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/\"},\"wordCount\":1139,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/debanhi-susana-escobar-bazaldua-1.jpg\",\"keywords\":[\"Debanhi Susana Escobar Bazald\u00faa\",\"Feminicidio\",\"Nuevo Le\u00f3n\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/\",\"name\":\"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/debanhi-susana-escobar-bazaldua-1.jpg\",\"datePublished\":\"2022-04-29T17:28:39+00:00\",\"dateModified\":\"2022-04-29T17:59:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/debanhi-susana-escobar-bazaldua-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/debanhi-susana-escobar-bazaldua-1.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/04\\\/29\\\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/fee3882e65fd0510d292c43a346d35d7\",\"name\":\"El Universal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g\",\"caption\":\"El Universal\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/el-universal\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/","og_locale":"es_MX","og_type":"article","og_title":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas","og_description":"Fiscal\u00eda traza ruta de \u00faltimos pasos de Debanhi tras declaraciones de amigas y chofer; en carpeta del caso se se\u00f1ala que pudo haber ca\u00eddo a cisterna Monterrey.\u2014 Aunque la Fiscal\u00eda General de Justicia de Nuevo Le\u00f3n investiga el caso de Debanhi Escobar como un feminicidio, los datos que ha presentado hasta ahora apuntan a que [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-04-29T17:28:39+00:00","article_modified_time":"2022-04-29T17:59:08+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg","type":"image\/jpeg"}],"author":"El Universal","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Universal","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/"},"author":{"name":"El Universal","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/fee3882e65fd0510d292c43a346d35d7"},"headline":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente","datePublished":"2022-04-29T17:28:39+00:00","dateModified":"2022-04-29T17:59:08+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/"},"wordCount":1139,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg","keywords":["Debanhi Susana Escobar Bazald\u00faa","Feminicidio","Nuevo Le\u00f3n"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/","name":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg","datePublished":"2022-04-29T17:28:39+00:00","dateModified":"2022-04-29T17:59:08+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/04\/debanhi-susana-escobar-bazaldua-1.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/04\/29\/aunque-indagan-feminicidio-de-debanhi-perfilan-que-fue-accidente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Aunque indagan feminicidio de Debanhi, perfilan que fue accidente"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/fee3882e65fd0510d292c43a346d35d7","name":"El Universal","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1ebc94d82b6c3c081781f73e5b76a0d0c1ac7bf8e57426f18802246eeaa2747c?s=96&d=mm&r=g","caption":"El Universal"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/el-universal\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/29644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=29644"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/29644\/revisions"}],"predecessor-version":[{"id":29645,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/29644\/revisions\/29645"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/28954"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=29644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=29644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=29644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}