{"id":26962,"date":"2022-03-25T01:48:00","date_gmt":"2022-03-25T08:48:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=26962"},"modified":"2022-03-24T23:00:00","modified_gmt":"2022-03-25T06:00:00","slug":"comunidad-lgbt-de-ucrania-teme-ocupacion-rusa","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/","title":{"rendered":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em><br>Miembros de la comunidad en ese pa\u00eds aseguran que pueden ser uno de los principales objetivos de las tropas rusas <\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comunidad LGBT+ ha vivido un gran cambio en los \u00faltimos a\u00f1os en Ucrania, pero todos esos avances podr\u00edan quedar paralizados por la guerra. De hecho, los activistas temen que si Mosc\u00fa llega a ocupar el pa\u00eds, pueden ser ellos uno de los principales objetos de las tropas rusas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el centro de Le\u00f3polis, en el oeste de Ucrania, Tymur Levchuk logr\u00f3 organizar Fulcrum, un refugio en el que se resguardan 13 hombres homosexuales que han huido de diferentes ciudades del pa\u00eds por la violencia de las tropas rusas durante la invasi\u00f3n que inici\u00f3 el pasado 24 de febrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodos los albergues oficiales est\u00e1n gestionados por el ayuntamiento, y s\u00f3lo llegan a mujeres, ni\u00f1os y personas mayores. Pero para los gay, y especialmente para los trans es dif\u00edcil, sobre todo los que tienen a\u00fan el g\u00e9nero en el pasaporte, es muy dif\u00edcil\u201d, afirm\u00f3 Levchuk, quien es director ejecutivo en Fulcrum UA, una de las pocas ONG LGBT+ en Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todos los hombres mayores de 18 a\u00f1os han sido llamados a ir al frente de guerra, lo que supone un gran problema para aquellos que no saben c\u00f3mo luchar o que simplemente no quieren ir a la guerra, indica Anton Levdik, director de Gesti\u00f3n del programa Fulcrum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EN LA LISTA NEGRA<br>D\u00edas antes del inicio del conflicto, Estados Unidos envi\u00f3 un mapa a la ONU advirtiendo que las fuerzas rusas hab\u00edan elaborado una lista de ciudadanos ucranianos para matarlos, algo que fue tachado por Mosc\u00fa como una falsedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los objetivos probables son personas que se oponen a las acciones rusas, entre aquellos disidentes de Rusia y Bielorrusia que viven en Ucrania, as\u00ed como periodistas, activistas anticorrupci\u00f3n y miembros de minor\u00edas \u00e9tnicas y religiosas y de la comunidad LGBT+.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ledvik asegur\u00f3 que m\u00e1s que una simple teor\u00eda, esta lista puede ser cierta, ya que los chechenos, que participan en la guerra con Mosc\u00fa, \u201chan prometido luchar y matar a los miembros de la comunidad LGBT+\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEsto es muy serio y si el r\u00e9gimen de Putin toma Ucrania, tenemos que decir adi\u00f3s a todas las organizaciones LGBT+ y tambi\u00e9n a todos los activistas, uno por uno\u201d, se\u00f1ala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yura Dvizhon, cofundadora de Ukraine Pride, dice que es \u201cseguro\u201d que su n\u00famero est\u00e9 en esta lista, al ser uno de los activistas m\u00e1s conocidos en Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero dice que, al menos en estos momentos, no tiene miedo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesde el inicio de esta guerra, hay diferentes niveles de miedo. Hoy, por ejemplo, no tengo miedo de Rusia y estoy listo para pelear todo lo que pueda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">AVANCES PARALIZADOS<br>Dvizhon afirm\u00f3 que Ucrania \u201cha cambiado mucho en los \u00faltimos cinco a\u00f1os\u201d respecto a la tolerancia a la comunidad LGBT+ y que se ha convertido en el pa\u00eds refugio de todos los homosexuales y trans de los estados que conformaban anteriormente la Uni\u00f3n Sovi\u00e9tica, como Bielorrusia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Justo antes de la guerra, los activistas estaban exigiendo a las autoridades ucranianas que aprobaran el proyecto de ley 5488, que abordaba cuestiones legales relacionadas con los delitos de odio contra la comunidad, pero eso ha quedado paralizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHe visto c\u00f3mo la situaci\u00f3n ha mejorado en el pa\u00eds y es por eso que me ha quedado aqu\u00ed\u201d, asevera Dvizhon, que tiene esperanza de que cuando acabe la guerra, se apruebe la ley antidiscriminaci\u00f3n como un gran paso para la comunidad en este pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Levchuk, desde su organizaci\u00f3n Fulcrum est\u00e1 intentando reunir m\u00e1s financiamiento para abrir un segundo refugio y que el dinero que les llegue tambi\u00e9n sea donado para el Ej\u00e9rcito ucraniano, donde adem\u00e1s hay un grupo de \u201cmilitares LGBT+\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPor supuesto que necesitamos apoyo, m\u00e1s capacidad para m\u00e1s refugios que proporcionen alimentos b\u00e1sicos, pero esta es una acci\u00f3n temporal que no podr\u00eda ayudarnos a largo plazo. Necesitamos apoyo internacional (\u2026) y en primer lugar, para el Ej\u00e9rcito\u201d, afirma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Levdik dice que la comunidad internacional \u201cnecesita escuchar\u201d que es \u201chora de actuar\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTenemos que detener a Putin, cualquier cosa que puedan hacer todos los pa\u00edses que apoyen a Ucrania. Si no empiezan a hacer algo ahora mismo, no s\u00e9 qu\u00e9 pasar\u00e1\u201d, subraya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s derechos para la comunidad<br>Apenas en septiembre pasado unas 7 mil personas participaron en el centro de Kiev en la llamada &#8220;Marcha por la igualdad&#8221; para exigir m\u00e1s derechos para la comunidad LGBT+ en este pa\u00eds, entre ellos el reconocimiento de la uni\u00f3n civil y una lucha m\u00e1s eficaz contra los delitos de odio contra el colectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los activistas ondearon banderas arco\u00edris y pancartas con lemas como &#8220;este es mi pa\u00eds de origen tambi\u00e9n&#8221;, &#8220;juntos por la igualdad de derechos&#8221; o &#8220;yo existo&#8221;, adem\u00e1s de que corearon consignas como &#8220;rebelde, amor, no renuncies a los derechos&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Por un lado, hay m\u00e1s visibilidad (de la comunidad LGBT+ en Ucrania), la gente se vuelve m\u00e1s abierta&#8221;, dijo a la agencia Efe Dzvenyslava Shcherba, representante de Amnist\u00eda Internacional (AI) y activista que encabezaba la marcha.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"768\" height=\"479\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/03-INT-EXTRA-896fbca116e817af1ca482b6db3394243a91502d.jpg\" alt=\"\" class=\"wp-image-26963\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pero &#8220;por otro lado, todav\u00eda existen muchas limitaciones legales: las personas LGBT+ no pueden casarse o adoptar ni\u00f1os y los delitos de odio contra ellos no se investigan&#8221;, recalc\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las principales demandas de los organizadores de la marcha por la igualdad ese a\u00f1o fueron adoptar e implementar leyes sobre delitos de odio, as\u00ed como las que permiten las uniones civiles de parejas LGBT+ en Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Hay parejas que conviven desde hace 15, 20 a\u00f1os, que cr\u00edan hijos, pero el Estado no las reconoce como familias&#8221;, explic\u00f3 Olena Shevchenko, coordinadora de &#8220;Orgullo Kiev&#8221; y directora de la ONG Insight, que opera en diez ciudades ucranianas, donde promueve los derechos de las mujeres y del colectivo LGBT+, y donde brinda asistencia legal y psicol\u00f3gica a estas personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Existe una gran brecha entre la sociedad, que se est\u00e1 volviendo m\u00e1s tolerante y tolerante con las personas LGBT+ y los pol\u00edticos, que todav\u00eda creen que Ucrania es un pa\u00eds muy conservador&#8221;, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">VETERANOS DE GUERRA LGBT+ POR LA IGUALDAD<br>En el orgullo gay en Kiev se encontraban ONG ucranianas e internacionales de derechos humanos, organizaciones de padres de ni\u00f1os LGBT+ que enfrentan acoso escolar y una comunidad de veteranos de guerra que crea conciencia sobre los derechos de los homosexuales en el Ej\u00e9rcito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viktor Pylypenko, uno de los primeros veteranos de la guerra en el Donb\u00e1s que declar\u00f3 abiertamente que era gay despu\u00e9s de dejar el Ej\u00e9rcito en 2018, visti\u00f3 su uniforme militar con condecoraciones. Pylypenko es cofundador de la ONG &#8220;Soldados LGBT ucranianos por la igualdad de derechos&#8221;, que cuenta con 120 miembros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Estoy aqu\u00ed porque quiero igualdad de derechos, en particular el derecho a casarme y tener una familia&#8221;\u2026 Me golpearon hace dos a\u00f1os despu\u00e9s de declararme gay y conozco a muchos soldados que son discriminados por su orientaci\u00f3n sexual&#8221;, dijo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"768\" height=\"479\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/2021-09-19T110055Z_1822496441_MT1SIPA000OIW5OK_RTRMADP_3_SIPA-USA.jpg\" alt=\"\" class=\"wp-image-26964\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para Shcherba esta era su cuarta marcha LBGT+ y se sent\u00eda m\u00e1s seguro que los anteriores. A principios de a\u00f1o se llevaron a cabo dos marchas del orgullo gay en las ciudades de J\u00e1rkov y Odesa. Hubo peque\u00f1os enfrentamientos entre la polic\u00eda y los grupos de extrema derecha en Odesa, que terminaron en arrestos, pero no se reportaron ataques a activistas LGBT.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para garantizar la seguridad de la marcha, hubo en Kiev una fuerte presencia policial. Varias estaciones de metro se cerraron al p\u00fablico y se emplearon detectores de metal en los puntos de acceso al acto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Todos los participantes del Orgullo recibieron una larga lista con medidas de seguridad antes del acto. Hay mucha polic\u00eda, vallas met\u00e1licas. Esto est\u00e1 mal y por eso estamos aqu\u00ed, porque queremos ser aceptados&#8221;, recalc\u00f3 Shcherba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez finalizada la marcha, la polic\u00eda escolt\u00f3 a los activistas hasta una de las estaciones de metro en las afueras de Kiev, para evitar posibles ataques de grupos religiosos y de extrema derecha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miembros de la comunidad en ese pa\u00eds aseguran que pueden ser uno de los principales objetivos de las tropas rusas La comunidad LGBT+ ha vivido un gran cambio en los \u00faltimos a\u00f1os en Ucrania, pero todos esos avances podr\u00edan quedar paralizados por la guerra. De hecho, los activistas temen que si Mosc\u00fa llega a ocupar [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":26972,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-26962","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Miembros de la comunidad en ese pa\u00eds aseguran que pueden ser uno de los principales objetivos de las tropas rusas La comunidad LGBT+ ha vivido un gran cambio en los \u00faltimos a\u00f1os en Ucrania, pero todos esos avances podr\u00edan quedar paralizados por la guerra. De hecho, los activistas temen que si Mosc\u00fa llega a ocupar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-25T08:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"479\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Sol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Sol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/\"},\"author\":{\"name\":\"El Sol\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/e42cf8194648cef93ec04777ab0c2929\"},\"headline\":\"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa\",\"datePublished\":\"2022-03-25T08:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/\"},\"wordCount\":1375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/\",\"name\":\"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg\",\"datePublished\":\"2022-03-25T08:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg\",\"width\":768,\"height\":479},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/03\\\/25\\\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/e42cf8194648cef93ec04777ab0c2929\",\"name\":\"El Sol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"caption\":\"El Sol\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/elsol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/","og_locale":"es_MX","og_type":"article","og_title":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas","og_description":"Miembros de la comunidad en ese pa\u00eds aseguran que pueden ser uno de los principales objetivos de las tropas rusas La comunidad LGBT+ ha vivido un gran cambio en los \u00faltimos a\u00f1os en Ucrania, pero todos esos avances podr\u00edan quedar paralizados por la guerra. De hecho, los activistas temen que si Mosc\u00fa llega a ocupar [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-03-25T08:48:00+00:00","og_image":[{"width":768,"height":479,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg","type":"image\/jpeg"}],"author":"El Sol","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Sol","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/"},"author":{"name":"El Sol","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/e42cf8194648cef93ec04777ab0c2929"},"headline":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa","datePublished":"2022-03-25T08:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/"},"wordCount":1375,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/","name":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg","datePublished":"2022-03-25T08:48:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/03\/01-PORTADA-428c75791e413d2cae749359115d559ae606ee2a.jpg","width":768,"height":479},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/03\/25\/comunidad-lgbt-de-ucrania-teme-ocupacion-rusa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Comunidad LGBT+ de Ucrania teme ocupaci\u00f3n rusa"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/e42cf8194648cef93ec04777ab0c2929","name":"El Sol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","caption":"El Sol"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/elsol\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=26962"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26962\/revisions"}],"predecessor-version":[{"id":26965,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/26962\/revisions\/26965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/26972"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=26962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=26962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=26962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}