{"id":2653,"date":"2021-05-21T05:24:15","date_gmt":"2021-05-21T12:24:15","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=2653"},"modified":"2021-05-21T05:24:17","modified_gmt":"2021-05-21T12:24:17","slug":"joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/","title":{"rendered":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Estados Unidos respald\u00f3 a Israel para defenderse de los grupos terroristas<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- El presidente de Estados Unidos, Joe Biden, confirm\u00f3 que despu\u00e9s de hablar con el primer ministro israel\u00ed, Benjamin Netanyahu, Israel hab\u00eda acordado un &#8220;alto el fuego mutuo e incondicional&#8221;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que Estados Unidos respald\u00f3 a Israel para defenderse de los grupos terroristas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que su administraci\u00f3n ayudar\u00eda a garantizar que el sistema de c\u00fapula de hierro se reponga para el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oficina del primer ministro israel\u00ed, Benjamin Netanyahu, dijo que su gabinete de seguridad hab\u00eda votado un\u00e1nimemente a favor de una tregua &#8220;mutua e incondicional&#8221; en Gaza propuesta por Egipto, pero agreg\u00f3 que la hora de implementaci\u00f3n a\u00fan no se hab\u00eda acordado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hamas y Egipto dijeron que la tregua comenzar\u00eda a las 2 am, despu\u00e9s de 11 d\u00edas de hostilidades israelo-palestinas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de una creciente alarma mundial por el derramamiento de sangre, Biden hab\u00eda instado a Netanyahu a buscar la reducci\u00f3n de la escalada, mientras que Egipto, Qatar y las Naciones Unidas buscaban mediar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al extender sus condolencias a los desconsolados israel\u00edes y palestinos, Biden dijo que Washington trabajar\u00e1 con las Naciones Unidas &#8220;y otras partes interesadas internacionales para brindar asistencia humanitaria r\u00e1pida&#8221; para la reconstrucci\u00f3n de la Gaza controlada por Hamas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estados Unidos respald\u00f3 a Israel para defenderse de los grupos terroristas Ciudad de M\u00e9xico.- El presidente de Estados Unidos, Joe Biden, confirm\u00f3 que despu\u00e9s de hablar con el primer ministro israel\u00ed, Benjamin Netanyahu, Israel hab\u00eda acordado un &#8220;alto el fuego mutuo e incondicional&#8221; A\u00f1adi\u00f3 que Estados Unidos respald\u00f3 a Israel para defenderse de los grupos [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":2654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[413,360,491,368,90],"class_list":["post-2653","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales","tag-franja-de-gaza","tag-gaza","tag-hamas","tag-israel","tag-joe-biden"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos respald\u00f3 a Israel para defenderse de los grupos terroristas Ciudad de M\u00e9xico.- El presidente de Estados Unidos, Joe Biden, confirm\u00f3 que despu\u00e9s de hablar con el primer ministro israel\u00ed, Benjamin Netanyahu, Israel hab\u00eda acordado un &#8220;alto el fuego mutuo e incondicional&#8221; A\u00f1adi\u00f3 que Estados Unidos respald\u00f3 a Israel para defenderse de los grupos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-21T12:24:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-21T12:24:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"980\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Vanguardia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Vanguardia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/\"},\"author\":{\"name\":\"Vanguardia\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\"},\"headline\":\"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor\",\"datePublished\":\"2021-05-21T12:24:15+00:00\",\"dateModified\":\"2021-05-21T12:24:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/\"},\"wordCount\":243,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/biden_34.jpg\",\"keywords\":[\"Franja de Gaza\",\"Gaza\",\"Hamas\",\"Israel\",\"Joe Biden\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/\",\"name\":\"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/biden_34.jpg\",\"datePublished\":\"2021-05-21T12:24:15+00:00\",\"dateModified\":\"2021-05-21T12:24:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/biden_34.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/biden_34.jpg\",\"width\":980,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/05\\\/21\\\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/bce747fb6a0b0feefab1e3e7c4e84d2b\",\"name\":\"Vanguardia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g\",\"caption\":\"Vanguardia\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/vanguardia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/","og_locale":"es_MX","og_type":"article","og_title":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas","og_description":"Estados Unidos respald\u00f3 a Israel para defenderse de los grupos terroristas Ciudad de M\u00e9xico.- El presidente de Estados Unidos, Joe Biden, confirm\u00f3 que despu\u00e9s de hablar con el primer ministro israel\u00ed, Benjamin Netanyahu, Israel hab\u00eda acordado un &#8220;alto el fuego mutuo e incondicional&#8221; A\u00f1adi\u00f3 que Estados Unidos respald\u00f3 a Israel para defenderse de los grupos [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-05-21T12:24:15+00:00","article_modified_time":"2021-05-21T12:24:17+00:00","og_image":[{"width":980,"height":655,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg","type":"image\/jpeg"}],"author":"Vanguardia","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Vanguardia","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/"},"author":{"name":"Vanguardia","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b"},"headline":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor","datePublished":"2021-05-21T12:24:15+00:00","dateModified":"2021-05-21T12:24:17+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/"},"wordCount":243,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg","keywords":["Franja de Gaza","Gaza","Hamas","Israel","Joe Biden"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/","name":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg","datePublished":"2021-05-21T12:24:15+00:00","dateModified":"2021-05-21T12:24:17+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/05\/biden_34.jpg","width":980,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/05\/21\/joe-biden-confirma-el-alto-al-fuego-entre-israel-y-hamas-que-ya-entro-en-vigor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Joe Biden confirma el alto al fuego entre Israel y Hamas, que ya entr\u00f3 en vigor"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/bce747fb6a0b0feefab1e3e7c4e84d2b","name":"Vanguardia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d7e1e0fdcdef594fdfc9206070adafb95cd5cd9b47c113cb987d91ee74e35df?s=96&d=mm&r=g","caption":"Vanguardia"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/vanguardia\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2653","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2653"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2653\/revisions"}],"predecessor-version":[{"id":2655,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/2653\/revisions\/2655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/2654"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}