{"id":22892,"date":"2022-01-29T09:33:01","date_gmt":"2022-01-29T16:33:01","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=22892"},"modified":"2022-01-29T09:33:02","modified_gmt":"2022-01-29T16:33:02","slug":"mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/","title":{"rendered":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Al menos 3 mil 400 vuelos nacionales e internacionales fueron cancelados en las \u00faltimas horas debido a un temporal que golpear\u00e1 la costa este del pa\u00eds, principalmente a Nueva York.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos.- Miles de vuelos en Estados Unidos fueron cancelados este s\u00e1bado ante la llegada de una potente tormenta de nieve y fuertes viento que golpear\u00e1 la Costa Este del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El fen\u00f3meno ser\u00e1 particularmente intenso en el noreste y afectar\u00e1 a Nueva York y Boston para luego seguir su curso por el Atl\u00e1ntico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1quinas de sal y quitanieves estaban listos para ser movilizados en Nueva York, cuyo alcalde Eric Adams tuite\u00f3 que esperaban unos 30 cent\u00edmetros de nieve, aunque &#8220;la Madre Naturaleza tiene tendencia a hacer lo que quiere&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unos 3 mil 400 vuelos, tanto internos como internacionales, fueron suspendidos para el s\u00e1bado en Estados Unidos, seg\u00fan el rastreador de vuelos FlightAware.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes, las cancelaciones llegaron a m\u00e1s de mil 450.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Servicio Meteorol\u00f3gico Nacional alert\u00f3 de &#8220;condiciones de baja visibilidad&#8221; que har\u00edan &#8220;casi imposible de viajar&#8221; en amplias partes de la costa noreste de Estados Unidos, con acumulaciones de nieve superiores a los 30 cent\u00edmetros en partes de esa regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8220;Cicl\u00f3n bomba&#8221;<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los gobernadores de Nueva York y Nueva Jersey declararon el estado de emergencia y la alcaldesa de Boston, Michelle Wu, decret\u00f3 emergencia por nieve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tormenta provocar\u00e1 temperaturas extremadamente fr\u00edas con rachas de viento peligrosas entre el s\u00e1bado por la noche y el domingo por la ma\u00f1ana, indic\u00f3 el servicio meteorol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Vuelvan a casa esta noche con cuidado, qu\u00e9dense en casa durante el fin de semana, eviten cualquier viaje innecesario&#8221;, recomend\u00f3 la gobernadora de Nueva York, Kathy Hochul, en un comunicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Advirti\u00f3 de nevadas especialmente fuertes en Long Island, la ciudad de Nueva York y la zona baja del valle del Hudson.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El servicio meteorol\u00f3gico de la regi\u00f3n indic\u00f3 que la tormenta se intensificar\u00eda r\u00e1pidamente en las siguientes 24 horas y que la presi\u00f3n pod\u00eda caer a 35 milibares el s\u00e1bado por la noche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta r\u00e1pida intensificaci\u00f3n a veces se conoce como &#8220;cicl\u00f3n bomba&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta borrasca llega despu\u00e9s de otra tormenta invernal similar que emblanqueci\u00f3 hace dos semanas gran parte del este de Norteam\u00e9rica, desde Georgia hasta Canad\u00e1, dejando muchos hogares sin luz y perturbando miles de conexiones a\u00e9reas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos 3 mil 400 vuelos nacionales e internacionales fueron cancelados en las \u00faltimas horas debido a un temporal que golpear\u00e1 la costa este del pa\u00eds, principalmente a Nueva York. Estados Unidos.- Miles de vuelos en Estados Unidos fueron cancelados este s\u00e1bado ante la llegada de una potente tormenta de nieve y fuertes viento que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":22893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-22892","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Al menos 3 mil 400 vuelos nacionales e internacionales fueron cancelados en las \u00faltimas horas debido a un temporal que golpear\u00e1 la costa este del pa\u00eds, principalmente a Nueva York. Estados Unidos.- Miles de vuelos en Estados Unidos fueron cancelados este s\u00e1bado ante la llegada de una potente tormenta de nieve y fuertes viento que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T16:33:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T16:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exc\u00e9lsior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exc\u00e9lsior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/\"},\"author\":{\"name\":\"Exc\u00e9lsior\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\"},\"headline\":\"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal\",\"datePublished\":\"2022-01-29T16:33:01+00:00\",\"dateModified\":\"2022-01-29T16:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/\"},\"wordCount\":410,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/NIEVE_LIMPIA.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/\",\"name\":\"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/NIEVE_LIMPIA.jpg\",\"datePublished\":\"2022-01-29T16:33:01+00:00\",\"dateModified\":\"2022-01-29T16:33:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/NIEVE_LIMPIA.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/NIEVE_LIMPIA.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/29\\\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\",\"name\":\"Exc\u00e9lsior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"caption\":\"Exc\u00e9lsior\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/excelsior\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/","og_locale":"es_MX","og_type":"article","og_title":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas","og_description":"Al menos 3 mil 400 vuelos nacionales e internacionales fueron cancelados en las \u00faltimas horas debido a un temporal que golpear\u00e1 la costa este del pa\u00eds, principalmente a Nueva York. Estados Unidos.- Miles de vuelos en Estados Unidos fueron cancelados este s\u00e1bado ante la llegada de una potente tormenta de nieve y fuertes viento que [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-01-29T16:33:01+00:00","article_modified_time":"2022-01-29T16:33:02+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg","type":"image\/jpeg"}],"author":"Exc\u00e9lsior","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Exc\u00e9lsior","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/"},"author":{"name":"Exc\u00e9lsior","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780"},"headline":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal","datePublished":"2022-01-29T16:33:01+00:00","dateModified":"2022-01-29T16:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/"},"wordCount":410,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/","name":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg","datePublished":"2022-01-29T16:33:01+00:00","dateModified":"2022-01-29T16:33:02+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/NIEVE_LIMPIA.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/29\/mas-de-3-mil-vuelos-cancelados-en-eu-por-tormenta-invernal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s de 3 mil vuelos cancelados en EU por tormenta invernal"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780","name":"Exc\u00e9lsior","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","caption":"Exc\u00e9lsior"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/excelsior\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=22892"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22892\/revisions"}],"predecessor-version":[{"id":22894,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22892\/revisions\/22894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/22893"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=22892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=22892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=22892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}