{"id":22254,"date":"2022-01-20T10:41:44","date_gmt":"2022-01-20T17:41:44","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=22254"},"modified":"2022-01-20T10:41:45","modified_gmt":"2022-01-20T17:41:45","slug":"acusa-lopez-obrador-abusos-y-derroche-en-el-ine","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/","title":{"rendered":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Reiter\u00f3 propuesta para que en el instituto se aplique plan de austeridad; destac\u00f3 que en el Gobierno ha habido importantes ahorros; gana menos que consejeros<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador acus\u00f3 que en el INE hay un derroche econ\u00f3mico y muestra de ello son los beneficios que reciben los consejeros, as\u00ed como los salarios de \u00e9stos, los cuales superan al del mismo mandatario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia en Palacio Nacional, el titular del Ejecutivo federal critic\u00f3 que dentro del instituto electoral no haya \u201cconsciencia\u201d de la austeridad, pues, como ha dicho en otras ocasiones, hay<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;S\u00f3lo pueden ganar m\u00e1s que el presidente quienes llevan a cabo funciones espec\u00edficas, como el cuerpo diplom\u00e1tico y otros casos, pero en lo del INE son abusos, excesos, derroche, porque ellos no tienen consciencia de lo que es la austeridad\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe mencionar que mientras L\u00f3pez Obrador percibe un salario mensual neto de 112 mil 122 pesos de acuerdo con el\u00a0Presupuesto de Egresos de la Federaci\u00f3n para el Ejercicio Fiscal 2022; sin embargo, el INE precisa en su portal web que su consejero presidente, Lorenzo C\u00f3rdova,\u00a0percibe un salario mensual neto de 179 mil 52.20 pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior, incluso que el art\u00edculo 9 de la Ley Federal de Remuneraciones de los Servidores P\u00fablicos establece que ning\u00fan servidor deber\u00e1 ganar m\u00e1s que el presidente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador lament\u00f3 que el instituto electoral no quiera aplicar un plan de austeridad como lo ha hecho el Gobierno y el cual s\u00ed ha dado resultados desde 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que, por ejemplo, mientras en 2018, \u00faltimo a\u00f1o de la administraci\u00f3n de Enrique Pe\u00f1a Nieto, se autorizaron mil 797 millones 418 mil 247 pesos, el monto ejercido fue de 3 mil 682 millones 52 mil 375.06 pesos, lo que represent\u00f3 un subejercicio de 105 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En comparaci\u00f3n con eso, el presidente detall\u00f3 que, por ejemplo, en 2020 se autorizaron 805 millones 24 mil 292 pesos, aunque el monto ejercido fue 523 millones 883 mil 35.89 pesos, lo que represent\u00f3 un ahorro de 43 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;S\u00ed hay forma de ahorrar y el ejemplo se est\u00e1 dando en nuestro gobierno, entonces cuando se les hizo la propuesta de austeridad es pedirles que aplicaran lo mismo que nosotros hacemos, porque tienen servicio m\u00e9dico particular y aqu\u00ed no hay, y es un ahorro importante, porque se abusa de eso, me consta que en los anteriores gobiernos se hac\u00edan hasta cirug\u00edas pl\u00e1sticas con cargo al erario por ese servicio m\u00e9dico privado. Entonces eso es un abuso, es injusto\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reiter\u00f3 que con una pol\u00edtica de austeridad es posible obtener ahorros para transferirlos a la ciudadan\u00eda, no como suced\u00eda en gobiernos anteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que el pasado 13 de enero el Gobierno federal present\u00f3 \u201cde manera respetuosa\u201d al INE un plan de austeridad para que pueda ahorrar 2 mil 972 millones de pesos para\u00a0garantizar la revocaci\u00f3n de mandato, lo que significa incluso mil 234 millones de pesos m\u00e1s de lo que solicita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con las autoridades federales, el INE podr\u00eda obtener los recursos necesarios mediante la aplicaci\u00f3n de este plan de austeridad en los siguientes rubros:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/cdn2.excelsior.com.mx\/media\/inside-the-note\/pictures\/2022\/01\/20\/a94193b5-137f-4027-a16a-bdadfef9ea9f1.gif\" alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Reiter\u00f3 propuesta para que en el instituto se aplique plan de austeridad; destac\u00f3 que en el Gobierno ha habido importantes ahorros; gana menos que consejeros Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador acus\u00f3 que en el INE hay un derroche econ\u00f3mico y muestra de ello son los beneficios que reciben los consejeros, as\u00ed [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":22255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[247,297,264,263,1582],"class_list":["post-22254","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales","tag-amlo","tag-andres-manuel-lopez-obrador","tag-ine","tag-instituto-nacional-electoral","tag-revocacion-de-mandato"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Reiter\u00f3 propuesta para que en el instituto se aplique plan de austeridad; destac\u00f3 que en el Gobierno ha habido importantes ahorros; gana menos que consejeros Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador acus\u00f3 que en el INE hay un derroche econ\u00f3mico y muestra de ello son los beneficios que reciben los consejeros, as\u00ed [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-20T17:41:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-20T17:41:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Exc\u00e9lsior\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Exc\u00e9lsior\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/\"},\"author\":{\"name\":\"Exc\u00e9lsior\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\"},\"headline\":\"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE\",\"datePublished\":\"2022-01-20T17:41:44+00:00\",\"dateModified\":\"2022-01-20T17:41:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/AMLO_2001.jpg\",\"keywords\":[\"AMLO\",\"Andr\u00e9s Manuel L\u00f3pez Obrador\",\"INE\",\"Instituto Nacional Electoral\",\"Revocaci\u00f3n de mandato\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/\",\"name\":\"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/AMLO_2001.jpg\",\"datePublished\":\"2022-01-20T17:41:44+00:00\",\"dateModified\":\"2022-01-20T17:41:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/AMLO_2001.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/AMLO_2001.jpg\",\"width\":800,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2022\\\/01\\\/20\\\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/ec4edd1fbf5efa3e44fce34fe2787780\",\"name\":\"Exc\u00e9lsior\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g\",\"caption\":\"Exc\u00e9lsior\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/excelsior\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/","og_locale":"es_MX","og_type":"article","og_title":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas","og_description":"Reiter\u00f3 propuesta para que en el instituto se aplique plan de austeridad; destac\u00f3 que en el Gobierno ha habido importantes ahorros; gana menos que consejeros Ciudad de M\u00e9xico.- El presidente Andr\u00e9s Manuel L\u00f3pez Obrador acus\u00f3 que en el INE hay un derroche econ\u00f3mico y muestra de ello son los beneficios que reciben los consejeros, as\u00ed [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2022-01-20T17:41:44+00:00","article_modified_time":"2022-01-20T17:41:45+00:00","og_image":[{"width":800,"height":600,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg","type":"image\/jpeg"}],"author":"Exc\u00e9lsior","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Exc\u00e9lsior","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/"},"author":{"name":"Exc\u00e9lsior","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780"},"headline":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE","datePublished":"2022-01-20T17:41:44+00:00","dateModified":"2022-01-20T17:41:45+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg","keywords":["AMLO","Andr\u00e9s Manuel L\u00f3pez Obrador","INE","Instituto Nacional Electoral","Revocaci\u00f3n de mandato"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/","name":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg","datePublished":"2022-01-20T17:41:44+00:00","dateModified":"2022-01-20T17:41:45+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2022\/01\/AMLO_2001.jpg","width":800,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2022\/01\/20\/acusa-lopez-obrador-abusos-y-derroche-en-el-ine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Acusa L\u00f3pez Obrador \u2018abusos\u2019 y \u2018derroche\u2019 en el INE"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/ec4edd1fbf5efa3e44fce34fe2787780","name":"Exc\u00e9lsior","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b7ee9206b48be08447852b3f0814dbc7c0f3b51541b164f1464a2725614020b?s=96&d=mm&r=g","caption":"Exc\u00e9lsior"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/excelsior\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=22254"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22254\/revisions"}],"predecessor-version":[{"id":22256,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/22254\/revisions\/22256"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/22255"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=22254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=22254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=22254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}