{"id":20489,"date":"2021-12-24T07:04:22","date_gmt":"2021-12-24T14:04:22","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=20489"},"modified":"2021-12-24T07:04:23","modified_gmt":"2021-12-24T14:04:23","slug":"crean-la-primera-criptomoneda-lgbt-maricoin","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/","title":{"rendered":"Crean la primera Criptomoneda LGBT: Maricoin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Esta moneda virtual se usar\u00e1 para pagar en establecimientos &#8220;de ambiente&#8221;.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Espa\u00f1a.- En la actualidad las criptomonedas comienzan a ganarse un lugar en el mercado, y comienzan a ser m\u00e1s aceptadas como un m\u00e9todo alternativo de pago y alejado de los medios tradicionales como el dinero f\u00edsico, o las tarjetas de cr\u00e9dito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sum\u00e1ndose a este tendencia en Espa\u00f1a surgi\u00f3 Maricoin, la primera criptomoneda pensada como una forma de apoyo para la comunidad LGTB y los negocios que est\u00e1n relacionados con este colectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pensada en apoyo a la comunidad LGBTI+<\/strong><br>El creador de esta nueva criptomoneda fue Juan Belmonte, una reconocida figura de la comunidad gay en Espa\u00f1a, a quien se le ocurri\u00f3 este proyecto como una forma de apoyar la econom\u00eda y al colectivo que apoya la diversidad sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un video publicado en Youtube, Belmonte explica:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNuestra propia moneda nos va a unificar, nos va a dar poder en este mundo globalizado capitalista. Podremos ayudar a otras personas que en este momento no tienen los mismos derechos que nosotros\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De momento, Maricoin es aceptada en 25 establecimientos ubicados en ciudades espa\u00f1olas como Madrid o Barcelona, pero se espera que en un futuro pr\u00f3ximo se expanda a otros sitios.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Maricoin Pitch by Juan por Dios\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/FBpnJ8_bWTI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 es una criptomoneda?<\/strong><br>Como su nombre lo indica son monedas, pero a diferencia de las que estamos acostumbrados a utilizar todos los d\u00edas, est\u00e1n son digitales y no est\u00e1n \u201ccentralizadas\u201d como el dinero cotidiano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A lo que nos referimos cuando decimos que no est\u00e1n centralizadas es que no est\u00e1n regidas por una instituci\u00f3n o un servicio, como lo ser\u00eda un banco o el gobierno de un pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfEntonces, como adquieren su valor? Existen un grupo de ordenadores \u201cdescentralizados\u201d que se encargan de revisar las transacciones que se realizan y dar validez de las mismas. En este sentido, una criptomoneda solo es valida para las personas que le dan valor a la misma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Nota de MVS Noticias<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta moneda virtual se usar\u00e1 para pagar en establecimientos &#8220;de ambiente&#8221;. Espa\u00f1a.- En la actualidad las criptomonedas comienzan a ganarse un lugar en el mercado, y comienzan a ser m\u00e1s aceptadas como un m\u00e9todo alternativo de pago y alejado de los medios tradicionales como el dinero f\u00edsico, o las tarjetas de cr\u00e9dito. Sum\u00e1ndose a este [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-20489","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Esta moneda virtual se usar\u00e1 para pagar en establecimientos &#8220;de ambiente&#8221;. Espa\u00f1a.- En la actualidad las criptomonedas comienzan a ganarse un lugar en el mercado, y comienzan a ser m\u00e1s aceptadas como un m\u00e9todo alternativo de pago y alejado de los medios tradicionales como el dinero f\u00edsico, o las tarjetas de cr\u00e9dito. Sum\u00e1ndose a este [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-24T14:04:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-24T14:04:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"415\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Crean la primera Criptomoneda LGBT: Maricoin\",\"datePublished\":\"2021-12-24T14:04:22+00:00\",\"dateModified\":\"2021-12-24T14:04:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/\"},\"wordCount\":350,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MARICOIN.jpeg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/\",\"name\":\"Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MARICOIN.jpeg\",\"datePublished\":\"2021-12-24T14:04:22+00:00\",\"dateModified\":\"2021-12-24T14:04:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MARICOIN.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/MARICOIN.jpeg\",\"width\":739,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/24\\\/crean-la-primera-criptomoneda-lgbt-maricoin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Crean la primera Criptomoneda LGBT: Maricoin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/","og_locale":"es_MX","og_type":"article","og_title":"Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas","og_description":"Esta moneda virtual se usar\u00e1 para pagar en establecimientos &#8220;de ambiente&#8221;. Espa\u00f1a.- En la actualidad las criptomonedas comienzan a ganarse un lugar en el mercado, y comienzan a ser m\u00e1s aceptadas como un m\u00e9todo alternativo de pago y alejado de los medios tradicionales como el dinero f\u00edsico, o las tarjetas de cr\u00e9dito. Sum\u00e1ndose a este [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-12-24T14:04:22+00:00","article_modified_time":"2021-12-24T14:04:23+00:00","og_image":[{"width":739,"height":415,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Crean la primera Criptomoneda LGBT: Maricoin","datePublished":"2021-12-24T14:04:22+00:00","dateModified":"2021-12-24T14:04:23+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/"},"wordCount":350,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/","name":"Crean la primera Criptomoneda LGBT: Maricoin - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg","datePublished":"2021-12-24T14:04:22+00:00","dateModified":"2021-12-24T14:04:23+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/MARICOIN.jpeg","width":739,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/24\/crean-la-primera-criptomoneda-lgbt-maricoin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Crean la primera Criptomoneda LGBT: Maricoin"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/20489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=20489"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/20489\/revisions"}],"predecessor-version":[{"id":20491,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/20489\/revisions\/20491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/20490"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=20489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=20489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=20489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}