{"id":19714,"date":"2021-12-13T07:27:04","date_gmt":"2021-12-13T14:27:04","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=19714"},"modified":"2021-12-13T07:27:05","modified_gmt":"2021-12-13T14:27:05","slug":"en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/","title":{"rendered":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya"},"content":{"rendered":"\n<p><strong><em>Ricardo Anaya critic\u00f3 la gesti\u00f3n de AMLO en salud, seguridad y econom\u00eda, y consider\u00f3 que lo peor es que el presidente a dividido a los mexicanos.<\/em><\/strong><\/p>\n\n\n\n<p>Ciudad de M\u00e9xico.- Morena tiene que irse en 2024, hay que reconstruir el pa\u00eds y encaminarlo a una visi\u00f3n del futuro, apunt\u00f3 este lunes el excandidato presidencial Ricardo Anaya.<\/p>\n\n\n\n<p>\u201cQuiz\u00e1 lo m\u00e1s grave que ha hecho L\u00f3pez Obrador es dividirnos, ponernos a unos contra otros, cuando lo que M\u00e9xico necesita es que todos sumemos, que trabajemos juntos. En 2024 Morena se tiene que ir, as\u00ed podemos reconstruir nuestro pa\u00eds, y lo vamos a regresar al lugar que se merece: atraeremos inversi\u00f3n, generaremos empleos y prosperidad, invertiremos en educaci\u00f3n y salud\u201d, dijo en su video semanal.<\/p>\n\n\n\n<p>En esta ocasi\u00f3n, el panista hizo una cr\u00edtica a la administraci\u00f3n del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, asegurando que ha hecho barbaridades y que la ciudadan\u00eda ya se est\u00e1 acostumbrando a eso. Y se\u00f1al\u00f3 tres temas: salud, inseguridad y corrupci\u00f3n.<\/p>\n\n\n\n<p>Anaya record\u00f3 que el a\u00f1o pasado el subsecretario de Salud, Hugo L\u00f3pez-Gatell, declar\u00f3 que en un escenario catastr\u00f3fico morir\u00edan 60 mil personas por COVID-19. Sin embargo, la cifra se rebas\u00f3 y van m\u00e1s de 600 mil personas fallecidas. Adem\u00e1s, dijo, el presidente elimin\u00f3 el Seguro Popular, lo cual ha afectado a miles de personas.<\/p>\n\n\n\n<p>\u201cLuego el grav\u00edsimo problema de la inseguridad. Nada m\u00e1s acu\u00e9rdate, se burl\u00f3 y minimiz\u00f3 el problema de los asesinatos. Insisti\u00f3 en tratar bien a los delincuentes. O sea, persigue opositores y a los delincuentes los felicita, porque seg\u00fan \u00e9l se portan bien (\u2026) Las consecuencias de tantos errores son tr\u00e1gicas: ya van m\u00e1s de 100 mil asesinatos\u201d, declar\u00f3.<\/p>\n\n\n\n<p>En cuanto a la corrupci\u00f3n, Anaya record\u00f3 la frase del presidente sobre que barrer\u00eda este problema como a las escaleras: de arriba para abajo. \u201c Y seg\u00fan \u00e9l ya no hay corrupci\u00f3n arriba. \u00bfC\u00f3mo que ya no hay corrupci\u00f3n arriba? \u00bfY sus hermanos recibiendo dinero en efectivo, los contratos de su prima, las casas de Bartlett y de Irma Er\u00e9ndira?\u201d.<\/p>\n\n\n\n<p>El panista tambi\u00e9n se\u00f1al\u00f3 que la econom\u00eda \u201cest\u00e1 fuera de control\u201d, pues varios art\u00edculos est\u00e1n subiendo de precio, y la gasolina est\u00e1 a m\u00e1s de 20 pesos por litro.<\/p>\n\n\n\n<p>Ricardo Anaya destac\u00f3 que M\u00e9xico debe ser insertado en el mundo que viene, con una visi\u00f3n de futuro, para construir un gobierno \u201cque hable menos y haga m\u00e1s\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">Dif\u00edcil de creer la cantidad de torpezas, enga\u00f1os y promesas incumplidas que acumula L\u00f3pez Obrador. En 2024 Morena se tiene que ir. \u00a1S\u00ed hay de otra! <a href=\"https:\/\/t.co\/mRMIvGug1k\">pic.twitter.com\/mRMIvGug1k<\/a><\/p>&mdash; RicardoAnayaC (@RicardoAnayaC) <a href=\"https:\/\/twitter.com\/RicardoAnayaC\/status\/1470377973471612930?ref_src=twsrc%5Etfw\">December 13, 2021<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ricardo Anaya critic\u00f3 la gesti\u00f3n de AMLO en salud, seguridad y econom\u00eda, y consider\u00f3 que lo peor es que el presidente a dividido a los mexicanos. Ciudad de M\u00e9xico.- Morena tiene que irse en 2024, hay que reconstruir el pa\u00eds y encaminarlo a una visi\u00f3n del futuro, apunt\u00f3 este lunes el excandidato presidencial Ricardo Anaya. [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":19715,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[247,297,1322,45,719],"class_list":{"0":"post-19714","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias-nacionales","8":"tag-amlo","9":"tag-andres-manuel-lopez-obrador","10":"tag-elecciones-2024","11":"tag-morena","12":"tag-ricardo-anaya"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Ricardo Anaya critic\u00f3 la gesti\u00f3n de AMLO en salud, seguridad y econom\u00eda, y consider\u00f3 que lo peor es que el presidente a dividido a los mexicanos. Ciudad de M\u00e9xico.- Morena tiene que irse en 2024, hay que reconstruir el pa\u00eds y encaminarlo a una visi\u00f3n del futuro, apunt\u00f3 este lunes el excandidato presidencial Ricardo Anaya. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-13T14:27:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-13T14:27:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Financiero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Financiero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/\"},\"author\":{\"name\":\"El Financiero\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/494f7e0dce8dfaaec5b64f16615b78e9\"},\"headline\":\"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya\",\"datePublished\":\"2021-12-13T14:27:04+00:00\",\"dateModified\":\"2021-12-13T14:27:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/\"},\"wordCount\":446,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/R_ANAYA.jpg\",\"keywords\":[\"AMLO\",\"Andr\u00e9s Manuel L\u00f3pez Obrador\",\"Elecciones 2024\",\"morena\",\"Ricardo Anaya\"],\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/\",\"name\":\"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/R_ANAYA.jpg\",\"datePublished\":\"2021-12-13T14:27:04+00:00\",\"dateModified\":\"2021-12-13T14:27:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/R_ANAYA.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/R_ANAYA.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/12\\\/13\\\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/494f7e0dce8dfaaec5b64f16615b78e9\",\"name\":\"El Financiero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g\",\"caption\":\"El Financiero\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/financiero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/","og_locale":"es_MX","og_type":"article","og_title":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas","og_description":"Ricardo Anaya critic\u00f3 la gesti\u00f3n de AMLO en salud, seguridad y econom\u00eda, y consider\u00f3 que lo peor es que el presidente a dividido a los mexicanos. Ciudad de M\u00e9xico.- Morena tiene que irse en 2024, hay que reconstruir el pa\u00eds y encaminarlo a una visi\u00f3n del futuro, apunt\u00f3 este lunes el excandidato presidencial Ricardo Anaya. [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-12-13T14:27:04+00:00","article_modified_time":"2021-12-13T14:27:05+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg","type":"image\/jpeg"}],"author":"El Financiero","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Financiero","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/"},"author":{"name":"El Financiero","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/494f7e0dce8dfaaec5b64f16615b78e9"},"headline":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya","datePublished":"2021-12-13T14:27:04+00:00","dateModified":"2021-12-13T14:27:05+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/"},"wordCount":446,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg","keywords":["AMLO","Andr\u00e9s Manuel L\u00f3pez Obrador","Elecciones 2024","morena","Ricardo Anaya"],"articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/","name":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg","datePublished":"2021-12-13T14:27:04+00:00","dateModified":"2021-12-13T14:27:05+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/12\/R_ANAYA.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/12\/13\/en-2024-morena-se-tiene-que-ir-reconstruiremos-mexico-ricardo-anaya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"En 2024 Morena se tiene que ir, reconstruiremos M\u00e9xico: Ricardo Anaya"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/494f7e0dce8dfaaec5b64f16615b78e9","name":"El Financiero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/88c0f3f2079389318ef8dd35c22cb997212aa89646e357ba59b318db26ed91a9?s=96&d=mm&r=g","caption":"El Financiero"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/financiero\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19714"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19714\/revisions"}],"predecessor-version":[{"id":19716,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/19714\/revisions\/19716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/19715"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}