{"id":18638,"date":"2021-11-29T13:29:52","date_gmt":"2021-11-29T20:29:52","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=18638"},"modified":"2021-11-29T13:33:02","modified_gmt":"2021-11-29T20:33:02","slug":"registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/","title":{"rendered":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>En Sinaloa, el 100% de los homicidios culposos son por accidentes de tr\u00e1nsito, mientras que a nivel nacional son el 80%<\/em><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Culiac\u00e1n, Sin.- Durante octubre Sinaloa registr\u00f3 el n\u00famero m\u00e1s alto de muertes por accidentes viales en lo que va del a\u00f1o y se perfila para cerrar el 2021 con cifra r\u00e9cord en este delito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Diagn\u00f3stico Mensual Octubre 2021, elaborado por la Coordinaci\u00f3n General del Consejo Estatal de Seguridad P\u00fablica (CESP), muestra que en octubre se registraron 77 homicidios culposos, conocidos tambi\u00e9n como imprudenciales, mientras que en el periodo enero-octubre de 2021 se contabilizaron 584 muertes de este tipo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Sinaloa, el 100% de los homicidios culposos son por accidentes de tr\u00e1nsito, mientras que a nivel nacional son el 80%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al hist\u00f3rico anual, la cifra m\u00e1s alta registrada es del 2011 con 672 casos. De no implementarse en el corto plazo&nbsp;campa\u00f1as efectivas de concientizaci\u00f3n vial, prevenci\u00f3n y aplicaci\u00f3n de los reglamentos viales sin distingos, influyentismos ni corrupci\u00f3n, se&nbsp;cerrar\u00eda el 2021 con un aproximado de 700 muertes por accidentes, por lo que pasar\u00eda a ser la cifra m\u00e1s alta de la que se tenga registro en este delito en Sinaloa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso, la cifra de homicidios culposos en la entidad ha crecido al grado de superar a los homicidios dolosos, es decir los asesinatos, que en octubre fueron 48 y en total en el a\u00f1o suman 515 casos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos son algunos de los datos contenidos en el Diagn\u00f3stico Mensual Octubre 2021 de este observatorio ciudadano, donde se incluyen en total 13 delitos, as\u00ed como indicadores del Sistema de Justicia Penal Acusatorio, estado de fuerza policial y delitos cometidos con armas de fuego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Consulta el diagn\u00f3stico aqu\u00ed:&nbsp;<a href=\"http:\/\/coordinaciongeneralcesp.org.mx\/diagnosticos-mensuales\/%20\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/coordinaciongeneralcesp.org.mx\/diagnosticos-mensuales\/<\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-1024x1024.jpg\" alt=\"\" class=\"wp-image-18640\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-1024x1024.jpg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-300x300.jpg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-150x150.jpg 150w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-768x767.jpg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-696x695.jpg 696w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-1068x1067.jpg 1068w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-420x420.jpg 420w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021-70x70.jpg 70w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Muertes-por-accidentes-en-Sinaloa-2021.jpg 1201w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-1024x1024.jpg\" alt=\"\" class=\"wp-image-18639\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-1024x1024.jpg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-300x300.jpg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-150x150.jpg 150w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-768x768.jpg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-696x696.jpg 696w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-1068x1068.jpg 1068w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-420x420.jpg 420w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa-70x70.jpg 70w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/Historico-de-muertes-por-accidentes-viales-en-Sinaloa.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En Sinaloa, el 100% de los homicidios culposos son por accidentes de tr\u00e1nsito, mientras que a nivel nacional son el 80%. Culiac\u00e1n, Sin.- Durante octubre Sinaloa registr\u00f3 el n\u00famero m\u00e1s alto de muertes por accidentes viales en lo que va del a\u00f1o y se perfila para cerrar el 2021 con cifra r\u00e9cord en este delito. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[2209,632,2210,49],"class_list":["post-18638","post","type-post","status-publish","format-standard","has-post-thumbnail","category-nota-principal","tag-accidentes-viales","tag-coordinacion-general-del-consejo-estatal-de-seguridad-publica","tag-muertes","tag-sinaloa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"En Sinaloa, el 100% de los homicidios culposos son por accidentes de tr\u00e1nsito, mientras que a nivel nacional son el 80%. Culiac\u00e1n, Sin.- Durante octubre Sinaloa registr\u00f3 el n\u00famero m\u00e1s alto de muertes por accidentes viales en lo que va del a\u00f1o y se perfila para cerrar el 2021 con cifra r\u00e9cord en este delito. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T20:29:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-29T20:33:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"840\" \/>\n\t<meta property=\"og:image:height\" content=\"473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP\",\"datePublished\":\"2021-11-29T20:29:52+00:00\",\"dateModified\":\"2021-11-29T20:33:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/\"},\"wordCount\":306,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/accidente-sahagun4_1-focus-0-0-840-473.jpg\",\"keywords\":[\"Accidentes viales\",\"Coordinaci\u00f3n General del Consejo Estatal de Seguridad P\u00fablica\",\"Muertes\",\"sinaloa\"],\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/\",\"name\":\"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/accidente-sahagun4_1-focus-0-0-840-473.jpg\",\"datePublished\":\"2021-11-29T20:29:52+00:00\",\"dateModified\":\"2021-11-29T20:33:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/accidente-sahagun4_1-focus-0-0-840-473.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/accidente-sahagun4_1-focus-0-0-840-473.jpg\",\"width\":840,\"height\":473},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/29\\\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/","og_locale":"es_MX","og_type":"article","og_title":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas","og_description":"En Sinaloa, el 100% de los homicidios culposos son por accidentes de tr\u00e1nsito, mientras que a nivel nacional son el 80%. Culiac\u00e1n, Sin.- Durante octubre Sinaloa registr\u00f3 el n\u00famero m\u00e1s alto de muertes por accidentes viales en lo que va del a\u00f1o y se perfila para cerrar el 2021 con cifra r\u00e9cord en este delito. [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-11-29T20:29:52+00:00","article_modified_time":"2021-11-29T20:33:02+00:00","og_image":[{"width":840,"height":473,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP","datePublished":"2021-11-29T20:29:52+00:00","dateModified":"2021-11-29T20:33:02+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/"},"wordCount":306,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg","keywords":["Accidentes viales","Coordinaci\u00f3n General del Consejo Estatal de Seguridad P\u00fablica","Muertes","sinaloa"],"articleSection":["NOTA PRINCIPAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/","name":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg","datePublished":"2021-11-29T20:29:52+00:00","dateModified":"2021-11-29T20:33:02+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/accidente-sahagun4_1-focus-0-0-840-473.jpg","width":840,"height":473},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/29\/registra-sinaloa-cifra-record-de-muertes-por-accidentes-viales-cesp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Registra Sinaloa cifra r\u00e9cord de muertes por accidentes viales: CESP"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=18638"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18638\/revisions"}],"predecessor-version":[{"id":18643,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/18638\/revisions\/18643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/18641"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=18638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=18638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=18638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}