{"id":17218,"date":"2021-11-11T12:21:09","date_gmt":"2021-11-11T19:21:09","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=17218"},"modified":"2021-11-11T17:05:40","modified_gmt":"2021-11-12T00:05:40","slug":"recorre-rocha-moya-oficinas-de-palacio-de-gobierno","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/","title":{"rendered":"Recorre Rocha Moya oficinas de Palacio de Gobierno"},"content":{"rendered":"\n<p><em><strong>El gobernador del estado visit\u00f3 de improviso varias dependencias estatales, donde salud\u00f3 a los trabajadores y les dijo que est\u00e1 a sus \u00f3rdenes<\/strong><\/em><\/p>\n\n\n\n<p>Culiac\u00e1n, Sin. \u2013 No daban todav\u00eda las 10 de la ma\u00f1ana cuando cientos de trabajadores de Palacio de Gobierno quedaron gratamente sorprendidos al ver entrar a sus oficinas al gobernador Rub\u00e9n Rocha Moya, quien dedic\u00f3 gran parte de la ma\u00f1ana de este jueves para recorrer varias dependencias, con el prop\u00f3sito de saludar personalmente a los que llam\u00f3 en reiteradas veces sus \u201ccompa\u00f1eros de trabajo\u201d.<\/p>\n\n\n\n<p>De buen \u00e1nimo, sonriente, incluso haciendo bromas y chascarrillos, el mandatario estatal inici\u00f3 con su recorrido por el s\u00f3tano de Palacio de Gobierno, pues precis\u00f3 que quer\u00eda empezar con los de abajo, que es el personal que no ve la luz del sol durante toda su jornada laboral. \u201cQuiero estar atento a los trabajadores de abajo\u201d, recalc\u00f3.<\/p>\n\n\n\n<p>La primera oficina que visit\u00f3 fue el SATES, tomando por sorpresa a los trabajadores e incluso al propio titular, Oscar Luis L\u00f3pez Barraza, quien lo recibi\u00f3 gustoso y lo acompa\u00f1\u00f3 por entre los escritorios, y el gobernador salud\u00f3 de mano a todos los empleados y les preguntaba su nombre, cu\u00e1l era su funci\u00f3n y cu\u00e1ntos a\u00f1os ten\u00edan trabajando, e incluso se top\u00f3 con bastantes caras conocidas.<\/p>\n\n\n\n<p>\u201cNo ando en campa\u00f1a ni tampoco ando buscando votos, ahora soy su compa\u00f1ero de trabajo, y por azares del destino soy gobernador, pero quiero que sepan que estoy a sus \u00f3rdenes, estar\u00e9 atento de ustedes, y si los trata mal su jefe me dicen\u201d, brome\u00f3 el mandatario estatal.<\/p>\n\n\n\n<p>Al tiempo de saludarlos de mano a cada uno y hasta tomarse \u201cselfies\u201d, Rocha Moya les reconoci\u00f3 la labor que hacen diariamente, pues dijo que \u00e9l como gobernador se apoyar\u00e1 en ese mismo trabajo, y precis\u00f3 que no hay trabajo peque\u00f1o, sino que el quehacer de todos en lo individual alimenta la maquinaria y los engranes de la administraci\u00f3n p\u00fablica, que ahora a \u00e9l le toca encabezar.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0013-1024x682.jpg\" alt=\"\" class=\"wp-image-17219\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0013-1024x682.jpg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0013-300x200.jpg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0013-768x511.jpg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0013.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En su recorrido el gobernador entraba por una puerta y sal\u00eda por otra, conociendo todos los vericuetos del s\u00f3tano de Palacio de Gobierno, y durante su visita a la oficina del Archivo de Personal de Recursos Humanos, el delegado sindical, que se identific\u00f3 como Camilo, le hizo una petici\u00f3n especial, pues le explic\u00f3 que en el \u00e1rea donde laboran no existen extractores de aire, ya que no hay manera de sacar los ductos por ning\u00fan lado debido a que est\u00e1n rodeados de oficinas, lo que representa un peligro para su salud ya que su trabajo consiste en digitalizar los viejos archivos de papel, en muchos casos muy antiguos que datan de m\u00e1s de 30 a\u00f1os, algunos da\u00f1ados por polilla, y al abrirlos despiden diversas part\u00edculas que quedan flotando en aire en su oficina, sin posibilidad de salida.<\/p>\n\n\n\n<p>Al escuchar este argumento, el rostro del gobernador Rub\u00e9n Rocha Moya, que en todo momento era risue\u00f1o, cambi\u00f3 para tornarse serio y preocupado. Les dijo a los trabajadores que ante la imposibilidad de colocar extractores de aire, se buscar\u00e1 la reubicaci\u00f3n de todo este personal a un \u00e1rea donde puedan laborar sin menoscabo alguno de su salud.<\/p>\n\n\n\n<p>El anuncio arranc\u00f3 hasta aplausos en los trabajadores, la mayor\u00eda mujeres, quienes le externaron su agradecimiento, pues era algo que siempre hab\u00edan solicitado en las pasadas administraciones.<\/p>\n\n\n\n<p>Rocha Moya tambi\u00e9n visit\u00f3 las oficinas del Servicio Nacional del Empleo, donde igualmente se present\u00f3 ante todos los trabajadores, los salud\u00f3 de mano, les pregunt\u00f3 su nombre, y les reiter\u00f3 que lo vean como un compa\u00f1ero de trabajo m\u00e1s.<\/p>\n\n\n\n<p>De igual manera aprovech\u00f3 para hacerle una indicaci\u00f3n a su director, Juan Uliv Guerra Medina, de que todo el trabajo del Servicio Nacional del Empleo debe hacerse con perspectiva de g\u00e9nero, que favorezca a las mujeres. \u201cQuiero que tengamos muchos empleos para las mujeres\u201d, fue la encomienda.<\/p>\n\n\n\n<p>As\u00ed fue como el gobernador del estado se mezcl\u00f3 entre los trabajadores del S\u00f3tano de Palacio de Gobierno, aqu\u00e9llos que no ven la luz del sol, los de abajo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0014-1024x682.jpg\" alt=\"\" class=\"wp-image-17220\" srcset=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0014-1024x682.jpg 1024w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0014-300x200.jpg 300w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0014-768x511.jpg 768w, https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0014.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Nos call\u00f3 la boca\u201d comentaron entre s\u00ed dos trabajadoras del s\u00f3tano de Palacio de Gobierno, cuando el gobernador Rub\u00e9n Rocha Moya continu\u00f3 su recorrido que inici\u00f3 durante la ma\u00f1ana para saludar a sus \u201ccompa\u00f1eros de trabajo\u201d, el cual tuvo que interrumpir un par de horas para atender una cita en su despacho, pero con la promesa que \u201cal ratito\u201d regresar\u00eda.<\/p>\n\n\n\n<p>Por eso, cuando despu\u00e9s de la una de la tarde regres\u00f3 el gobernador para continuar con su recorrido por las dependencias que le falt\u00f3 visitar por la ma\u00f1ana, el asombro de las dos mujeres fue notorio, pues horas antes hab\u00edan comentado con incredulidad: \u201cQu\u00e9 va regresar, ahorita se mete a su oficina y ya no regresa, \u00a1pero mira amiga, nos call\u00f3 la boca!\u201d.<\/p>\n\n\n\n<p>Como ocurri\u00f3 durante la ma\u00f1ana, el traj\u00edn habitual, casi silencioso, del s\u00f3tano de Palacio de Gobierno de nuevo se revolote\u00f3, cuando Rocha Moya cumpli\u00f3 su palabra y regres\u00f3 empezando la tarde, para conocer y platicar con sus nuevos \u201ccompa\u00f1eros de trabajo\u201d, pues en cada una de las oficinas les reiter\u00f3 lo dicho durante su primer recorrido, que es uno de ellos.<\/p>\n\n\n\n<p>Con las visitas a la Subsecretar\u00eda de Desarrollo Administrativo, Secretar\u00eda T\u00e9cnica de la Secretar\u00eda de Turismo, Bodega de Servicios Generales, Almac\u00e9n y Control de Inventarios, Procuradur\u00eda Fiscal, Subsecretar\u00eda de Auditor\u00eda, Archivo General de Notar\u00edas, Unidad de Coordinaci\u00f3n con Entidades P\u00fablicas, y la Direcci\u00f3n de Financiamiento de la Secretar\u00eda de Salud, ya no le qued\u00f3 ninguna dependencia por visitar en el s\u00f3tano de Palacio de Gobierno.<\/p>\n\n\n\n<p>Incluso, el gobernador Rub\u00e9n Rocha Moya visit\u00f3 un punto en particular que a toda hora hay gente, y que es referente en Palacio. Se trata del puesto de los famosos \u201cChapitos\u201d, dos hermanos de capacidades diferentes que durante a\u00f1os se ganan la vida en la Unidad Administrativa, primero sacando copias y luego ampliando su negocio con venta de refrescos, pan, galletas, dulces, papas con chile, y hasta cevichurros, cualquier cosa que sirva para apaciguar el hambre de los trabajadores hasta que llega la hora de salida.<\/p>\n\n\n\n<p>\u201cPrimera vez que nos visita un gobernador\u201d, rieron entre s\u00ed los Chapitos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/WhatsApp-Image-2021-11-11-at-3.42.08-PM-1024x682.jpeg\" alt=\"\" class=\"wp-image-17249\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador del estado visit\u00f3 de improviso varias dependencias estatales, donde salud\u00f3 a los trabajadores y les dijo que est\u00e1 a sus \u00f3rdenes Culiac\u00e1n, Sin. \u2013 No daban todav\u00eda las 10 de la ma\u00f1ana cuando cientos de trabajadores de Palacio de Gobierno quedaron gratamente sorprendidos al ver entrar a sus oficinas al gobernador Rub\u00e9n Rocha [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":17221,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[37],"tags":[],"class_list":{"0":"post-17218","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nota-principal"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El gobernador del estado visit\u00f3 de improviso varias dependencias estatales, donde salud\u00f3 a los trabajadores y les dijo que est\u00e1 a sus \u00f3rdenes Culiac\u00e1n, Sin. \u2013 No daban todav\u00eda las 10 de la ma\u00f1ana cuando cientos de trabajadores de Palacio de Gobierno quedaron gratamente sorprendidos al ver entrar a sus oficinas al gobernador Rub\u00e9n Rocha [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-11T19:21:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-12T00:05:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\"},\"headline\":\"Recorre Rocha Moya oficinas de Palacio de Gobierno\",\"datePublished\":\"2021-11-11T19:21:09+00:00\",\"dateModified\":\"2021-11-12T00:05:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/\"},\"wordCount\":1082,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211111-WA0007.jpg\",\"articleSection\":[\"NOTA PRINCIPAL\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/\",\"name\":\"Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211111-WA0007.jpg\",\"datePublished\":\"2021-11-11T19:21:09+00:00\",\"dateModified\":\"2021-11-12T00:05:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211111-WA0007.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/IMG-20211111-WA0007.jpg\",\"width\":1280,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/11\\\/11\\\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Recorre Rocha Moya oficinas de Palacio de Gobierno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/331be9283d37198e2acd5750279085b0\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/","og_locale":"es_MX","og_type":"article","og_title":"Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas","og_description":"El gobernador del estado visit\u00f3 de improviso varias dependencias estatales, donde salud\u00f3 a los trabajadores y les dijo que est\u00e1 a sus \u00f3rdenes Culiac\u00e1n, Sin. \u2013 No daban todav\u00eda las 10 de la ma\u00f1ana cuando cientos de trabajadores de Palacio de Gobierno quedaron gratamente sorprendidos al ver entrar a sus oficinas al gobernador Rub\u00e9n Rocha [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-11-11T19:21:09+00:00","article_modified_time":"2021-11-12T00:05:40+00:00","og_image":[{"width":1280,"height":852,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg","type":"image\/jpeg"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0"},"headline":"Recorre Rocha Moya oficinas de Palacio de Gobierno","datePublished":"2021-11-11T19:21:09+00:00","dateModified":"2021-11-12T00:05:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/"},"wordCount":1082,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg","articleSection":["NOTA PRINCIPAL"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/","name":"Recorre Rocha Moya oficinas de Palacio de Gobierno - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg","datePublished":"2021-11-11T19:21:09+00:00","dateModified":"2021-11-12T00:05:40+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/11\/IMG-20211111-WA0007.jpg","width":1280,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/11\/11\/recorre-rocha-moya-oficinas-de-palacio-de-gobierno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Recorre Rocha Moya oficinas de Palacio de Gobierno"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/331be9283d37198e2acd5750279085b0","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f6d8782c11d12b2d4ad3fbb6931aeab5309937a4d6cd2fc9cfaa28a6396a5aec?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=17218"}],"version-history":[{"count":2,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17218\/revisions"}],"predecessor-version":[{"id":17251,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/17218\/revisions\/17251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/17221"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=17218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=17218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=17218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}