{"id":15905,"date":"2021-10-26T06:03:58","date_gmt":"2021-10-26T13:03:58","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=15905"},"modified":"2021-10-26T06:04:40","modified_gmt":"2021-10-26T13:04:40","slug":"estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/","title":{"rendered":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d"},"content":{"rendered":"\n<p>El estadio mexicano La Corregidora, de la ciudad de Quer\u00e9taro, se precia de ser el primer escenario de f\u00fatbol en el mundo con un espacio \u201camigable con las mascotas\u201d.<\/p>\n\n\n\n<p>En el \u00e1rea de plateas, situado en la parte baja de la estructura, el Quer\u00e9taro acondicion\u00f3 un espacio con 16 lugares para aficionados que asistieron con sus perros para ver el partido del torneo Apertura que los Gallos Blancos ganaron por 2-1 al Monterrey.<\/p>\n\n\n\n<p>En la zona se establecieron cristales que reducen el ruido para tranquilidad de las mascotas.<\/p>\n\n\n\n<p>Cada palco fue equipado con \u2018boxes\u2019, cuyo cupo es de hasta cuatro personas y dos mascotas de tama\u00f1o mediano. El \u00e1rea \u2018pet friendly\u2019 cuenta con corrales de descanso para mantener resguardados a los animales mientras los due\u00f1os realizan compras o van al ba\u00f1o.<\/p>\n\n\n\n<p>El acondicionamiento del espacio se dio por la empresa Mars Petcare M\u00e9xico, que estar\u00e1 a cargo del lugar, que adem\u00e1s contar\u00e1 con personal especializado y preparado para recibir a las mascotas.<\/p>\n\n\n\n<p>El gerente de asuntos corporativos de Mars Pet Nutrition M\u00e9xico, Rom\u00e1n Delgado, detall\u00f3 que el espacio cuenta tambi\u00e9n con dos zonas de descanso y de ba\u00f1o para los perros.<\/p>\n\n\n\n<p>Los trabajadores de la compa\u00f1\u00eda dan la bienvenida a las mascotas desde el momento de su arribo en veh\u00edculo, en un \u00e1rea de estacionamiento especial, para despu\u00e9s acompa\u00f1arlos hasta su lugar, en la platea sur.<\/p>\n\n\n\n<p>Los peludos que asistan a un juego en La Corregidora deber\u00e1n cumplir con ciertos requerimientos, entre ellos, contar con todas sus vacunas, ir acompa\u00f1ados de un adulto y pasar una prueba de conducta.<\/p>\n\n\n\n<p>La afici\u00f3n de los Gallos ha tenido una respuesta favorable a esta din\u00e1mica, asegur\u00f3 el director comercial y de mercadotecnia del Quer\u00e9taro, Sergio L\u00f3pez Vital, quien resalt\u00f3 que desde el anuncio los hinchas adquirieron los boletos para asistir al f\u00fatbol con sus mascotas.<\/p>\n\n\n\n<p>Aficionados consultados por Efe celebraron la experiencia de poder asistir a un partido de f\u00fatbol con el acompa\u00f1amiento de sus mascotas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estadio mexicano La Corregidora, de la ciudad de Quer\u00e9taro, se precia de ser el primer escenario de f\u00fatbol en el mundo con un espacio \u201camigable con las mascotas\u201d. En el \u00e1rea de plateas, situado en la parte baja de la estructura, el Quer\u00e9taro acondicion\u00f3 un espacio con 16 lugares para aficionados que asistieron con [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":15906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[32,36],"tags":[],"class_list":{"0":"post-15905","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-derechos-animales","8":"category-semanales"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El estadio mexicano La Corregidora, de la ciudad de Quer\u00e9taro, se precia de ser el primer escenario de f\u00fatbol en el mundo con un espacio \u201camigable con las mascotas\u201d. En el \u00e1rea de plateas, situado en la parte baja de la estructura, el Quer\u00e9taro acondicion\u00f3 un espacio con 16 lugares para aficionados que asistieron con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-26T13:03:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-26T13:04:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"EFE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"EFE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/\"},\"author\":{\"name\":\"EFE\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/0d44615087b5a626d5d3f13afe31ac41\"},\"headline\":\"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d\",\"datePublished\":\"2021-10-26T13:03:58+00:00\",\"dateModified\":\"2021-10-26T13:04:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/\"},\"wordCount\":359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga.jpg\",\"articleSection\":[\"DERECHOS ANIMALES\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/\",\"name\":\"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga.jpg\",\"datePublished\":\"2021-10-26T13:03:58+00:00\",\"dateModified\":\"2021-10-26T13:04:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/descarga.jpg\",\"width\":768,\"height\":506},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2021\\\/10\\\/26\\\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/0d44615087b5a626d5d3f13afe31ac41\",\"name\":\"EFE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g\",\"caption\":\"EFE\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/efe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/","og_locale":"es_MX","og_type":"article","og_title":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas","og_description":"El estadio mexicano La Corregidora, de la ciudad de Quer\u00e9taro, se precia de ser el primer escenario de f\u00fatbol en el mundo con un espacio \u201camigable con las mascotas\u201d. En el \u00e1rea de plateas, situado en la parte baja de la estructura, el Quer\u00e9taro acondicion\u00f3 un espacio con 16 lugares para aficionados que asistieron con [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2021-10-26T13:03:58+00:00","article_modified_time":"2021-10-26T13:04:40+00:00","og_image":[{"width":768,"height":506,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg","type":"image\/jpeg"}],"author":"EFE","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"EFE","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/"},"author":{"name":"EFE","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/0d44615087b5a626d5d3f13afe31ac41"},"headline":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d","datePublished":"2021-10-26T13:03:58+00:00","dateModified":"2021-10-26T13:04:40+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg","articleSection":["DERECHOS ANIMALES","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/","name":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg","datePublished":"2021-10-26T13:03:58+00:00","dateModified":"2021-10-26T13:04:40+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/10\/descarga.jpg","width":768,"height":506},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2021\/10\/26\/estadio-mexicano-primero-en-el-mundo-con-espacio-amigable-con-las-mascotas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Estadio mexicano, primero en el mundo con espacio \u201camigable con las mascotas\u201d"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/0d44615087b5a626d5d3f13afe31ac41","name":"EFE","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7048c2d9b569d9bed55bb53ad23821e6e047aa66338fb6ea9868627bbb9f54e8?s=96&d=mm&r=g","caption":"EFE"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/efe\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=15905"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15905\/revisions"}],"predecessor-version":[{"id":15907,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/15905\/revisions\/15907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/15906"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=15905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=15905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=15905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}