{"id":137958,"date":"2026-07-17T03:20:00","date_gmt":"2026-07-17T10:20:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=137958"},"modified":"2026-07-16T15:27:35","modified_gmt":"2026-07-16T22:27:35","slug":"comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/","title":{"rendered":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La comunidad LGBTQ+ busca acciones que obliguen a los partidos pol\u00edticos a postular personas de este nicho a puestos de elecci\u00f3n popular, y para lograrlo, entregaron al Instituto Electoral y de Participaci\u00f3n Ciudadana del Estado de Guerrero (IEPC) un planteamiento de diez puntos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alberto Serna Mogoll\u00f3n, presidente de la asociaci\u00f3n&nbsp;de&nbsp;homosexuales&nbsp;y de&nbsp;lesbianas&nbsp;del Estado de Guerrero A. C., entre los puntos a considerar del planteamiento est\u00e1 que&nbsp;<strong>haya candidaturas para activistas con al menos tres a\u00f1os de experiencia<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de, colocar en las listas de regidores integren a la acci\u00f3n afirmativa en el n\u00famero 3 de su lista porque en la acci\u00f3n pasada se les coloc\u00f3 en los lugares 7, 8 o m\u00e1s y eso impidi\u00f3 que llegaran a los cabildos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los pocos espacios que la comunidad logr\u00f3 se encuentra una diputaci\u00f3n en la zona centro, sin embargo hasta este d\u00eda la legisladora que la ostenta no ha tenido ninguna iniciativa que busque mejorar las condiciones de vida de las comunidades de la diversidad sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEsperamos que en esta ruta final de su encargo la diputada Citlali se active y presente alguna acci\u00f3n para el sector de la sociedad que representa\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alberto Serna Mogoll\u00f3n adelant\u00f3 que en caso de que el IEPC no responda de forma afirmativa en la aplicaci\u00f3n de la acci\u00f3n afirmativa tendr\u00eda que acudir a la justicia federal para solicitar un amparo, donde ya existe jurisprudencia y podr\u00edan ganarlo f\u00e1cilmente para que se aplique en Guerrero la acci\u00f3n afirmativa en favor de las comunidades de la diversidad Sexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resalt\u00f3 que el Congreso del Estado tuvo su tiempo para legislar sobre la acci\u00f3n afirmativa pero lamentablemente los legisladores no realizaron ninguna reforma a la ley electoral, en cuanto a las acciones afirmativas, por ello es que se tiene que solicitar la aplicaci\u00f3n de la acci\u00f3n afirmativa y escuchar las demandas que emanaron del foro para que los representantes populares que lleguen al cargo por esta acci\u00f3n sean realmente miembros de la comunidad LGBT.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comunidad LGBTQ+ busca acciones que obliguen a los partidos pol\u00edticos a postular personas de este nicho a puestos de elecci\u00f3n popular, y para lograrlo, entregaron al Instituto Electoral y de Participaci\u00f3n Ciudadana del Estado de Guerrero (IEPC) un planteamiento de diez puntos. Alberto Serna Mogoll\u00f3n, presidente de la asociaci\u00f3n&nbsp;de&nbsp;homosexuales&nbsp;y de&nbsp;lesbianas&nbsp;del Estado de Guerrero A. [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":80759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[35,36],"tags":[],"class_list":["post-137958","post","type-post","status-publish","format-standard","has-post-thumbnail","category-amor-es-amor","category-semanales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La comunidad LGBTQ+ busca acciones que obliguen a los partidos pol\u00edticos a postular personas de este nicho a puestos de elecci\u00f3n popular, y para lograrlo, entregaron al Instituto Electoral y de Participaci\u00f3n Ciudadana del Estado de Guerrero (IEPC) un planteamiento de diez puntos. Alberto Serna Mogoll\u00f3n, presidente de la asociaci\u00f3n&nbsp;de&nbsp;homosexuales&nbsp;y de&nbsp;lesbianas&nbsp;del Estado de Guerrero A. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-17T10:20:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"El Sol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"El Sol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/\"},\"author\":{\"name\":\"El Sol\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/e42cf8194648cef93ec04777ab0c2929\"},\"headline\":\"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular\",\"datePublished\":\"2026-07-17T10:20:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"articleSection\":[\"AMOR ES AMOR\",\"SEMANALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/\",\"name\":\"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"datePublished\":\"2026-07-17T10:20:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/comunidad-lgbt.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/17\\\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/e42cf8194648cef93ec04777ab0c2929\",\"name\":\"El Sol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g\",\"caption\":\"El Sol\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/elsol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/","og_locale":"es_MX","og_type":"article","og_title":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas","og_description":"La comunidad LGBTQ+ busca acciones que obliguen a los partidos pol\u00edticos a postular personas de este nicho a puestos de elecci\u00f3n popular, y para lograrlo, entregaron al Instituto Electoral y de Participaci\u00f3n Ciudadana del Estado de Guerrero (IEPC) un planteamiento de diez puntos. Alberto Serna Mogoll\u00f3n, presidente de la asociaci\u00f3n&nbsp;de&nbsp;homosexuales&nbsp;y de&nbsp;lesbianas&nbsp;del Estado de Guerrero A. [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-07-17T10:20:00+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","type":"image\/jpeg"}],"author":"El Sol","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"El Sol","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/"},"author":{"name":"El Sol","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/e42cf8194648cef93ec04777ab0c2929"},"headline":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular","datePublished":"2026-07-17T10:20:00+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","articleSection":["AMOR ES AMOR","SEMANALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/","name":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","datePublished":"2026-07-17T10:20:00+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2024\/05\/comunidad-lgbt.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/17\/comunidad-lgbtq-busca-garantizar-candidaturas-a-cargos-de-eleccion-popular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Comunidad LGBTQ+ busca garantizar candidaturas a cargos de elecci\u00f3n popular"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/e42cf8194648cef93ec04777ab0c2929","name":"El Sol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/150fbeded465cf15d26e08fc82bc20f3776e1e0a9e9298940a5ae65d05dba4a7?s=96&d=mm&r=g","caption":"El Sol"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/elsol\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=137958"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137958\/revisions"}],"predecessor-version":[{"id":137961,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137958\/revisions\/137961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/80759"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=137958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=137958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=137958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}