{"id":137821,"date":"2026-07-15T10:18:20","date_gmt":"2026-07-15T17:18:20","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=137821"},"modified":"2026-07-15T10:18:25","modified_gmt":"2026-07-15T17:18:25","slug":"sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/","title":{"rendered":"SEP publica el calendario escolar oficial 2026 &#8211; 2027: estas son las fechas clave"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>La SEP present\u00f3 en la Ley General de Educaci\u00f3n los calendarios propuestos con fechas de regreso a clases, as\u00ed como algunos d\u00edas clave, como parte de su anteproyecto del calendario escolar.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) public\u00f3 el calendario escolar 2026 &#8211; 2027 y da el panorama completo de lo que ser\u00e1 el pr\u00f3ximo calendario de actividades para estudiantes de educaci\u00f3n b\u00e1sica, es decir, preescolar, primaria y secundaria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras presentar un&nbsp;anteproyecto, mismo que corresponde a una propuesta normativa mediante la cual se busca establecer el calendario escolar del ciclo 2026 &#8211; 2027 en toda la Rep\u00fablica Mexicana, la SEP hizo p\u00fablicas las fechas que componen el pr\u00f3xmio ciclo de educaci\u00f3n b\u00e1sica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recordemos que la Ley General de Educaci\u00f3n, establece que los calendarios escolares deben contemplar un m\u00ednimo de 185 d\u00edas efectivos de clases y un m\u00e1ximo de 200 d\u00edas. En este calendario se presentan tambi\u00e9n las fechas para las sesiones de Consejo T\u00e9cnico Escolar (CTE) as\u00ed como los d\u00edas de suspensi\u00f3n de clases y las capacitaciones que recibir\u00e1 el personal docente.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><em>Calendario escolar 2026 &#8211; 2027: Fechas clave con d\u00edas feriados propuestos por la SEP<\/em><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el calendario presentado por la SEP para el ciclo escolar 2026 &#8211; 2027, el regreso a clases ser\u00e1 el 31 de agosto, fecha en la que concluir\u00e1&nbsp;el periodo vacacional de verano y comenzar\u00e1n las clases presenciales en los distintos planteles de educaci\u00f3n b\u00e1sica en M\u00e9xico.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este calendario se aplicar\u00eda en preescolar, primaria, secundaria, escuelas p\u00fablicas y planteles particulares incorporados al Sistema Educativo Nacional. Las fechas m\u00e1s importantes del calendario son las siguientes:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Inicio del ciclo escolar: 31 de agosto de 2026<\/li>\n\n\n\n<li>Fin de clases: 9 de julio de 2027<\/li>\n\n\n\n<li>Periodo previo al inicio del ciclo: una semana adicional de actividades para docentes durante agosto<\/li>\n\n\n\n<li>D\u00edas de suspensi\u00f3n de labores por fechas conmemorativa y sesiones ordinarias del CTE<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a los periodos vacacionales, el calendario de la SEP marca:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Vacaciones de invierno: del 21 de diciembre del 2026 al 5\u00a0de enero del 2027<\/li>\n\n\n\n<li>Vacaciones de Semana Santa: del 22 de marzo al 1\u00a0de abril del 2027<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfCu\u00e1les son los d\u00edas de descanso obligatorio marcados en este calendario propuesto?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el calendario de la SEP, las fechas marcadas como de descanso obligatorio son las siguientes:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fin de curso ser\u00e1 el 9 de julio del 2027<\/li>\n\n\n\n<li>Mi\u00e9rcoles 16 de septiembre del 2026 por el D\u00eda de la Independencia<\/li>\n\n\n\n<li>Lunes 2 de noviembre, por D\u00eda de Muertos<\/li>\n\n\n\n<li>Lunes 16 de noviembre, por el 20 de noviembre D\u00eda de la Revoluci\u00f3n Mexicana<\/li>\n\n\n\n<li>Viernes 25 de diciembre, por Navidad<\/li>\n\n\n\n<li>Viernes 1 de enero, por A\u00f1o Nuevo<\/li>\n\n\n\n<li>Mi\u00e9rcoles 6 de enero, por D\u00eda de Reyes<\/li>\n\n\n\n<li>Lunes 1 de febrero por el 5 de febrero, D\u00eda de la Constituci\u00f3n<\/li>\n\n\n\n<li>Lunes 15 de marzo, por el 21 de marzo Natalicio de Benito Ju\u00e1rez<\/li>\n\n\n\n<li>Mi\u00e9rcoles 5 de mayo, D\u00eda de la Batalla de Puebla<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfY los periodos vacacionales?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo a lo publicado por la SEP, los periodos vacacionales ser\u00e1n los siguientes:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las vacaciones de diciembre inician el lunes 21 de diciembre del 2026 y concluir\u00edan el mi\u00e9rcoles 6 de enero del 2027<\/li>\n\n\n\n<li>Las vacaciones de Semana Santa comienza el lunes 22 de marzo del 2027 y termina el viernes de abril del 2027<\/li>\n\n\n\n<li>Las juntas de Consejo T\u00e9cnico Escolar se celebran el \u00faltimo viernes de cada mes<\/li>\n\n\n\n<li>Periodos de entrega de calificaciones, se dividen en 3: del lunes 23 al jueves 26 de noviembre; del martes 16 al viernes 19 de marzo del 2027 y del jueves 8 al viernes 9 de julio del 2027.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>La SEP present\u00f3 en la Ley General de Educaci\u00f3n los calendarios propuestos con fechas de regreso a clases, as\u00ed como algunos d\u00edas clave, como parte de su anteproyecto del calendario escolar. La Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) public\u00f3 el calendario escolar 2026 &#8211; 2027 y da el panorama completo de lo que ser\u00e1 el pr\u00f3ximo [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":137822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-137821","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"La SEP present\u00f3 en la Ley General de Educaci\u00f3n los calendarios propuestos con fechas de regreso a clases, as\u00ed como algunos d\u00edas clave, como parte de su anteproyecto del calendario escolar. La Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) public\u00f3 el calendario escolar 2026 &#8211; 2027 y da el panorama completo de lo que ser\u00e1 el pr\u00f3ximo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T17:18:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T17:18:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Heraldo de M\u00e9xico\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Heraldo de M\u00e9xico\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/\"},\"author\":{\"name\":\"Heraldo de M\u00e9xico\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/1c75a595e538894333ebe35c2bf6e23a\"},\"headline\":\"SEP publica el calendario escolar oficial 2026 &#8211; 2027: estas son las fechas clave\",\"datePublished\":\"2026-07-15T17:18:20+00:00\",\"dateModified\":\"2026-07-15T17:18:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/\"},\"wordCount\":609,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/\",\"name\":\"SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg\",\"datePublished\":\"2026-07-15T17:18:20+00:00\",\"dateModified\":\"2026-07-15T17:18:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/07\\\/15\\\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEP publica el calendario escolar oficial 2026 &#8211; 2027: estas son las fechas clave\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/1c75a595e538894333ebe35c2bf6e23a\",\"name\":\"Heraldo de M\u00e9xico\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g\",\"caption\":\"Heraldo de M\u00e9xico\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/heraldo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/","og_locale":"es_MX","og_type":"article","og_title":"SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas","og_description":"La SEP present\u00f3 en la Ley General de Educaci\u00f3n los calendarios propuestos con fechas de regreso a clases, as\u00ed como algunos d\u00edas clave, como parte de su anteproyecto del calendario escolar. La Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP) public\u00f3 el calendario escolar 2026 &#8211; 2027 y da el panorama completo de lo que ser\u00e1 el pr\u00f3ximo [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-07-15T17:18:20+00:00","article_modified_time":"2026-07-15T17:18:25+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg","type":"image\/jpeg"}],"author":"Heraldo de M\u00e9xico","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"Heraldo de M\u00e9xico","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/"},"author":{"name":"Heraldo de M\u00e9xico","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/1c75a595e538894333ebe35c2bf6e23a"},"headline":"SEP publica el calendario escolar oficial 2026 &#8211; 2027: estas son las fechas clave","datePublished":"2026-07-15T17:18:20+00:00","dateModified":"2026-07-15T17:18:25+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/"},"wordCount":609,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/","name":"SEP publica el calendario escolar oficial 2026 - 2027: estas son las fechas clave - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg","datePublished":"2026-07-15T17:18:20+00:00","dateModified":"2026-07-15T17:18:25+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/07\/5c606ee6-1190-4885-9eee-8621d4653476-1.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/07\/15\/sep-publica-el-calendario-escolar-oficial-2026-2027-estas-son-las-fechas-clave\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"SEP publica el calendario escolar oficial 2026 &#8211; 2027: estas son las fechas clave"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/1c75a595e538894333ebe35c2bf6e23a","name":"Heraldo de M\u00e9xico","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a6c40de68e5cf2d8aac15267bd2dad2b9fdeb309dac7c5a7c2bb87ed5b81cb6?s=96&d=mm&r=g","caption":"Heraldo de M\u00e9xico"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/heraldo\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=137821"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137821\/revisions"}],"predecessor-version":[{"id":137823,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/137821\/revisions\/137823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/137822"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=137821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=137821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=137821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}