{"id":133371,"date":"2026-05-11T17:56:02","date_gmt":"2026-05-12T00:56:02","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=133371"},"modified":"2026-05-11T17:59:06","modified_gmt":"2026-05-12T00:59:06","slug":"hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/","title":{"rendered":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nuevo Le\u00f3n.- La Fiscal\u00eda General de la Rep\u00fablica (FGR) inform\u00f3 este lunes que fue asegurado un t\u00fanel clandestino utilizado para el robo de combustible en instalaciones de Petr\u00f3leos Mexicanos (Pemex), que conectaba con un domicilio contiguo que fue hallado en Santa Catarina, Nuevo Le\u00f3n. Adem\u00e1s, se decomis\u00f3 205 mil litros de hidrocarburo, equipo especializado para su extracci\u00f3n y una flota de veh\u00edculos presuntamente utilizada para su traslado.<\/p>\n\n\n\n<p class=\"nota-justify wp-block-paragraph\">\u201cLos elementos de la Agencia de Investigaci\u00f3n Criminal (AIC) localizaron dicha excavaci\u00f3n, tipo t\u00fanel, en las instalaciones de la Terminal de Almacenamiento y Despacho (TAD) de Pemex, ubicada en Santa Catarina, Nuevo Le\u00f3n\u201d, inform\u00f3 Ulises Lara L\u00f3pez, fiscal Especial en Investigaci\u00f3n de Asuntos Relevantes y vocero de esta FGR en un video en redes sociales.&nbsp;<\/p>\n\n\n\n<p class=\"nota-justify wp-block-paragraph\">En el operativo participaron elementos de la FGR, Pemex, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), la Secretar\u00eda de la Defensa Nacional, la Guardia Nacional y autoridades estatales, tras labores de inteligencia y trabajo de campo.<\/p>\n\n\n\n<p class=\"nota-justify wp-block-paragraph\">De acuerdo con la versi\u00f3n oficial, los agentes del la AIC localizaron dicha excavaci\u00f3n tipo t\u00fanel en las instalaciones de Pemex, el cual conectaba con un inmueble contiguo, ubicado sobre el antiguo camino a Villas de Garc\u00eda, en el citado municipio, el cual fue posteriormente cateado y se confirm\u00f3 que el t\u00fanel conectaba dicho predio con el poliducto de 18 pulgadas de Pemex.&nbsp;<\/p>\n\n\n\n<p class=\"nota-justify wp-block-paragraph\">En el inmueble fueron localizados equipos utilizados para la extracci\u00f3n il\u00edcita de hidrocarburo, entre ellos una conexi\u00f3n soldada al ducto, v\u00e1lvulas, herramientas especializadas y mangueras de alta presi\u00f3n. Las autoridades tambi\u00e9n detectaron que el predio presuntamente operaba como centro de almacenamiento de combustible, pues contaba con oficinas, \u00e1reas comunes, tractocamiones, autotanques y diversos contenedores, todos asegurados durante el operativo.<\/p>\n\n\n\n<p class=\"nota-justify wp-block-paragraph\">\u201cDe igual forma, el personal de la Polic\u00eda Federal Ministerial (PFM) de la Agencia de Investigaci\u00f3n Criminal, junto con las autoridades mencionadas, localiz\u00f3 un contenedor met\u00e1lico mar\u00edtimo en cuyo interior se encontraba oculto el acceso al t\u00fanel, con lo que qued\u00f3 confirmada la conexi\u00f3n entre el inmueble cateado y las instalaciones de Pemex Santa Catarina.\u201d, se\u00f1al\u00f3 el fiscal especial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del aseguramiento del inmueble y del t\u00fanel, las autoridades aseguraron aproximadamente 205 mil 418 litros de hidrocarburo, 23 tractocamiones, 10 autotanques, una gr\u00faa, siete cajas secas, tres veh\u00edculos, un contenedor met\u00e1lico mar\u00edtimo, un cubitanque, un tambo, dos bidones, diversos costales de arena, herramienta para construcci\u00f3n, documentaci\u00f3n diversa y un tel\u00e9fono celular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuevo Le\u00f3n.- La Fiscal\u00eda General de la Rep\u00fablica (FGR) inform\u00f3 este lunes que fue asegurado un t\u00fanel clandestino utilizado para el robo de combustible en instalaciones de Petr\u00f3leos Mexicanos (Pemex), que conectaba con un domicilio contiguo que fue hallado en Santa Catarina, Nuevo Le\u00f3n. Adem\u00e1s, se decomis\u00f3 205 mil litros de hidrocarburo, equipo especializado para [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":133370,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-133371","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Nuevo Le\u00f3n.- La Fiscal\u00eda General de la Rep\u00fablica (FGR) inform\u00f3 este lunes que fue asegurado un t\u00fanel clandestino utilizado para el robo de combustible en instalaciones de Petr\u00f3leos Mexicanos (Pemex), que conectaba con un domicilio contiguo que fue hallado en Santa Catarina, Nuevo Le\u00f3n. Adem\u00e1s, se decomis\u00f3 205 mil litros de hidrocarburo, equipo especializado para [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-12T00:56:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T00:59:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"741\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Jornada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Jornada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/\"},\"author\":{\"name\":\"La Jornada\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\"},\"headline\":\"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL\",\"datePublished\":\"2026-05-12T00:56:02+00:00\",\"dateModified\":\"2026-05-12T00:59:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/\"},\"wordCount\":447,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img_9218.jpeg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/\",\"name\":\"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img_9218.jpeg\",\"datePublished\":\"2026-05-12T00:56:02+00:00\",\"dateModified\":\"2026-05-12T00:59:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img_9218.jpeg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/img_9218.jpeg\",\"width\":1200,\"height\":741},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/11\\\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\",\"name\":\"La Jornada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"caption\":\"La Jornada\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/jornada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/","og_locale":"es_MX","og_type":"article","og_title":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas","og_description":"Nuevo Le\u00f3n.- La Fiscal\u00eda General de la Rep\u00fablica (FGR) inform\u00f3 este lunes que fue asegurado un t\u00fanel clandestino utilizado para el robo de combustible en instalaciones de Petr\u00f3leos Mexicanos (Pemex), que conectaba con un domicilio contiguo que fue hallado en Santa Catarina, Nuevo Le\u00f3n. Adem\u00e1s, se decomis\u00f3 205 mil litros de hidrocarburo, equipo especializado para [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-05-12T00:56:02+00:00","article_modified_time":"2026-05-12T00:59:06+00:00","og_image":[{"width":1200,"height":741,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg","type":"image\/jpeg"}],"author":"La Jornada","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Jornada","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/"},"author":{"name":"La Jornada","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35"},"headline":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL","datePublished":"2026-05-12T00:56:02+00:00","dateModified":"2026-05-12T00:59:06+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/"},"wordCount":447,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/","name":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg","datePublished":"2026-05-12T00:56:02+00:00","dateModified":"2026-05-12T00:59:06+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/img_9218.jpeg","width":1200,"height":741},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/11\/hallan-tunel-de-huachicol-conectado-a-poliducto-de-pemex-en-nl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Hallan t\u00fanel de huachicol conectado a poliducto de Pemex en NL"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35","name":"La Jornada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","caption":"La Jornada"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/jornada\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=133371"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133371\/revisions"}],"predecessor-version":[{"id":133372,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133371\/revisions\/133372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/133370"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=133371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=133371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=133371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}