{"id":133341,"date":"2026-05-13T12:27:19","date_gmt":"2026-05-13T19:27:19","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=133341"},"modified":"2026-05-11T12:29:03","modified_gmt":"2026-05-11T19:29:03","slug":"video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/","title":{"rendered":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo"},"content":{"rendered":"\n<p>Un cami\u00f3n se qued\u00f3 sin frenos y termin\u00f3 impactando, al menos, tres veh\u00edculos sobre la autopista M\u00e9xico-Tuxpan, cerca de Tulancingo, Hidalgo. A trav\u00e9s de redes sociales se comparti\u00f3 un video en el que se aprecia c\u00f3mo, pese a las maniobras del operador, termin\u00f3 chocando otras unidades. El saldo, seg\u00fan reportes, ser\u00eda de, al menos, tres personas lesionadas.<\/p>\n\n\n\n<p>En las im\u00e1genes captadas por otro conductor que transitaba por la conocida \u201cBajada de la muerte\u201d, se ve c\u00f3mo, por varios metros, el cami\u00f3n esquiva algunos carros buscando la rampa de frenado.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u2b55\ufe0f|| Este es el momento en el que un cami\u00f3n de volteo se queda sin frenos en la llamada \u201cBajada de la Muerte\u201d, en <a href=\"https:\/\/twitter.com\/hashtag\/Tulancingo?src=hash&amp;ref_src=twsrc%5Etfw\">#Tulancingo<\/a> ,y comienza a maniobrar para esquivar a los veh\u00edculos e ingresar a la rampa de frenado; sin embargo, no lo logr\u00f3 y embisti\u00f3 a dos camionetas, las cuales\u2026 <a href=\"https:\/\/t.co\/SVYBbx5nDX\">pic.twitter.com\/SVYBbx5nDX<\/a><\/p>&mdash; Punto por punto (@puntoporpuntomx) <a href=\"https:\/\/twitter.com\/puntoporpuntomx\/status\/2052827273372270972?ref_src=twsrc%5Etfw\">May 8, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>De acuerdo con el video, el cami\u00f3n sin&nbsp;<strong>frenos&nbsp;<\/strong>habr\u00eda estado a punto de chocar con un&nbsp;<strong>autob\u00fas<\/strong>, aparentemente de&nbsp;<strong>pasajeros<\/strong>. Sin embargo, logr\u00f3 esquivarlo, pero en la&nbsp;<strong>maniobra&nbsp;<\/strong>y con la&nbsp;<strong>velocidad&nbsp;<\/strong>termin\u00f3&nbsp;<strong>golpeando&nbsp;<\/strong>otras&nbsp;<strong>unidades<\/strong>.<\/p>\n\n\n\n<p>Por el impacto, los autom\u00f3viles&nbsp;<strong>terminaron&nbsp;<\/strong>fuera del camino y&nbsp;<strong>severamente da\u00f1os<\/strong>. Incluso, testigos afirman que la pesada unidad habr\u00eda partido a la mitad una de las&nbsp;<strong>camionetas&nbsp;<\/strong>con las que&nbsp;<strong>choc\u00f3<\/strong>.<\/p>\n\n\n\n<p>Automovilistas que pasaban por el lugar&nbsp;<strong>auxiliaron&nbsp;<\/strong>a las&nbsp;<strong>personas heridas&nbsp;<\/strong>a las que ayudaron a salir de los&nbsp;<strong>carros chocados<\/strong>, seg\u00fan consta en las&nbsp;<strong>im\u00e1genes<\/strong>.<\/p>\n\n\n\n<p>M\u00e1s tarde, a la zona llegaron elementos de emergencia quienes atendieron a algunos&nbsp;<strong>heridos&nbsp;<\/strong>y trasladaron, al menos a uno a un hospital para su&nbsp;<strong>atenci\u00f3n<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cami\u00f3n se qued\u00f3 sin frenos y termin\u00f3 impactando, al menos, tres veh\u00edculos sobre la autopista M\u00e9xico-Tuxpan, cerca de Tulancingo, Hidalgo. A trav\u00e9s de redes sociales se comparti\u00f3 un video en el que se aprecia c\u00f3mo, pese a las maniobras del operador, termin\u00f3 chocando otras unidades. El saldo, seg\u00fan reportes, ser\u00eda de, al menos, tres [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":133342,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[40],"tags":[],"class_list":{"0":"post-133341","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-las-asombrosas"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"Un cami\u00f3n se qued\u00f3 sin frenos y termin\u00f3 impactando, al menos, tres veh\u00edculos sobre la autopista M\u00e9xico-Tuxpan, cerca de Tulancingo, Hidalgo. A trav\u00e9s de redes sociales se comparti\u00f3 un video en el que se aprecia c\u00f3mo, pese a las maniobras del operador, termin\u00f3 chocando otras unidades. El saldo, seg\u00fan reportes, ser\u00eda de, al menos, tres [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T19:27:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"UNO TV\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"UNO TV\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/\"},\"author\":{\"name\":\"UNO TV\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/d121cdb5b05da85078ff634900eb8b43\"},\"headline\":\"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo\",\"datePublished\":\"2026-05-13T19:27:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/\"},\"wordCount\":311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/images-10.jpg\",\"articleSection\":[\"LAS ASOMBROSAS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/\",\"name\":\"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/images-10.jpg\",\"datePublished\":\"2026-05-13T19:27:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/images-10.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/images-10.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/05\\\/13\\\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/d121cdb5b05da85078ff634900eb8b43\",\"name\":\"UNO TV\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g\",\"caption\":\"UNO TV\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/unotv\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/","og_locale":"es_MX","og_type":"article","og_title":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas","og_description":"Un cami\u00f3n se qued\u00f3 sin frenos y termin\u00f3 impactando, al menos, tres veh\u00edculos sobre la autopista M\u00e9xico-Tuxpan, cerca de Tulancingo, Hidalgo. A trav\u00e9s de redes sociales se comparti\u00f3 un video en el que se aprecia c\u00f3mo, pese a las maniobras del operador, termin\u00f3 chocando otras unidades. El saldo, seg\u00fan reportes, ser\u00eda de, al menos, tres [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-05-13T19:27:19+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg","type":"image\/jpeg"}],"author":"UNO TV","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"UNO TV","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/"},"author":{"name":"UNO TV","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/d121cdb5b05da85078ff634900eb8b43"},"headline":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo","datePublished":"2026-05-13T19:27:19+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/"},"wordCount":311,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg","articleSection":["LAS ASOMBROSAS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/","name":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg","datePublished":"2026-05-13T19:27:19+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/05\/images-10.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/05\/13\/video-camion-sin-frenos-impacta-varios-vehiculos-en-la-bajada-de-la-muerte-en-hidalgo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"Video: cami\u00f3n sin frenos impacta varios veh\u00edculos en la \u201cBajada de la muerte\u201d en Hidalgo"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/d121cdb5b05da85078ff634900eb8b43","name":"UNO TV","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6b329c442e2a611d9019175d0dc7f1d31dc6459a87e1652726f26e209691b32c?s=96&d=mm&r=g","caption":"UNO TV"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/unotv\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=133341"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133341\/revisions"}],"predecessor-version":[{"id":133343,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/133341\/revisions\/133343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/133342"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=133341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=133341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=133341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}