{"id":131296,"date":"2026-04-13T11:04:00","date_gmt":"2026-04-13T18:04:00","guid":{"rendered":"https:\/\/fuentesfidedignas.com.mx\/?p=131296"},"modified":"2026-04-13T11:04:04","modified_gmt":"2026-04-13T18:04:04","slug":"el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra","status":"publish","type":"post","link":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/","title":{"rendered":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &#8220;seguir\u00e9 pronunci\u00e1ndome contra la guerra&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>El papa Le\u00f3n XIV se dirige a las autoridades, miembros de la sociedad civil y del cuerpo diplom\u00e1tico en el Centro de Conferencias \u201cDjamaa el Djazair\u201d el 13 de abril de 2026.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A bordo del avi\u00f3n papal, el papa Le\u00f3n XIV respondi\u00f3 este lunes al presidente Donald Trump, que arremeti\u00f3 contra \u00e9l por la guerra con Ir\u00e1n, al se\u00f1alar a reporteros que no teme al gobierno del magnate y que sus llamados a la paz y la reconciliaci\u00f3n est\u00e1n arraigados en el Evangelio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Poner mi mensaje en el mismo plano que lo que el presidente ha intentado hacer aqu\u00ed, creo que es no entender cu\u00e1l es el mensaje del Evangelio\u201d, dijo Le\u00f3n a The Associated Press a bordo del avi\u00f3n papal rumbo a Argelia. \u201cY lamento escuchar eso, pero continuar\u00e9 con lo que creo que es la misi\u00f3n de la Iglesia en el mundo hoy\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El primer Papa de la historia nacido en Estados Unidos subray\u00f3 que no hac\u00eda un ataque directo contra Trump ni contra nadie m\u00e1s con su llamado general a la paz y sus cr\u00edticas a la \u201cilusi\u00f3n de omnipotencia\u201d que avivan la guerra en Ir\u00e1n y otros conflictos en todo el mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo entrar\u00e9 en debate. Las cosas que digo ciertamente no est\u00e1n destinadas como ataques contra nadie. El mensaje del Evangelio es muy claro: \u2018Bienaventurados los que trabajan por la paz\u2019\u201d, declar\u00f3 Robert Francis Prevost. \u201cNo me apartar\u00e9 de anunciar el mensaje del Evangelio e invitar a todas las personas a buscar maneras de construir puentes de paz y reconciliaci\u00f3n, y buscar maneras de evitar la guerra siempre que sea posible\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hablar con otros reporteros, a\u00f1adi\u00f3: \u201cno tengo miedo del gobierno de Trump ni de hablar en voz alta sobre el mensaje del Evangelio, que es por lo que trabaja la Iglesia\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo somos pol\u00edticos. No vemos la pol\u00edtica exterior desde la misma perspectiva que \u00e9l pueda tener\u201d, indic\u00f3 el Papa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSeguir\u00e9 pronunci\u00e1ndome con firmeza contra la guerra, buscando promover la paz, promoviendo el di\u00e1logo y el multilateralismo entre los Estados para encontrar soluciones a los problemas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDemasiadas personas est\u00e1n sufriendo hoy, demasiadas personas inocentes han sido asesinadas, y creo que alguien debe levantarse y decir que hay una mejor manera\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente estadunidense critic\u00f3 a Le\u00f3n XIV en redes sociales el domingo por la noche, al aseverar que no cre\u00eda que el l\u00edder mundial de la Iglesia cat\u00f3lica estuviera \u201chaciendo un muy buen trabajo\u201d y que \u201ces una persona muy progresista\u201d, al tiempo que tambi\u00e9n sugiri\u00f3 que el pont\u00edfice deber\u00eda \u201cdejar de complacer a la izquierda radical\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su vuelo de regreso a Washington desde Florida, Trump utiliz\u00f3 una extensa publicaci\u00f3n en redes sociales para criticar duramente al pont\u00edfice, y luego sigui\u00f3 haci\u00e9ndolo despu\u00e9s de bajar del avi\u00f3n, en comentarios en la pista a reporteros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo soy fan del papa Le\u00f3n\u201d, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los comentarios de Trump se produjeron despu\u00e9s que Le\u00f3n XIV sugiri\u00f3 durante el fin de semana que una \u201cilusi\u00f3n de omnipotencia\u201d aviva la guerra de Estados Unidos e Israel en Ir\u00e1n. Si bien no es inusual que papas y presidentes est\u00e9n en desacuerdo, es sumamente raro que el Papa critique directamente a un mandatario estadunidense \u2014y la mordaz respuesta de Trump es igualmente poco com\u00fan, si no m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl papa Le\u00f3n es d\u00e9bil con el crimen y terrible en pol\u00edtica exterior\u201d, escribi\u00f3 el mandatario norteamericano en redes sociales, y a\u00f1adi\u00f3: \u201cNo quiero un Papa que piense que est\u00e1 bien que Ir\u00e1n tenga un arma nuclear\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Solidaridad en Italia<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pol\u00edticos italianos de todo el espectro mostraron su solidaridad con Le\u00f3n XIV. La primera ministra Giorgia Meloni envi\u00f3 un mensaje de apoyo a su misi\u00f3n de paz, mientras que la l\u00edder del principal partido de oposici\u00f3n Elly Schlein fue m\u00e1s directa, calificando los ataques de Trump de \u201cextremadamente graves\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trump sostuvo que \u201cno nos gusta un Papa que diga que est\u00e1 bien tener un arma nuclear\u201d. Luego public\u00f3 una imagen que suger\u00eda que \u00e9l ten\u00eda poderes similares a los de un santo, parecidos a los de Jesucristo. Con una t\u00fanica de estilo b\u00edblico, se ve a Trump imponiendo las manos sobre un hombre postrado en cama al tiempo que la luz emana de sus dedos, mientras un soldado, una enfermera, una mujer rezando y un hombre barbudo con una gorra de b\u00e9isbol observan con admiraci\u00f3n. El cielo arriba est\u00e1 lleno de \u00e1guilas, una bandera estadunidense e im\u00e1genes vaporosas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo eso ocurri\u00f3 luego que Le\u00f3n XIV presidi\u00f3 un servicio vespertino de oraci\u00f3n en la bas\u00edlica de San Pedro el s\u00e1bado, el mismo d\u00eda en que Estados Unidos e Ir\u00e1n iniciaron negociaciones cara a cara en Pakist\u00e1n durante un fr\u00e1gil alto el fuego, con el vicepresidente JD Vance a la cabeza de la delegaci\u00f3n estadunidense. Vance es cat\u00f3lico y recientemente public\u00f3 un libro sobre su fe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su servicio vespertino de oraci\u00f3n, el papa no mencion\u00f3 por su nombre a Estados Unidos ni a Trump, pero el tono y el mensaje parecieron dirigidos a Trump y a funcionarios estadunidenses, quienes se han jactado de la superioridad militar de Estados Unidos y han justificado la guerra en t\u00e9rminos religiosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le\u00f3n XIV \u2014quien est\u00e1 en un viaje de 11 d\u00edas a \u00c1frica a partir de este lunes \u2014 ha dicho previamente que Dios \u201cno escucha las oraciones de quienes hacen la guerra, sino que las rechaza\u201d. Tambi\u00e9n ha citado un pasaje del Antiguo Testamento de Isa\u00edas, diciendo que \u201ccuando multipliques la oraci\u00f3n, yo no oir\u00e9; llenas est\u00e1n de sangre tus manos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Antes del alto el fuego, cuando Trump advirti\u00f3 de ataques masivos contra plantas el\u00e9ctricas iran\u00edes y otra infraestructura y que \u201cuna civilizaci\u00f3n entera morir\u00e1 esta noche\u201d, Le\u00f3n describi\u00f3 tal amenaza como \u201crealmente inaceptable\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su publicaci\u00f3n en redes sociales el domingo por la noche, sin embargo, Trump fue mucho m\u00e1s all\u00e1 de la guerra en Ir\u00e1n al criticar a Le\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente escribi\u00f3: \u201cNo quiero un Papa que piense que es terrible que Estados Unidos atacara a Venezuela, un pa\u00eds que estaba enviando cantidades masivas de drogas a Estados Unidos\u201d. Eso fue una referencia a que el gobierno de Trump secuestr\u00f3 al presidente venezolano Nicol\u00e1s Maduro en enero. \u201cNo quiero un Papa que critique al presidente de Estados Unidos porque estoy haciendo exactamente para lo que fui elegido, en una aplastante victoria\u201d, a\u00f1adi\u00f3 Trump, al hacer referencia a su victoria electoral de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n sugiri\u00f3 en la publicaci\u00f3n que Le\u00f3n XIV s\u00f3lo obtuvo su cargo \u201cporque era estadunidense, y pensaron que esa ser\u00eda la mejor manera de lidiar con el presidente Donald J. Trump\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi yo no estuviera en la Casa Blanca, Le\u00f3n no estar\u00eda en el Vaticano\u201d, escribi\u00f3 Trump, y a\u00f1adi\u00f3: \u201cLe\u00f3n deber\u00eda ponerse las pilas como Papa, usar el sentido com\u00fan, dejar de complacer a la izquierda radical y centrarse en ser un gran papa, no un pol\u00edtico. \u00a1Le est\u00e1 haciendo mucho da\u00f1o y, m\u00e1s importante, le est\u00e1 haciendo da\u00f1o a la Iglesia cat\u00f3lica!\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respuesta de la Iglesia cat\u00f3lica<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El arzobispo Paul S. Coakley, presidente de la Conferencia de Obispos Cat\u00f3licos de Estados Unidos, emiti\u00f3 un comunicado diciendo que estaba \u201cdesalentado\u201d por los comentarios de Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl papa Le\u00f3n no es su rival; ni el papa es un pol\u00edtico. Es el Vicario de Cristo que habla desde la verdad del Evangelio y por el cuidado de las almas\u201d, asegur\u00f3 Coakley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Conferencia Episcopal Italiana expres\u00f3 su pesar por las palabras de Trump y subray\u00f3 que el papa \u201cno es un contraparte pol\u00edtico, sino el sucesor de Pedro, llamado a servir al Evangelio, la verdad y la paz\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las elecciones de 2024, Trump gan\u00f3 55 por ciento del voto del electorado cat\u00f3lico, seg\u00fan Ap VoteCast, una amplia encuesta a votantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero el gobierno de Trump tambi\u00e9n tiene v\u00ednculos estrechos con l\u00edderes protestantes evang\u00e9licos conservadores y ha afirmado contar con respaldo celestial para la guerra en Ir\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Defensa Pete Hegseth, quien tiene tatuajes de los cruzados, inst\u00f3 a los estadunidenses a rezar por la victoria \u201cen el nombre de Jesucristo\u201d. Y, cuando se le pregunt\u00f3 a Trump si cre\u00eda que Dios aprobaba la guerra, dijo: \u201cS\u00ed, lo creo, porque Dios es bueno, porque Dios es bueno y Dios quiere ver que la gente sea atendida\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El papa Le\u00f3n XIV se dirige a las autoridades, miembros de la sociedad civil y del cuerpo diplom\u00e1tico en el Centro de Conferencias \u201cDjamaa el Djazair\u201d el 13 de abril de 2026. A bordo del avi\u00f3n papal, el papa Le\u00f3n XIV respondi\u00f3 este lunes al presidente Donald Trump, que arremeti\u00f3 contra \u00e9l por la guerra [&hellip;]<\/p>\n","protected":false},"author":45,"featured_media":131297,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[39],"tags":[],"class_list":["post-131296","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias-nacionales"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &quot;seguir\u00e9 pronunci\u00e1ndome contra la guerra&quot; - Fuentes Fidedignas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &quot;seguir\u00e9 pronunci\u00e1ndome contra la guerra&quot; - Fuentes Fidedignas\" \/>\n<meta property=\"og:description\" content=\"El papa Le\u00f3n XIV se dirige a las autoridades, miembros de la sociedad civil y del cuerpo diplom\u00e1tico en el Centro de Conferencias \u201cDjamaa el Djazair\u201d el 13 de abril de 2026. A bordo del avi\u00f3n papal, el papa Le\u00f3n XIV respondi\u00f3 este lunes al presidente Donald Trump, que arremeti\u00f3 contra \u00e9l por la guerra [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuentes Fidedignas\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-13T18:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T18:04:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La Jornada\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:site\" content=\"@fidedignas\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"La Jornada\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/\"},\"author\":{\"name\":\"La Jornada\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\"},\"headline\":\"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &#8220;seguir\u00e9 pronunci\u00e1ndome contra la guerra&#8221;\",\"datePublished\":\"2026-04-13T18:04:00+00:00\",\"dateModified\":\"2026-04-13T18:04:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/\"},\"wordCount\":1487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/el-papa-dice-no-temerle-a-trump-.jpg\",\"articleSection\":[\"NOTICIAS NACIONALES\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/\",\"name\":\"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; \\\"seguir\u00e9 pronunci\u00e1ndome contra la guerra\\\" - Fuentes Fidedignas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/el-papa-dice-no-temerle-a-trump-.jpg\",\"datePublished\":\"2026-04-13T18:04:00+00:00\",\"dateModified\":\"2026-04-13T18:04:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/el-papa-dice-no-temerle-a-trump-.jpg\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/el-papa-dice-no-temerle-a-trump-.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/2026\\\/04\\\/13\\\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &#8220;seguir\u00e9 pronunci\u00e1ndome contra la guerra&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#website\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"name\":\"Fuentes Fidedignas\",\"description\":\"Otro sitio realizado con WordPress\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#organization\",\"name\":\"Fuentes Fidedignas\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-retina.png\",\"width\":280,\"height\":51,\"caption\":\"Fuentes Fidedignas\"},\"image\":{\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fuentes-Fidedignas-368234489921644\",\"https:\\\/\\\/x.com\\\/fidedignas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/#\\\/schema\\\/person\\\/87eacee4072e149fccc7de67f9634f35\",\"name\":\"La Jornada\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g\",\"caption\":\"La Jornada\"},\"url\":\"https:\\\/\\\/fuentesfidedignas.com.mx\\\/index.php\\\/author\\\/jornada\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; \"seguir\u00e9 pronunci\u00e1ndome contra la guerra\" - Fuentes Fidedignas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/","og_locale":"es_MX","og_type":"article","og_title":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; \"seguir\u00e9 pronunci\u00e1ndome contra la guerra\" - Fuentes Fidedignas","og_description":"El papa Le\u00f3n XIV se dirige a las autoridades, miembros de la sociedad civil y del cuerpo diplom\u00e1tico en el Centro de Conferencias \u201cDjamaa el Djazair\u201d el 13 de abril de 2026. A bordo del avi\u00f3n papal, el papa Le\u00f3n XIV respondi\u00f3 este lunes al presidente Donald Trump, que arremeti\u00f3 contra \u00e9l por la guerra [&hellip;]","og_url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/","og_site_name":"Fuentes Fidedignas","article_publisher":"https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","article_published_time":"2026-04-13T18:04:00+00:00","article_modified_time":"2026-04-13T18:04:04+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg","type":"image\/jpeg"}],"author":"La Jornada","twitter_card":"summary_large_image","twitter_creator":"@fidedignas","twitter_site":"@fidedignas","twitter_misc":{"Escrito por":"La Jornada","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#article","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/"},"author":{"name":"La Jornada","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35"},"headline":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &#8220;seguir\u00e9 pronunci\u00e1ndome contra la guerra&#8221;","datePublished":"2026-04-13T18:04:00+00:00","dateModified":"2026-04-13T18:04:04+00:00","mainEntityOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/"},"wordCount":1487,"commentCount":0,"publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg","articleSection":["NOTICIAS NACIONALES"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/","url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/","name":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; \"seguir\u00e9 pronunci\u00e1ndome contra la guerra\" - Fuentes Fidedignas","isPartOf":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#primaryimage"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#primaryimage"},"thumbnailUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg","datePublished":"2026-04-13T18:04:00+00:00","dateModified":"2026-04-13T18:04:04+00:00","breadcrumb":{"@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#primaryimage","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2026\/04\/el-papa-dice-no-temerle-a-trump-.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/fuentesfidedignas.com.mx\/index.php\/2026\/04\/13\/el-papa-dice-no-temerle-a-trump-por-mensajes-sobre-iran-seguire-pronunciandome-contra-la-guerra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/fuentesfidedignas.com.mx\/"},{"@type":"ListItem","position":2,"name":"El Papa dice no temerle a Trump por mensajes sobre Ir\u00e1n; &#8220;seguir\u00e9 pronunci\u00e1ndome contra la guerra&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/fuentesfidedignas.com.mx\/#website","url":"https:\/\/fuentesfidedignas.com.mx\/","name":"Fuentes Fidedignas","description":"Otro sitio realizado con WordPress","publisher":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuentesfidedignas.com.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fuentesfidedignas.com.mx\/#organization","name":"Fuentes Fidedignas","url":"https:\/\/fuentesfidedignas.com.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/","url":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","contentUrl":"https:\/\/fuentesfidedignas.com.mx\/wp-content\/uploads\/2021\/04\/logo-retina.png","width":280,"height":51,"caption":"Fuentes Fidedignas"},"image":{"@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fuentes-Fidedignas-368234489921644","https:\/\/x.com\/fidedignas"]},{"@type":"Person","@id":"https:\/\/fuentesfidedignas.com.mx\/#\/schema\/person\/87eacee4072e149fccc7de67f9634f35","name":"La Jornada","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b09f15a418e222775ffd645761e3fcecd1fb9d7a38a3ba858adf349aab82c7c?s=96&d=mm&r=g","caption":"La Jornada"},"url":"https:\/\/fuentesfidedignas.com.mx\/index.php\/author\/jornada\/"}]}},"_links":{"self":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/131296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/comments?post=131296"}],"version-history":[{"count":1,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/131296\/revisions"}],"predecessor-version":[{"id":131298,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/posts\/131296\/revisions\/131298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media\/131297"}],"wp:attachment":[{"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/media?parent=131296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/categories?post=131296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fuentesfidedignas.com.mx\/index.php\/wp-json\/wp\/v2\/tags?post=131296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}